{"id":38,"date":"2020-10-30T17:29:39","date_gmt":"2020-10-30T16:29:39","guid":{"rendered":"https:\/\/webhosting.de\/cloudflare\/"},"modified":"2020-10-30T17:29:39","modified_gmt":"2020-10-30T16:29:39","slug":"cloudflare","status":"publish","type":"page","link":"https:\/\/webhosting.de\/es\/cloudflare\/","title":{"rendered":"Cloudflare"},"content":{"rendered":"[vc_row][vc_column][vc_column_text]Wir stellen Ihnen heute mit <strong>Cloudflare<\/strong> einen preiswerten Anbieter f\u00fcr grundlegende Website Sicherheit und Beschleunigung vor. Die Abrufgeschwindigkeit Ihrer Website wird immer wichtiger, deshalb ist es sinnvoll neben einem guten Webhoster der sich um die Sicherheit und den Betrieb Ihrer Seite k\u00fcmmert auch noch zus\u00e4tzlichen Schutz durch externe Systeme zu verwenden.<\/p>\n<p><strong>Die \u00dcbersicht des\u00a0Cloudflare Systems<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h2>Was ist CloudFlare?<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>CloudFlare<\/strong> ist ein sogenanntes <strong>Content Delivery Network (CDN)<\/strong>. Das hei\u00dft, dass das Netzwerk die Daten die Ihr Webserver ausliefert zwischenspeichert und aufbereitet. Durch die Umstellung des DNS werden Anfragen von Besuchern Ihrer Website zun\u00e4chst an CloudFlare geleitet und von denen ausgeliefert. Cloudflare ruft die Daten dann von Ihrem Webserver ab. Hier werden allerdings nur ver\u00e4nderte Daten abgerufen, sodass statische Dateien wie Bilder, html, Javascript oder CSS Dateien alle bereits bei Cloudflare liegen und direkt an den Besucher ausgegeben werden. Somit sparen Sie Traffic ein und die Webserver werden weniger belastet. Durch viele Zusatzfeatures werden die Webseiten auch optimiert, d.h. in der Gr\u00f6\u00dfe verkleinert und suchmaschinenfreundlich optimiert. Durch eine Firewall wird die Seite auch vor vielen Angriffen gesch\u00fctzt.<\/p>\n<p>Das Unternehmen setzt bei seiner Infrastruktur auf ein dezentrales Netzwerk aus Servern, die mit einem angeh\u00e4ngten DNS funktionieren. Insgesamt hat <strong>CloudFlare<\/strong> Server in 102 verschiedenen Rechenzentren, die in \u00fcber 49 L\u00e4ndern betrieben werden werden. Das macht <strong>CloudFlare<\/strong> sehr sicher vor Angriffen durch Hacker und zudem sehr widerstandsf\u00e4hig f\u00fcr technische Probleme und St\u00f6rungen. Heute z\u00e4hlt <strong>CloudFlare<\/strong> zu einem der beliebtesten und am weitesten verbreiteten CDNs weltweit. Viele Webhoster, auch in Deutschland, haben <strong>CloudFlare<\/strong> inzwischen in ihre Hostingpakete integriert und erm\u00f6glichen den Kunden so Zugang zu dem Content, den das CDN zu bieten hat.<\/p>\n<p>&nbsp;<\/p>\n<h2>Warum integrieren Webhoster Cloudflare in ihre Pakete?<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>CDNs<\/strong> gelten als sichere Zwischenspeicher f\u00fcr statische Dateien die direkt vom CDN Anbieter wie Cloudflare ausgeliefert werden und somit nicht erneut vom Server des Webhosters angefragt werden m\u00fcssen. Stattdessen liegen die Daten gesichert bei <strong>CloudFlare<\/strong>, welches diese Daten auf Wunsch auch f\u00fcr eine schnellere Auslieferung optimiert. Dieses Verfahren hat Vorteile sowohl f\u00fcr den Webhoster als auch f\u00fcr Sie als Kunden. Der Webhoster kann seinen Kunden einen zus\u00e4tzlichen Mehrwert\u00a0anbieten, der sicher ist, aber keinen Speicherplatz einnimmt und\u00a0einen zus\u00e4tzlichen Schutz bietet. Der Kunde auf der anderen Seite profitiert von einer besseren Geschwindigkeit und kann ggf. zus\u00e4tzliche Lizenzen f\u00fcr Optimierungssoftware in seinem CMS einsparen.[\/vc_column_text][vc_column_text]\n<h2>Wie k\u00f6nnen Sie CloudFlare aktivieren?<\/h2>\n<p>Auch wenn <strong>CloudFlare<\/strong> von vielen Webhostern angeboten wird, ist das <strong>CDN<\/strong> nicht immer standardm\u00e4\u00dfig aktiviert. M\u00f6chten Sie <strong>CloudFlare<\/strong> nutzen, dann bieten Ihnen die Hosting Anbieter die M\u00f6glichkeit, das <strong>CDN<\/strong> \u00fcber die Einstellungen bzw. das Kontrollcenter oder den Kundenbereich zu aktivieren. Sofern <strong>CloudFlare<\/strong> in Ihrem Webosting oder Server Paket enthalten ist, ist die Aktivierung kostenlos und es fallen keine weiteren Kosten an. M\u00f6chten Sie <strong>CloudFlare<\/strong> nutzen und die Option ist nicht verf\u00fcgbar, dann m\u00fcssen Sie sich an Ihren Hosting Provider wenden und dort erfragen, ob die Aktivierung in Ihrem Tarif bzw. bei dem Hoster generell m\u00f6glich ist. Hier kann man Ihnen au\u00dferdem bei der Aktivierung helfen und eventuelle Fragen beantworten.<\/p>\n<p>In unserem Beispiel der <a href=\"https:\/\/www.webhoster.ag\/webhosting\/\" target=\"_blank\" rel=\"noopener noreferrer\">webhoster.de AG<\/a>, oder <a href=\"https:\/\/www.ehrenwert-it.de\" target=\"_blank\" rel=\"noopener noreferrer\">Agentur Ehrenwert<\/a> k\u00f6nnen Sie Cloudflare im Administrationsinterface <a href=\"https:\/\/webhosting.de\/es\/plesk-joomla-toolkit\/\">Plesk<\/a> administrieren.<\/p>\n<p>Bitte beachten Sie, dass Cloudflare in diesem Fall nur \u00fcber Subdomains funktioniert, also https:\/\/www.ihrefirma.de und nicht https:\/\/ihrefirma.de. Dies ist bedingt durch das DNS System in Bezug auf CNAME Eintr\u00e4ge.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8220;2131&#8243; img_size=&#8220;large&#8220; alignment=&#8220;center&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Im Administrationsmen\u00fc finden Sie im Hauptbereich &#8222;Website&amp;Domains&#8220; auf der rechten Seite den Men\u00fcpunkt <strong>Servershield von CloudFlare<\/strong>.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_plesk_endkunde.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-2788\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_plesk_endkunde-1024x802.png\" alt=\" width=\"618\" height=\"484\" \/><\/a><\/p>\n<h2>Cloudflare aktivieren<\/h2>\n<p>Wenn Ihr Account schon bei Cloudflare aktiviert wurde gelangen Sie direkt ins Cloudflare Men\u00fc. Andernfalls k\u00f6nnen Sie sich bei Cloudflare direkt anmelden und die Logindaten in das Anmeldeformular eingeben. Wenn Sie mehrere Domains \u00a0bei Cloudflare betreiben, k\u00f6nnen Sie alle mit dem selben Account anmelden um die Domains einfacher verwalten zu k\u00f6nnen.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_plesk_endkunde_logindaten.png\"><img decoding=\"async\" class=\"alignnone size-large wp-image-2787\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_plesk_endkunde_logindaten-1024x802.png\" alt=\" width=\"618\" height=\"484\" \/><\/a><\/p>\n<h2>Das Cloudflare Men\u00fc<\/h2>\n<p>Nachdem Sie sich angemeldet haben stehen die grundlegenden Funktionen direkt im Plesk Men\u00fc zur Verf\u00fcgung. Zur exakten Einrichtung der Domain eignet sich das allerdings nicht. Aktivieren Sie hier einfach Ihre Domain(s) in dem Sie auf &#8222;on&#8220; klicken. Die Domain wird dann Ihrem Cloudflare Account hinzugef\u00fcgt. In diesem Schritt erscheinen noch ein paar Hinweise, oder m\u00f6glicherweise auch Fehlermeldungen, wenn Sie die Domain bereits einem anderen Cloudflare Account zugewiesen hatten, oder der DNS nicht konfigurierbar ist.<\/p>\n<p>In der Regel ist der Nameserver aber extern, somit k\u00f6nnen Sie diese Hinweise dann ignorieren \u00a0und Ihren DNS Server manuell ver\u00e4ndern. \u00a0Mehr dazu weiter unten.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_plesk_endkunde_dashboard.png\"><img decoding=\"async\" class=\"alignnone size-full wp-image-2786\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_plesk_endkunde_dashboard.png\" alt=\" width=\"833\" height=\"728\" \/><\/a><\/p>\n<h2>Cloudflare Hauptmen\u00fc<\/h2>\n<p>Melden Sie sich direkt bei Cloudflare.com mit Ihren Logindaten an. Dann wird Ihnen folgendes Hauptmen\u00fc angezeigt. Wichtig ist nun im ersten Schritt, dass Ihre Website mit einem Zertifikat ausgestattet wird, bzw. das bereits vorhandene \u00a0Zertifikat auf dem Server (z.B. mit Letsencrypt) eine korrekte \u00a0Verschl\u00fcsselung erm\u00f6glicht. \u00a0Bei Cloudflare gibt es verschiedene M\u00f6glichkeiten ein Zertifkat auszustellen. Allerdings f\u00fchrt das Flexible Zertifikat oftmals zu Problemen wenn die Domain nicht vollst\u00e4ndig verschl\u00fcsselt ist.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_endkunde_dashboard.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2784\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_endkunde_dashboard-1024x802.png\" alt=\" width=\"618\" height=\"484\" \/><\/a><\/p>\n<p>Deshalb m\u00fcssen wir im n\u00e4chsten Schritt zun\u00e4chst die richtige Verschl\u00fcsselungsmethode ausw\u00e4hlen.<\/p>\n<h2>Cloudflare Crypto<\/h2>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_crypto_full.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2781\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_crypto_full.png\" alt=\" width=\"971\" height=\"407\" \/><\/a><\/p>\n<p>Stellen Sie den Modus &#8222;Full&#8220; ein. Ein \u00a0Zertifikat wird dann von Cloudflare erstellt sofern auf Ihrem Webserver bereits ein Zertifikat aktiviert ist.<\/p>\n<p>Dieser Vorgang kann laut Cloudflare 24h dauern. Aber bei den bezahlten Accounts geht dieses innerhalb weniger Minuten nachdem Sie die Domain umgestellt haben.<\/p>\n<p>Achten Sie also darauf, dass in Ihrem Plesk Account ein g\u00fcltiges Zertifikat hinterlegt ist. Dies kann ein gekauftes Zertifikat sein, oder ein kostenloses LetsEncrypt Zertifikat. Sie sollten im Plesk auch die Option ausw\u00e4hlen, dass eine Umleitung von http auf https erfolgt und die Domain am besten \u00fcber eine Subdomain wie www. erreichbar ist.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_crypto_alwayshttps.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2780\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_crypto_alwayshttps.png\" alt=\"cloudflare_crypto_alwayshttps\" width=\"958\" height=\"210\" \/><\/a><\/p>\n<h2>HTTP Strict Transport Security<\/h2>\n<p>Mit der Option Always use HTTPS werden ebenfalls alle http Anfragen auf https umgeleitet und nur noch verschl\u00fcsselt \u00fcbertragen.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_hsts.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2796\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_hsts.png\" alt=\"cloudflare_hsts\" width=\"959\" height=\"159\" \/><\/a><\/p>\n<p>Wenn sp\u00e4ter alles funktioniert und die Anfragen \u00fcber Cloudflare geleitet werden, kann die Option <a href=\"https:\/\/de.wikipedia.org\/wiki\/HTTP_Strict_Transport_Security\" target=\"_blank\" rel=\"noopener noreferrer\">HSTS<\/a> aktiviert werden. Hier ist aber dringend zu beachten, dass die Domain dann nur noch verschl\u00fcsselt vom eingesetzten Browser abgerufen werden kann. Bei Zertifikatsfehlern oder anderen Problemen auf CMS Seite kann der Aufruf nicht mehr \u00fcber http:\/\/ erfolgen.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h2>Web Application Firewall<\/h2>\n<p>Nun geht es weiter mit der <strong>Cloudflare Firewall<\/strong> die in den kostenpflichtigen Tarifen bereits mit der Web Application Firewall verf\u00fcgbar ist. Bei der kostenlosen Cloudflare Variante steht dieses leider nicht zur Verf\u00fcgung.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_firewall.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2785\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_firewall-1024x260.png\" alt=\" width=\"618\" height=\"157\" \/><\/a><\/p>\n<p>Klicken Sie im Men\u00fc auf Firewall und w\u00e4hlen Sie dann auf der Seite die Web Application Firewall aus. Mit dieser k\u00f6nnen Sie dann effektiv bekannte Angriffsversuche auf Ihre Website verhindern.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_waf_wordpress.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2793\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_waf_wordpress-684x1024.png\" alt=\"cloudflare_waf_wordpress\" width=\"618\" height=\"925\" \/><\/a><\/p>\n<p>In diesem Beispiel gehen wir einmal davon aus, dass die Website mit WordPress erstellt wurde. Wenn Sie <a href=\"https:\/\/webhosting.de\/es\/joomla-website-zu-wordpress-umziehen\/\">Joomla<\/a> verwenden, w\u00e4hlen Sie am besten die Joomla Regeln aus.<\/p>\n<p>In der Regel laufen auf dem Server auch Firewalls wie <a href=\"https:\/\/webhosting.de\/es\/plesk-modsecurity-aktivieren\/\">mod_security<\/a> mit entsprechenden Regeln von z.B. Atomic oder Comodo. Es macht aber immer Sinn Angriffe bereits ausserhalb der eigenen Infrastruktur zu filtern. Somit entsteht weniger Last auf dem Server.<\/p>\n<h2>Cache aktivieren<\/h2>\n<p>Weiter geht&#8217;s mit dem Cloudflare Cache.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_speed_caching.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2790\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_speed_caching-1024x665.png\" alt=\"cloudflare_speed_caching\" width=\"618\" height=\"401\" \/><\/a><\/p>\n<p>Stellen Sie den Caching Level auf Standard. Diese Option kann man sich sp\u00e4ter noch einmal ansehen, wenn der erste Traffic \u00fcber Cloudflare geleitet wird. Mit dem Button ganz oben rechts kann der Cache dann auch kurzfristig geleert werden. Dies ist sinnvoll, wenn an der Seite gearbeitet wird und der lokale Cache entfernt wurde. Hierzu kann auch der unten gezeigte developer Modus aktiviert werden, in dem Fall leitet cloudflare die Anfragen unver\u00e4ndert weiter.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_cache_alwayson_dev.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2779\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_cache_alwayson_dev.png\" alt=\"cloudflare_cache_alwayson_dev\" width=\"963\" height=\"477\" \/><\/a><\/p>\n<p>Eine insbesondere f\u00fcr statische Seiten praktische Funktion ist always on. Cloudflare liefert dann die Seite an den Besucher aus, auch wenn der Server eine Fehlfunktion hat. In der Regel wird dann allerdings auch ein Hinweis angezeigt und dem Kunden die M\u00f6glichkeit gegeben den Abruf noch einmal zu testen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h2>Cloudflare Speed<\/h2>\n<h2><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_speed_settings.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2792\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_speed_settings-1024x721.png\" alt=\"cloudflare_speed_settings\" width=\"618\" height=\"435\" \/><\/a><\/h2>\n<p>Mehr als nur ein CDN. Mit Cloudflare k\u00f6nnen Sie den Cache optimal nutzen und auch Ihre statischen Daten optimieren lassen. So stehen neben dem automatischen Minify, also der Zusammenfassung von javascript, css und html auch eine automatische Bildoptimierung zur Verf\u00fcgung. Zu gro\u00dfe Bilder werden dann in der Gr\u00f6\u00dfe nahezu verlustfrei verkleinert.<\/p>\n<p>Dies macht insbesondere dann Sinn, wenn man seine hochgeladenen Bilder nicht vorher optimiert hat, oder das verwendete CMS aus dem Bild ganz viele unterschiedliche Gr\u00f6\u00dfen erstellt. Um beim google Speed Test \u00fcberall in den gr\u00fcnen Bereich zu kommen empfiehlt es sich aber weiterhin vor dem Hochladen der Bilder entweder eine teilweise kostenlose Version von tinypng zu nehmen, oder die Seite mit dem google Pagespeed Insights Tool abzurufen. Google stellt dann optimierte Bilder zum Download zur Verf\u00fcgung die man dann einfach ersetzen kann.<\/p>\n<h2>Weitere Funktionen: Mirage<\/h2>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_speed_mirage.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2791\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_speed_mirage.png\" alt=\"cloudflare_speed_mirage\" width=\"957\" height=\"778\" \/><\/a><\/p>\n<p>Cloudflare Mirage ist eine sch\u00f6ne Funktion, um Webseiten schneller an langsame Verbindungen oder Ger\u00e4te mit kleinerem Display auszuliefern.<\/p>\n<p>Hier werden dann Bilder in geringerer Aufl\u00f6sung und Gr\u00f6\u00dfe \u00fcbertragen, damit das verwendete Endger\u00e4t die Seite in einer optimalen Zeit l\u00e4d und trotzdem alles gut erkennen kann.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h2>DNS \u00a0Einstellungen anpassen<\/h2>\n<p>Wenn alle Einstellungen durchgef\u00fchrt sind kann im letzten Schritt die Domain zu cloudflare geroutet werden.<\/p>\n<p>Da sich diese Einstellung sofort auf die Verf\u00fcgbarkeit der Domain auswirkt sollten wir noch einmal \u00fcberpr\u00fcfen ob folgende Punkte auch durchgef\u00fchrt wurden:<\/p>\n<ol>\n<li>Die Domain wurde auf eine Subdomain umgestellt wie www.ihrefirma.de in der Konfiguration (Hosting Einstellungen) des Plesk und auch im Content Management System z.B. unter Einstellungen bei WordPress.<\/li>\n<li>Es gibt ein g\u00fcltiges Zertifikat und die Domain ist fehlerfrei unter https:\/\/www.ihrefirma.de erreichbar.<\/li>\n<li>Bei Cloudflare ist der Crypto Modus <strong>Full<\/strong> aktiviert.<\/li>\n<\/ol>\n<p>Wir k\u00f6nnen nun den DNS \u00a0Eintrag setzen. Hierzu sind 2 Eintr\u00e4ge erforderlich die man im DNS Manager \u00e4ndern bzw. hinzuf\u00fcgen kann. Es sind \u00a02 CNAME Eintr\u00e4ge. Einmal www.ihrefirma.de , also der Domainname mit www. mit dem CNAME \u00a0Ziel www.ihrefirma.de.cdn.cloudflare.net. Achten Sie darauf, dass Sie sich hier nicht verschreiben. Man vergisst gerne das cdn. in der Domain.<\/p>\n<p>Der 2. Eintrag ist dann ein CNAME Eintrag f\u00fcr cf.www.ihrefirma.de \u00a0mit dem Ziel der root Domain, also ihrefirma.de.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_dns.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2783\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_dns.png\" alt=\"cloudflare_dns\" width=\"718\" height=\"121\" \/><\/a><\/p>\n<p>Es kann nun sein, dass das Zertfikat bei Cloudflare noch nicht verifiziert ist und somit nur eine Fehlermeldung erscheint. Warten Sie am besten 10-15 Minuten und versuchen Sie mehrmals auf die Domain zuzugreifen mit https:\/\/www.ihrefirma.de .<\/p>\n<p>Testen \u00a0Sie es am besten auch mit externen Scripten wie google pagespeed insights, gtmetrix, oder pingdom.<\/p>\n<h2>Statistik<\/h2>\n<p>Sobald der erste Traffic durchgeleitet wird, sehen Sie bei den Zugriffsstatistiken die ersten Aufrufe. Stellen Sie zu Beginn die Statistik auf 6 Stunden \u00a0um erste \u00a0Werte zu sehen.<\/p>\n<p><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_statistik.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2799\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2017\/07\/cloudflare_statistik-1024x726.png\" alt=\"cloudflare_statistik\" width=\"618\" height=\"438\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\">Gl\u00fcckwunsch.<\/h2>\n<p style=\"text-align: center;\">Nun ist Ihre Seite \u00fcber Cloudflare beschleunigt und gesichert.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/4&#8243;][vc_facebook][\/vc_column][vc_column width=&#8220;1\/4&#8243;][vc_tweetmeme type=&#8220;follow&#8220; follow_user=&#8220;webhostingDE&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243;][vc_googleplus][\/vc_column][vc_column width=&#8220;1\/4&#8243;][vc_pinterest][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Wir stellen Ihnen heute mit Cloudflare einen preiswerten Anbieter f\u00fcr grundlegende Website Sicherheit und Beschleunigung vor. Die Abrufgeschwindigkeit Ihrer Website wird immer wichtiger, deshalb ist es sinnvoll neben einem guten Webhoster der sich um die Sicherheit und den Betrieb Ihrer Seite k\u00fcmmert auch noch zus\u00e4tzlichen Schutz durch externe Systeme zu verwenden. Die \u00dcbersicht des\u00a0Cloudflare Systems[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"class_list":["post-38","page","type-page","status-publish","hentry"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":null,"_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":null,"_edit_lock":null,"_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"5331","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"cloudflare","_trp_automatically_translated_slug_lv":"cloudflare","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"cloudflare","_trp_automatically_translated_slug_ja":"%e3%82%af%e3%83%a9%e3%82%a6%e3%83%89%e3%83%95%e3%83%ac%e3%82%a2","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":[],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"1081","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":null,"rank_math_contentai_score":null,"ilj_limitincominglinks":null,"ilj_maxincominglinks":null,"ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":null,"ilj_linkdefinition":null,"_eb_reusable_block_ids":null,"rank_math_focus_keyword":null,"rank_math_og_content_image":{"check":"531c033df8c9e10ebfe88c3cf7b089f1","images":[1282]},"_yoast_wpseo_metadesc":null,"_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":null,"footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/pages\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}