{"id":4284,"date":"2020-10-30T20:27:23","date_gmt":"2020-10-30T19:27:23","guid":{"rendered":"https:\/\/webhosting.de\/wordpress-wartungsmodus-manuell-deaktivieren\/"},"modified":"2020-10-30T20:27:23","modified_gmt":"2020-10-30T19:27:23","slug":"modo-de-mantenimiento-de-wordpress-desactivar-manualmente","status":"publish","type":"post","link":"https:\/\/webhosting.de\/es\/wordpress-wartungsmodus-manuell-deaktivieren\/","title":{"rendered":"Deshabilitar manualmente el modo de mantenimiento de WordPress"},"content":{"rendered":"<p>En algunas situaciones puede ser necesario desactivar el modo de mantenimiento de la <a href=\"https:\/\/webhosting.de\/es\/wordpress-gehackt-bekommen-sie-es-wieder-sicher\/\">WordPress<\/a> manualmente. Esto puede ser el caso, por ejemplo, si el modo de mantenimiento se establece de acuerdo con la \u00faltima <a href=\"https:\/\/webhosting.de\/es\/taegliche-updates-auf-facebook\/\">Actualizaciones<\/a> no se apaga por s\u00ed mismo. En este caso, WordPress permanece en modo de mantenimiento y no se puede acceder a la p\u00e1gina. Una soluci\u00f3n r\u00e1pida al problema es desactivar y luego reinstalar el modo de mantenimiento de WordPress.<\/p>\n<p>\u00bfPor qu\u00e9 y cu\u00e1ndo se utiliza el modo de mantenimiento de WordPress?<br \/>\nPara todas las actualizaciones, que se realizan autom\u00e1ticamente en segundo plano, el programa WordPress tambi\u00e9n cambia autom\u00e1ticamente al modo de mantenimiento. De esta forma, las \u00faltimas actualizaciones de los distintos plugins pueden instalarse sin problemas. Si salta a diferentes p\u00e1ginas durante este tiempo, es posible que el proceso no se complete correctamente y el modo de mantenimiento no se complete correctamente. Pero tambi\u00e9n si quieres cambiar algo en la configuraci\u00f3n de tu Blog de WordPress de vez en cuando, tiene sentido activar el modo de mantenimiento para los visitantes durante este ajuste. De esta manera, los posibles invitados del sitio no recibir\u00e1n ning\u00fan mensaje de error durante este tiempo, lo que podr\u00eda asustarlos. Dado que el modo de mantenimiento de WordPress es est\u00e1ndar en este programa, no es posible iniciarlo manualmente. Si quieres hacer esto de todas formas, usa un plugin para ello, por ejemplo el plugin \"Mantenimiento\", que por supuesto es gratuito.<\/p>\n<p>\u00bfC\u00f3mo puedes saber que el modo de mantenimiento de WordPress ha sido activado?<br \/>\nSi se ha activado el modo de mantenimiento de WordPress de forma autom\u00e1tica o manual, haciendo clic en el <a href=\"https:\/\/webhosting.de\/es\/eine-eigene-webseite-fuer-ihr-unternehmen-ja-oder-nein\/\">sitio web<\/a> una p\u00e1gina blanca con la nota: \"Temporalmente no disponible debido a trabajos de mantenimiento planificados. Vuelve en unos minutos\". Por regla general, el mantenimiento s\u00f3lo deber\u00eda durar unos pocos minutos. Si no es as\u00ed, debe desactivar el m\u00f3dulo de mantenimiento manualmente.<\/p>\n<p>\u00bfC\u00f3mo puedes desactivar manualmente el modo de mantenimiento de WordPress?<br \/>\nComo ya no puedes acceder a tu Blog de WordPress por la nota mencionada, necesitas tu archivo FTP para desactivarlo. As\u00ed que con\u00e9ctese al FTP y vaya directamente al directorio ra\u00edz en la instalaci\u00f3n de WordPress. Adem\u00e1s de todos los archivos, tambi\u00e9n encontrar\u00e1 el archivo llamado \".maintenance\". Este archivo es responsable del modo de mantenimiento de WordPress y lo controla. Si el modo de mantenimiento est\u00e1 ahora atascado y no se cierra autom\u00e1ticamente despu\u00e9s de la actualizaci\u00f3n del programa, elim\u00ednelo borrando el archivo \".maintenance\". Este archivo es creado autom\u00e1ticamente por el programa siempre que el sitio web est\u00e1 en modo de mantenimiento. Cuando el trabajo de mantenimiento se termina, el archivo \".maintenance\" es normalmente borrado autom\u00e1ticamente por el programa de nuevo y el sitio web es liberado de nuevo para todos. Si no es as\u00ed, borre el archivo manualmente como se ha descrito anteriormente. Por \u00faltimo, vuelve a tu sitio web del blog de WordPress. Si aparece de nuevo la nota: \"Temporalmente no disponible debido a trabajos de mantenimiento planificados\". Por favor, vuelva pronto\", s\u00f3lo haga clic en el bot\u00f3n: \"Int\u00e9ntelo de nuevo\". Ahora el sitio web deseado se abrir\u00e1 de nuevo como de costumbre y sus visitantes podr\u00e1n acceder a usted.<br \/>\nSi el modo de mantenimiento se cuelga mientras se actualizan los plug-ins, deber\u00e1 volver a realizar las actualizaciones correctamente.<br \/>\nAs\u00ed que no es muy dif\u00edcil desactivar manualmente un modo de mantenimiento de WordPress si sabes c\u00f3mo hacerlo.<\/p>","protected":false},"excerpt":{"rendered":"<p>In manchen Situationen kann es n\u00f6tig sein, den Wartungsmodus des Programms WordPress manuell zu deaktivieren. Dies kann zum Beispiel der Fall sein, wenn sich der Wartungsmodus nach den neuesten Updates nicht von selbst abschaltet. In diesem Fall verbleibt WordPress weiterhin im Wartungsmodus und Sie k\u00f6nnen nicht auf die Seite zugreifen. Eine schnelle Behebung des Problems [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4284","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":"","_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":null,"_edit_lock":null,"_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"4580","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"wordpress-maintenance-mode-manually-deactivate","_trp_automatically_translated_slug_lv":"wordpress-maintenance-mode-manually-deactivate","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"wordpress-maintenance-mode-manually-deactivate","_trp_automatically_translated_slug_ja":"%e3%83%af%e3%83%bc%e3%83%89%e3%83%97%e3%83%ac%e3%82%b9%e3%81%ae%e3%83%a1%e3%83%b3%e3%83%86%e3%83%8a%e3%83%b3%e3%82%b9%e3%83%a2%e3%83%bc%e3%83%89-%e6%89%8b%e5%8b%95%e3%81%a7%e7%84%a1%e5%8a%b9%e3%81%ab","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":["tp-video-player"],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"1004","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":null,"rank_math_contentai_score":null,"ilj_limitincominglinks":null,"ilj_maxincominglinks":null,"ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":null,"ilj_linkdefinition":["wordpress wartungsmodus manuell deaktivieren"],"_eb_reusable_block_ids":[],"rank_math_focus_keyword":null,"rank_math_og_content_image":null,"_yoast_wpseo_metadesc":"","_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":null,"footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/posts\/4284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/comments?post=4284"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/posts\/4284\/revisions"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/media?parent=4284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/categories?post=4284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webhosting.de\/es\/wp-json\/wp\/v2\/tags?post=4284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}