{"id":41,"date":"2020-10-30T17:29:39","date_gmt":"2020-10-30T16:29:39","guid":{"rendered":"https:\/\/webhosting.de\/datenschutz\/"},"modified":"2025-02-22T15:52:46","modified_gmt":"2025-02-22T14:52:46","slug":"la-protection-des-donnees","status":"publish","type":"page","link":"https:\/\/webhosting.de\/fr\/datenschutz\/","title":{"rendered":"Protection des donn\u00e9es"},"content":{"rendered":"<h1>D\u00e9claration de confidentialit\u00e9<\/h1>\n<h2>1. La protection des donn\u00e9es en un coup d'\u0153il<\/h2>\n<h3>Notes g\u00e9n\u00e9rales<\/h3>\n<p>Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement. Vous trouverez des informations d\u00e9taill\u00e9es sur le th\u00e8me de la protection des donn\u00e9es dans notre d\u00e9claration de protection des donn\u00e9es figurant sous ce texte.<\/p>\n<h3>Collecte de donn\u00e9es sur ce site web<\/h3>\n<h4>Qui est responsable de la collecte des donn\u00e9es sur ce site ?<\/h4>\n<p>Le traitement des donn\u00e9es sur ce site web est effectu\u00e9 par l'exploitant du site web. Vous trouverez les coordonn\u00e9es de ce dernier dans la section \"Informations sur le responsable du traitement\" de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<h4>Comment collectons-nous vos donn\u00e9es ?<\/h4>\n<p>Vos donn\u00e9es sont collect\u00e9es, d'une part, lorsque vous nous les communiquez. Il peut s'agir, par exemple, de donn\u00e9es que vous saisissez dans un formulaire de contact.<\/p>\n<p>D'autres donn\u00e9es sont collect\u00e9es automatiquement ou apr\u00e8s votre consentement par nos syst\u00e8mes informatiques lorsque vous visitez le site. Il s'agit principalement de donn\u00e9es techniques (par exemple, le navigateur Internet, le syst\u00e8me d'exploitation ou l'heure de consultation de la page). La saisie de ces donn\u00e9es s'effectue automatiquement d\u00e8s que vous acc\u00e9dez \u00e0 ce site web.<\/p>\n<h4>\u00c0 quelles fins utilisons-nous vos donn\u00e9es ?<\/h4>\n<p>Une partie des donn\u00e9es est collect\u00e9e afin de garantir une mise \u00e0 disposition sans erreur du site web. D'autres donn\u00e9es peuvent \u00eatre utilis\u00e9es pour analyser votre comportement d'utilisateur. Dans la mesure o\u00f9 des contrats peuvent \u00eatre conclus ou initi\u00e9s via le site web, les donn\u00e9es transmises sont \u00e9galement trait\u00e9es pour des offres de contrat, des commandes ou d'autres demandes de commande.<\/p>\n<h4>Quels sont vos droits concernant vos donn\u00e9es ?<\/h4>\n<p>Vous avez \u00e0 tout moment le droit d'obtenir gratuitement des informations sur l'origine, le destinataire et la finalit\u00e9 de vos donn\u00e9es personnelles enregistr\u00e9es. Vous avez \u00e9galement le droit d'exiger la rectification ou la suppression de ces donn\u00e9es. Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, vous pouvez \u00e0 tout moment r\u00e9voquer ce consentement pour l'avenir. Vous avez \u00e9galement le droit de demander la limitation du traitement de vos donn\u00e9es personnelles dans certaines circonstances. En outre, vous disposez d'un droit de recours aupr\u00e8s de l'autorit\u00e9 de surveillance comp\u00e9tente.<\/p>\n<p>Vous pouvez nous contacter \u00e0 tout moment \u00e0 ce sujet ou pour toute autre question relative \u00e0 la protection des donn\u00e9es.<\/p>\n<h3>Outils d'analyse et outils de tiers<\/h3>\n<p>Lors de la visite de ce site web, votre comportement de navigation peut \u00eatre \u00e9valu\u00e9 statistiquement. Cela se fait principalement \u00e0 l'aide de programmes dits d'analyse.<\/p>\n<p>Vous trouverez des informations d\u00e9taill\u00e9es sur ces programmes d'analyse dans la d\u00e9claration de confidentialit\u00e9 suivante.<\/p>\n<h2>2. l'h\u00e9bergement et les r\u00e9seaux de diffusion de contenu (CDN)<\/h2>\n<p>Nous h\u00e9bergeons le contenu de notre site web chez le fournisseur suivant :<\/p>\n<h3>H\u00e9bergement externe<\/h3>\n<p>Ce site web est h\u00e9berg\u00e9 en externe. Les donn\u00e9es personnelles collect\u00e9es sur ce site sont stock\u00e9es sur les serveurs de l'h\u00e9bergeur\/des h\u00e9bergeurs. Il peut s'agir notamment d'adresses IP, de demandes de contact, de m\u00e9tadonn\u00e9es et de donn\u00e9es de communication, de donn\u00e9es contractuelles, de donn\u00e9es de contact, de noms, de visites de sites web et d'autres donn\u00e9es g\u00e9n\u00e9r\u00e9es par un site web.<\/p>\n<p>L'h\u00e9bergement externe est effectu\u00e9 aux fins de l'ex\u00e9cution du contrat vis-\u00e0-vis de nos clients potentiels et existants (article 6, paragraphe 1, point b) du RGPD) et dans l'int\u00e9r\u00eat d'une mise \u00e0 disposition s\u00fbre, rapide et efficace de notre offre en ligne par un fournisseur professionnel (article 6, paragraphe 1, point f) du RGPD). Si un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement est effectu\u00e9 exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans l'\u00e9quipement terminal de l'utilisateur (par exemple, empreinte digitale de l'appareil) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Notre(nos) h\u00e9bergeur(s) ne traitera(ont) vos donn\u00e9es que dans la mesure o\u00f9 cela est n\u00e9cessaire \u00e0 l'ex\u00e9cution de ses obligations de service et se conformera(ront) \u00e0 nos instructions concernant ces donn\u00e9es.<\/p>\n<p>Nous utilisons le ou les h\u00e9bergeurs suivants :<\/p>\n<p>webhoster.de AG<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons un <a href=\"https:\/\/webhosting.de\/fr\/webhosting-webdesign-und-asp-vertrag-was-sind-die-unterschiede\/\">Contrat<\/a> sur le traitement des commandes (AVV) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci traite les donn\u00e9es personnelles des visiteurs de notre site web uniquement selon nos instructions et dans le respect du RGPD.<\/p>\n<h3>Eclat des nuages<\/h3>\n<p>Nous utilisons le service \"Cloudflare\". Le fournisseur est Cloudflare Inc., 101 Townsend St., San Francisco, CA 94107, USA (ci-apr\u00e8s \"Cloudflare\").<\/p>\n<p>Cloudflare propose un r\u00e9seau de diffusion de contenu distribu\u00e9 dans le monde entier avec DNS. Techniquement, le transfert d'informations entre votre navigateur et notre site web est achemin\u00e9 via le r\u00e9seau de Cloudflare. Cela permet \u00e0 Cloudflare d'analyser le trafic entre votre navigateur et notre site web et de servir de filtre entre nos serveurs et le trafic potentiellement malveillant provenant d'Internet. Pour ce faire, Cloudflare peut \u00e9galement utiliser des cookies ou d'autres technologies permettant de reconna\u00eetre les utilisateurs d'Internet, mais ces technologies ne sont utilis\u00e9es qu'aux fins d\u00e9crites ici.<\/p>\n<p>L'utilisation de Cloudflare est bas\u00e9e sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 fournir notre offre web de la mani\u00e8re la plus s\u00fbre et sans erreur possible (article 6, paragraphe 1, point f du RGPD).<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez ici des d\u00e9tails et des informations suppl\u00e9mentaires sur le th\u00e8me de la s\u00e9curit\u00e9 et de la protection des donn\u00e9es chez Cloudflare : <a href=\"https:\/\/www.cloudflare.com\/privacypolicy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.cloudflare.com\/privacypolicy\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5666\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5666<\/a>.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h2>3. indications g\u00e9n\u00e9rales et informations obligatoires<\/h2>\n<h3>Protection des donn\u00e9es<\/h3>\n<p>Les exploitants de ces pages prennent la protection de vos donn\u00e9es personnelles tr\u00e8s au s\u00e9rieux. Nous traitons vos donn\u00e9es personnelles de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales en mati\u00e8re de protection des donn\u00e9es ainsi qu'\u00e0 la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<p>Lorsque vous utilisez ce site web, diverses donn\u00e9es personnelles sont collect\u00e9es. Les donn\u00e9es personnelles sont des donn\u00e9es qui permettent de vous identifier personnellement. La pr\u00e9sente d\u00e9claration de confidentialit\u00e9 explique quelles donn\u00e9es nous collectons et \u00e0 quelles fins nous les utilisons. Elle explique \u00e9galement comment et dans quel but nous le faisons.<\/p>\n<p>Nous attirons votre attention sur le fait que la transmission de donn\u00e9es sur Internet (par ex. lors de la communication par e-mail) peut pr\u00e9senter des failles de s\u00e9curit\u00e9. Une protection compl\u00e8te des donn\u00e9es contre l'acc\u00e8s par des tiers n'est pas possible.<\/p>\n<h3>Note sur l'organisme responsable<\/h3>\n<p>Le responsable du traitement des donn\u00e9es sur ce site est :<\/p>\n<p>Jan Schumacher<br \/>\niSearch GmbH<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<p>t\u00e9l\u00e9phone : 02924 84154<br \/>\ne-mail : info@isearch.de<\/p>\n<p>Le responsable du traitement est la personne physique ou morale qui, seule ou conjointement avec d'autres, d\u00e9termine les finalit\u00e9s et les moyens du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel (par exemple, les noms, les adresses \u00e9lectroniques ou autres).<\/p>\n<h3>Dur\u00e9e de stockage<\/h3>\n<p>Dans la mesure o\u00f9 aucune dur\u00e9e de stockage sp\u00e9cifique n'a \u00e9t\u00e9 mentionn\u00e9e dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es, vos donn\u00e9es \u00e0 caract\u00e8re personnel restent chez nous jusqu'\u00e0 ce que la finalit\u00e9 du traitement des donn\u00e9es n'ait plus lieu d'\u00eatre. Si vous faites valoir une demande l\u00e9gitime d'effacement ou si vous r\u00e9voquez votre consentement au traitement des donn\u00e9es, vos donn\u00e9es seront effac\u00e9es, \u00e0 moins que nous n'ayons d'autres raisons l\u00e9galement valables de conserver vos donn\u00e9es personnelles (par exemple, des d\u00e9lais de conservation en vertu du droit fiscal ou commercial) ; dans ce dernier cas, l'effacement aura lieu apr\u00e8s la disparition de ces raisons.<\/p>\n<h3>Informations g\u00e9n\u00e9rales sur les bases juridiques du traitement des donn\u00e9es sur ce site web<\/h3>\n<p>Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, nous traitons vos donn\u00e9es personnelles sur la base de l'article 6, paragraphe 1, point a) du RGPD ou de l'article 9, paragraphe 2, point a) du RGPD, dans la mesure o\u00f9 des cat\u00e9gories particuli\u00e8res de donn\u00e9es sont trait\u00e9es conform\u00e9ment \u00e0 l'article 9, paragraphe 1 du RGPD. En cas de consentement explicite au transfert de donn\u00e9es \u00e0 caract\u00e8re personnel vers des pays tiers, le traitement des donn\u00e9es s'effectue en outre sur la base de l'article 49, paragraphe 1, point a) du RGPD. Si vous avez consenti \u00e0 l'enregistrement de cookies ou \u00e0 l'acc\u00e8s \u00e0 des informations dans votre terminal (par ex. via Device-Fingerprinting), le traitement des donn\u00e9es s'effectue en outre sur la base de l'article 25, paragraphe 1, de la loi TDDDG. Ce consentement est r\u00e9vocable \u00e0 tout moment. Si vos donn\u00e9es sont n\u00e9cessaires \u00e0 l'ex\u00e9cution d'un contrat ou \u00e0 la mise en \u0153uvre de mesures pr\u00e9contractuelles, nous traitons vos donn\u00e9es sur la base de l'article 6, paragraphe 1, point b), du RGPD. En outre, nous traitons vos donn\u00e9es si elles sont n\u00e9cessaires pour remplir une obligation l\u00e9gale sur la base de l'article 6, paragraphe 1, point c) du RGPD. Le traitement des donn\u00e9es peut \u00e9galement \u00eatre effectu\u00e9 sur la base de notre int\u00e9r\u00eat l\u00e9gitime conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point f), du RGPD. Les paragraphes suivants de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es informent sur les bases juridiques applicables dans chaque cas.<\/p>\n<h3>D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h3>\n<p>Nous avons d\u00e9sign\u00e9 un responsable de la protection des donn\u00e9es.<\/p>\n<p>Jan Schumacher<br \/>\niSearch GmbH<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<p>t\u00e9l\u00e9phone : 02924 84154<br \/>\ne-mail : info@isearch.de<\/p>\n<h3>Remarque sur la transmission de donn\u00e9es dans des pays tiers non s\u00fbrs du point de vue de la protection des donn\u00e9es ainsi que la transmission \u00e0 des entreprises am\u00e9ricaines qui ne sont pas certifi\u00e9es DPF<\/h3>\n<p>Nous utilisons entre autres des outils d'entreprises dont le si\u00e8ge se trouve dans des pays tiers qui ne sont pas s\u00fbrs du point de vue de la protection des donn\u00e9es, ainsi que des outils am\u00e9ricains dont les fournisseurs ne sont pas certifi\u00e9s selon le cadre de protection des donn\u00e9es UE-\u00c9tats-Unis (DPF). Lorsque ces outils sont actifs, vos donn\u00e9es personnelles peuvent \u00eatre transf\u00e9r\u00e9es vers ces \u00c9tats et y \u00eatre trait\u00e9es. Nous attirons votre attention sur le fait qu'il n'est pas possible de garantir un niveau de protection des donn\u00e9es comparable \u00e0 celui de l'UE dans les pays tiers qui ne sont pas s\u00fbrs en mati\u00e8re de protection des donn\u00e9es.<\/p>\n<p>Nous attirons votre attention sur le fait que les \u00c9tats-Unis, en tant que pays tiers s\u00fbr, pr\u00e9sentent en principe un niveau de protection des donn\u00e9es comparable \u00e0 celui de l'UE. Un transfert de donn\u00e9es vers les \u00c9tats-Unis est donc autoris\u00e9 si le destinataire poss\u00e8de une certification selon le \"EU-US Data Privacy Framework\" (DPF) ou dispose de garanties suppl\u00e9mentaires appropri\u00e9es. Vous trouverez des informations sur les transferts vers des pays tiers, y compris les destinataires des donn\u00e9es, dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<h3>Destinataires des donn\u00e9es \u00e0 caract\u00e8re personnel<\/h3>\n<p>Dans le cadre de nos activit\u00e9s commerciales, nous collaborons avec diff\u00e9rents services externes. Dans ce cadre, il est parfois n\u00e9cessaire de transmettre des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 ces organismes externes. Nous ne transmettons des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 des organismes externes que si cela est n\u00e9cessaire dans le cadre de l'ex\u00e9cution d'un contrat, si nous y sommes contraints par la loi (par ex. transmission de donn\u00e9es aux autorit\u00e9s fiscales), si nous avons un int\u00e9r\u00eat l\u00e9gitime \u00e0 la transmission conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point f), du RGPD ou si une autre base juridique permet la transmission des donn\u00e9es. En cas de recours \u00e0 des sous-traitants, nous ne transmettons les donn\u00e9es \u00e0 caract\u00e8re personnel de nos clients que sur la base d'un contrat de traitement des commandes valable. En cas de traitement conjoint, un contrat de traitement conjoint est conclu.<\/p>\n<h3>R\u00e9vocation de votre consentement au traitement des donn\u00e9es<\/h3>\n<p>De nombreuses op\u00e9rations de traitement des donn\u00e9es ne sont possibles qu'avec votre consentement explicite. Vous pouvez r\u00e9voquer \u00e0 tout moment un consentement d\u00e9j\u00e0 donn\u00e9. La l\u00e9galit\u00e9 du traitement des donn\u00e9es effectu\u00e9 jusqu'\u00e0 la r\u00e9vocation n'est pas affect\u00e9e par la r\u00e9vocation.<\/p>\n<h3>Droit d'opposition \u00e0 la collecte de donn\u00e9es dans des cas particuliers ainsi qu'\u00e0 la publicit\u00e9 directe (art. 21 RGPD)<\/h3>\n<p>LORSQUE LE TRAITEMENT DES DONN\u00c9ES EST EFFECTU\u00c9 SUR LA BASE DE L'ART. 6 ABS. 1 LIT. E OU F DU RGPD, VOUS AVEZ LE DROIT DE VOUS OPPOSER \u00c0 TOUT MOMENT, POUR DES RAISONS TENANT \u00c0 VOTRE SITUATION PARTICULI\u00c8RE, AU TRAITEMENT DE VOS DONN\u00c9ES PERSONNELLES ; CECI S'APPLIQUE \u00c9GALEMENT AU PROFILAGE FOND\u00c9 SUR CES DISPOSITIONS. VOUS TROUVEREZ DANS LA PR\u00c9SENTE D\u00c9CLARATION DE PROTECTION DES DONN\u00c9ES LES BASES JURIDIQUES RESPECTIVES SUR LESQUELLES SE FONDE UN TRAITEMENT. SI VOUS VOUS Y OPPOSEZ, NOUS NE TRAITERONS PLUS VOS DONN\u00c9ES PERSONNELLES CONCERN\u00c9ES, \u00c0 MOINS QUE NOUS NE PUISSIONS D\u00c9MONTRER DES MOTIFS IMP\u00c9RIEUX ET L\u00c9GITIMES POUR LE TRAITEMENT QUI PR\u00c9VALENT SUR VOS INT\u00c9R\u00caTS, VOS DROITS ET VOS LIBERT\u00c9S, OU QUE LE TRAITEMENT SERVE \u00c0 FAIRE VALOIR, \u00c0 EXERCER OU \u00c0 D\u00c9FENDRE DES DROITS EN JUSTICE (OPPOSITION \u00c0 L'ARTICLE 21, PARAGRAPHE 1, DU DSGVO).<\/p>\n<p>SI VOS DONN\u00c9ES PERSONNELLES SONT TRAIT\u00c9ES \u00c0 DES FINS DE PUBLICIT\u00c9 DIRECTE, VOUS AVEZ LE DROIT DE VOUS OPPOSER \u00c0 TOUT MOMENT AU TRAITEMENT DES DONN\u00c9ES PERSONNELLES VOUS CONCERNANT \u00c0 DES FINS DE PUBLICIT\u00c9 DIRECTE ; CECI S'APPLIQUE \u00c9GALEMENT AU PROFILAGE DANS LA MESURE O\u00d9 IL EST LI\u00c9 \u00c0 UNE TELLE PUBLICIT\u00c9 DIRECTE. SI VOUS VOUS Y OPPOSEZ, VOS DONN\u00c9ES PERSONNELLES NE SERONT PLUS UTILIS\u00c9ES \u00c0 DES FINS DE PUBLICIT\u00c9 DIRECTE (OPPOSITION CONFORM\u00c9MENT \u00c0 L'ARTICLE 21, PARAGRAPHE 2, DU TRAIT\u00c9 D'AMSTERDAM).<\/p>\n<h3>Droit de recours aupr\u00e8s de l'autorit\u00e9 de surveillance comp\u00e9tente<\/h3>\n<p>En cas de violation du RGPD, les personnes concern\u00e9es disposent d'un droit de recours aupr\u00e8s d'une autorit\u00e9 de contr\u00f4le, notamment dans l'\u00c9tat membre de leur r\u00e9sidence habituelle, de leur lieu de travail ou du lieu de la violation pr\u00e9sum\u00e9e. Ce droit de recours s'exerce sans pr\u00e9judice des autres voies de recours administratives ou judiciaires.<\/p>\n<h3>Droit \u00e0 la portabilit\u00e9 des donn\u00e9es<\/h3>\n<p>Vous avez le droit de vous faire remettre ou de faire remettre \u00e0 un tiers, dans un format courant et lisible par machine, les donn\u00e9es que nous traitons de mani\u00e8re automatis\u00e9e sur la base de votre consentement ou en ex\u00e9cution d'un contrat. Si vous demandez la transmission directe des donn\u00e9es \u00e0 un autre responsable, cela ne se fera que dans la mesure o\u00f9 cela est techniquement possible.<\/p>\n<h3>Acc\u00e8s, rectification et suppression<\/h3>\n<p>Dans le cadre des dispositions l\u00e9gales en vigueur, vous avez \u00e0 tout moment le droit d'obtenir gratuitement des informations sur vos donn\u00e9es personnelles enregistr\u00e9es, leur origine et leur destinataire ainsi que sur la finalit\u00e9 du traitement des donn\u00e9es et, le cas \u00e9ch\u00e9ant, un droit de rectification ou de suppression de ces donn\u00e9es. Pour cela, ainsi que pour toute autre question relative aux donn\u00e9es personnelles, vous pouvez nous contacter \u00e0 tout moment.<\/p>\n<h3>Droit \u00e0 la limitation du traitement<\/h3>\n<p>Vous avez le droit de demander la limitation du traitement de vos donn\u00e9es personnelles. Pour ce faire, vous pouvez nous contacter \u00e0 tout moment. Le droit \u00e0 la limitation du traitement existe dans les cas suivants :<\/p>\n<ul>\n<li>Si vous contestez l'exactitude de vos donn\u00e9es \u00e0 caract\u00e8re personnel enregistr\u00e9es chez nous, nous avons g\u00e9n\u00e9ralement besoin de temps pour le v\u00e9rifier. Pendant la dur\u00e9e de la v\u00e9rification, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.<\/li>\n<li>Si le traitement de vos donn\u00e9es personnelles s'est produit\/se produit de mani\u00e8re ill\u00e9gale, vous pouvez demander la limitation du traitement des donn\u00e9es au lieu de leur suppression.<\/li>\n<li>Si nous n'avons plus besoin de vos donn\u00e9es \u00e0 caract\u00e8re personnel, mais que vous en avez besoin pour exercer, d\u00e9fendre ou faire valoir des droits juridiques, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel au lieu de leur suppression.<\/li>\n<li>Si vous avez fait opposition conform\u00e9ment \u00e0 l'article 21, paragraphe 1, du RGPD, une mise en balance de vos int\u00e9r\u00eats et des n\u00f4tres doit \u00eatre effectu\u00e9e. Tant qu'il n'a pas \u00e9t\u00e9 d\u00e9termin\u00e9 quels int\u00e9r\u00eats pr\u00e9valent, vous avez le droit d'exiger la limitation du traitement de vos donn\u00e9es personnelles.<\/li>\n<\/ul>\n<p>Si vous avez limit\u00e9 le traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel, ces donn\u00e9es - \u00e0 l'exception de leur conservation - ne peuvent \u00eatre trait\u00e9es qu'avec votre consentement ou pour la constatation, l'exercice ou la d\u00e9fense de droits en justice ou pour la protection des droits d'une autre personne physique ou morale, ou encore pour un motif d'int\u00e9r\u00eat public important de l'Union europ\u00e9enne ou d'un \u00c9tat membre.<\/p>\n<h3>Chiffrement SSL ou TLS<\/h3>\n<p>Pour des raisons de s\u00e9curit\u00e9 et afin de prot\u00e9ger la transmission de contenus confidentiels, comme par exemple les commandes ou les demandes que vous nous envoyez en tant qu'exploitant du site, ce site utilise un cryptage SSL ou TLS. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d'adresse du navigateur passe de \"http:\/\/\" \u00e0 \"https:\/\/\" et au symbole du cadenas dans la ligne de votre navigateur.<\/p>\n<p>Si le cryptage SSL ou TLS est activ\u00e9, les donn\u00e9es que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<h3>Paiement crypt\u00e9 sur ce site web<\/h3>\n<p>Si, apr\u00e8s la conclusion d'un contrat payant, il existe une obligation de nous transmettre vos donn\u00e9es de paiement (par ex. num\u00e9ro de compte en cas d'autorisation de pr\u00e9l\u00e8vement), ces donn\u00e9es sont n\u00e9cessaires au traitement du paiement.<\/p>\n<p>Le trafic des paiements via les moyens de paiement courants (Visa\/MasterCard, pr\u00e9l\u00e8vement automatique) s'effectue exclusivement via une connexion SSL ou TLS crypt\u00e9e. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d'adresse du navigateur passe de \"http:\/\/\" \u00e0 \"https:\/\/\" et au symbole du cadenas dans la ligne de votre navigateur.<\/p>\n<p>En cas de communication crypt\u00e9e, les donn\u00e9es de paiement que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<h3>Opposition aux e-mails publicitaires<\/h3>\n<p>L'utilisation des donn\u00e9es de contact publi\u00e9es dans le cadre des mentions l\u00e9gales obligatoires pour l'envoi de publicit\u00e9 et de mat\u00e9riel d'information non express\u00e9ment demand\u00e9s est interdite. Les exploitants des pages se r\u00e9servent express\u00e9ment le droit d'engager des poursuites judiciaires en cas d'envoi non sollicit\u00e9 d'informations publicitaires, par exemple par le biais de spams.<\/p>\n<h2>4. collecte de donn\u00e9es sur ce site web<\/h2>\n<h3>Cookies<\/h3>\n<p>Nos pages Internet utilisent ce que l'on appelle des \"cookies\". Les cookies sont de petits paquets de donn\u00e9es qui ne causent aucun dommage \u00e0 votre terminal. Ils sont enregistr\u00e9s sur votre terminal soit temporairement pour la dur\u00e9e d'une session (cookies de session), soit durablement (cookies permanents). Les cookies de session sont automatiquement supprim\u00e9s \u00e0 la fin de votre visite. Les cookies permanents restent enregistr\u00e9s sur votre terminal jusqu'\u00e0 ce que vous les supprimiez vous-m\u00eame ou qu'une suppression automatique soit effectu\u00e9e par votre navigateur web.<\/p>\n<p>Les cookies peuvent provenir de nous (cookies de premi\u00e8re partie) ou d'entreprises tierces (cookies dits de troisi\u00e8me partie). Les cookies tiers permettent d'int\u00e9grer certains services d'entreprises tierces au sein des pages web (par exemple, des cookies pour le traitement des services de paiement).<\/p>\n<p>Les cookies ont diff\u00e9rentes fonctions. De nombreux cookies sont techniquement n\u00e9cessaires, car certaines fonctions du site web ne fonctionneraient pas sans eux (par exemple la fonction de panier d'achat ou l'affichage de vid\u00e9os). D'autres cookies peuvent \u00eatre utilis\u00e9s pour \u00e9valuer le comportement de l'utilisateur ou \u00e0 des fins publicitaires.<\/p>\n<p>Les cookies n\u00e9cessaires \u00e0 l'ex\u00e9cution du processus de communication \u00e9lectronique, \u00e0 la mise \u00e0 disposition de certaines fonctions que vous souhaitez (par ex. pour la fonction de panier d'achat) ou \u00e0 l'optimisation du site web (par ex. cookies de mesure d'audience web) (cookies n\u00e9cessaires) sont enregistr\u00e9s sur la base de l'article 6, paragraphe 1, point f du RGPD, sauf si une autre base juridique est indiqu\u00e9e. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 l'enregistrement des cookies n\u00e9cessaires pour une mise \u00e0 disposition de ses services sans erreur technique et optimis\u00e9e. Si un consentement a \u00e9t\u00e9 demand\u00e9 pour le stockage de cookies et de technologies de reconnaissance comparables, le traitement est effectu\u00e9 exclusivement sur la base de ce consentement (article 6, paragraphe 1, point a) du RGPD et article 25, paragraphe 1 de la TDDDG) ; le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Vous pouvez configurer votre navigateur de mani\u00e8re \u00e0 \u00eatre inform\u00e9 de l'installation de cookies et \u00e0 n'autoriser les cookies qu'au cas par cas, \u00e0 exclure l'acceptation de cookies dans certains cas ou de mani\u00e8re g\u00e9n\u00e9rale, et \u00e0 activer la suppression automatique des cookies \u00e0 la fermeture du navigateur. En cas de d\u00e9sactivation des cookies, la fonctionnalit\u00e9 de ce site web peut \u00eatre limit\u00e9e.<\/p>\n<p>Pour savoir quels cookies et services sont utilis\u00e9s sur ce site, veuillez consulter la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n<h3>Consentement avec Usercentrics<\/h3>\n<p>Ce site web utilise la technologie Consent de Usercentrics pour obtenir votre consentement \u00e0 l'enregistrement de certains cookies sur votre terminal ou \u00e0 l'utilisation de certaines technologies et pour documenter ce consentement conform\u00e9ment \u00e0 la protection des donn\u00e9es. Le fournisseur de cette technologie est Usercentrics GmbH, Sendlinger Stra\u00dfe 7, 80331 Munich, site web : <a href=\"https:\/\/usercentrics.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/usercentrics.com\/de\/<\/a> (ci-apr\u00e8s \"Usercentrics\").<\/p>\n<p>Lorsque vous acc\u00e9dez \u00e0 notre site web, les donn\u00e9es personnelles suivantes sont transmises \u00e0 Usercentrics :<\/p>\n<ul>\n<li>votre\/vos consentement(s) ou le retrait de votre\/vos consentement(s)<\/li>\n<li>Votre adresse IP<\/li>\n<li>Informations sur votre navigateur<\/li>\n<li>Informations sur votre terminal<\/li>\n<li>l'heure de votre visite sur le site<\/li>\n<li>G\u00e9olocalisation<\/li>\n<\/ul>\n<p>En outre, Usercentrics enregistre un cookie dans votre navigateur afin de pouvoir vous attribuer les consentements donn\u00e9s ou leur r\u00e9vocation. Les donn\u00e9es ainsi collect\u00e9es sont conserv\u00e9es jusqu'\u00e0 ce que vous nous demandiez de les supprimer, que vous supprimiez vous-m\u00eame le cookie Usercentrics ou que le but de la conservation des donn\u00e9es ne soit plus valable. Les obligations l\u00e9gales de conservation obligatoires ne sont pas affect\u00e9es.<\/p>\n<p>L'utilisation de Usercentrics a lieu afin d'obtenir les consentements prescrits par la loi pour l'utilisation de certaines technologies. La base juridique pour cela est l'article 6, paragraphe 1, point c du RGPD.<\/p>\n<h3>Consentement avec le cookie de Borlab<\/h3>\n<p>Notre site Internet utilise la technologie Consent de Borlabs Cookie pour obtenir votre consentement \u00e0 l'enregistrement de certains cookies dans votre navigateur ou \u00e0 l'utilisation de certaines technologies et pour documenter ce consentement conform\u00e9ment \u00e0 la protection des donn\u00e9es. Le fournisseur de cette technologie est Borlabs GmbH, R\u00fcbenkamp 32, 22305 Hambourg (ci-apr\u00e8s Borlabs).<\/p>\n<p>Lorsque vous acc\u00e9dez \u00e0 notre site web, un cookie Borlabs est stock\u00e9 dans votre navigateur, dans lequel les consentements que vous avez donn\u00e9s ou le retrait de ces consentements sont enregistr\u00e9s. Ces donn\u00e9es ne sont pas transmises au fournisseur du cookie Borlabs.<\/p>\n<p>Les donn\u00e9es collect\u00e9es sont conserv\u00e9es jusqu'\u00e0 ce que vous nous demandiez de les supprimer ou que vous supprimiez vous-m\u00eame le cookie Borlabs, ou encore jusqu'\u00e0 ce que le but de la conservation des donn\u00e9es ne soit plus valable. Les d\u00e9lais de conservation l\u00e9gaux obligatoires ne sont pas affect\u00e9s. Vous trouverez des d\u00e9tails sur le traitement des donn\u00e9es du cookie de Borlab sous <a href=\"https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/<\/a>.<\/p>\n<p>L'utilisation de la technologie Borlabs Cookie-Consent a lieu afin d'obtenir les consentements prescrits par la loi pour l'utilisation de cookies. La base juridique pour cela est l'article 6, paragraphe 1, point c du RGPD.<\/p>\n<h3>Consentement avec cookiebot<\/h3>\n<p>Notre site web utilise la technologie Consent de Cookiebot pour obtenir votre consentement \u00e0 l'enregistrement de certains cookies sur votre terminal ou \u00e0 l'utilisation de certaines technologies et pour documenter ce consentement conform\u00e9ment \u00e0 la protection des donn\u00e9es. Le fournisseur de cette technologie est Cybot A\/S, Havnegade 39, 1058 Copenhague, Danemark (ci-apr\u00e8s \"Cookiebot\").<\/p>\n<p>Lorsque vous acc\u00e9dez \u00e0 notre site web, une connexion est \u00e9tablie avec les serveurs de Cookiebot afin de recueillir vos consentements et autres d\u00e9clarations relatives \u00e0 l'utilisation des cookies. Ensuite, Cookiebot enregistre un cookie dans votre navigateur afin de pouvoir vous attribuer les consentements donn\u00e9s ou leur r\u00e9vocation. Les donn\u00e9es ainsi collect\u00e9es sont conserv\u00e9es jusqu'\u00e0 ce que vous nous demandiez de les supprimer, que vous supprimiez vous-m\u00eame le cookie de Cookiebot ou que le but de la conservation des donn\u00e9es disparaisse. Les obligations l\u00e9gales de conservation obligatoires ne sont pas affect\u00e9es.<\/p>\n<p>L'utilisation de Cookiebot a lieu afin d'obtenir les consentements prescrits par la loi pour l'utilisation de cookies. La base juridique pour cela est l'article 6, paragraphe 1, point c du RGPD.<\/p>\n<h3>Fichiers journaux du serveur<\/h3>\n<p>Le fournisseur des pages collecte et enregistre automatiquement des informations dans ce que l'on appelle des fichiers journaux du serveur, que votre navigateur nous transmet automatiquement. Il s'agit de<\/p>\n<ul>\n<li>Type et version du navigateur<\/li>\n<li>Syst\u00e8me d'exploitation utilis\u00e9<\/li>\n<li>URL de r\u00e9f\u00e9rence<\/li>\n<li>Nom d'h\u00f4te de l'ordinateur d'acc\u00e8s<\/li>\n<li>Heure de la demande du serveur<\/li>\n<li>Adresse IP<\/li>\n<\/ul>\n<p>Ces donn\u00e9es ne sont pas recoup\u00e9es avec d'autres sources de donn\u00e9es.<\/p>\n<p>La collecte de ces donn\u00e9es s'effectue sur la base de l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que son site web soit pr\u00e9sent\u00e9 sans erreur technique et \u00e0 ce qu'il soit optimis\u00e9 - pour cela, les fichiers journaux du serveur doivent \u00eatre collect\u00e9s.<\/p>\n<h3>Formulaire de contact<\/h3>\n<p>Si vous nous faites parvenir des demandes par le biais du formulaire de contact, les informations que vous avez fournies dans le formulaire de demande, y compris les donn\u00e9es de contact que vous y avez indiqu\u00e9es, sont enregistr\u00e9es chez nous \u00e0 des fins de traitement de la demande et en cas de questions de suivi. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<\/p>\n<p>Le traitement de ces donn\u00e9es est fond\u00e9 sur l'article 6, paragraphe 1, point b), du RGPD, dans la mesure o\u00f9 votre demande est li\u00e9e \u00e0 l'ex\u00e9cution d'un contrat ou est n\u00e9cessaire \u00e0 l'ex\u00e9cution de mesures pr\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 traiter efficacement les demandes qui nous sont adress\u00e9es (article 6, paragraphe 1, point f) du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a) du RGPD) dans la mesure o\u00f9 celui-ci a \u00e9t\u00e9 demand\u00e9 ; le consentement peut \u00eatre retir\u00e9 \u00e0 tout moment.<\/p>\n<p>Les donn\u00e9es que vous avez saisies dans le formulaire de contact restent chez nous jusqu'\u00e0 ce que vous nous demandiez de les supprimer, que vous r\u00e9voquiez votre autorisation de les enregistrer ou que le but de l'enregistrement des donn\u00e9es devienne caduc (par ex. apr\u00e8s le traitement de votre demande). Les dispositions l\u00e9gales contraignantes - en particulier les d\u00e9lais de conservation - ne sont pas affect\u00e9es.<\/p>\n<h3>Inscription sur ce site<\/h3>\n<p>Vous pouvez vous enregistrer sur ce site web afin d'utiliser des fonctions suppl\u00e9mentaires sur le site. Nous n'utilisons les donn\u00e9es saisies \u00e0 cet effet que dans le but d'utiliser l'offre ou le service respectif pour lequel vous vous \u00eates enregistr\u00e9. Les donn\u00e9es obligatoires demand\u00e9es lors de l'enregistrement doivent \u00eatre fournies dans leur int\u00e9gralit\u00e9. Dans le cas contraire, nous refuserons l'enregistrement.<\/p>\n<p>En cas de modifications importantes, par exemple dans l'\u00e9tendue de l'offre ou en cas de modifications n\u00e9cessaires sur le plan technique, nous utilisons l'adresse e-mail indiqu\u00e9e lors de l'enregistrement pour vous en informer par ce biais.<\/p>\n<p>Le traitement des donn\u00e9es saisies lors de l'enregistrement a pour but d'ex\u00e9cuter la relation d'utilisation \u00e9tablie par l'enregistrement et, le cas \u00e9ch\u00e9ant, d'initier d'autres contrats (art. 6, al. 1, let. b du RGPD).<\/p>\n<p>Les donn\u00e9es saisies lors de l'enregistrement sont conserv\u00e9es par nos soins tant que vous \u00eates enregistr\u00e9 sur ce site web et sont ensuite supprim\u00e9es. Les d\u00e9lais de conservation l\u00e9gaux ne sont pas affect\u00e9s.<\/p>\n<h3>Inscription \u00e0 Facebook Connect<\/h3>\n<p>Au lieu de vous inscrire directement sur ce site, vous pouvez le faire avec <a href=\"https:\/\/webhosting.de\/fr\/facebook-likes-kaufen-der-koenigsweg-zur-kundenvertreibung\/\">Facebook<\/a> S'inscrire \u00e0 Connect. Le fournisseur de ce service est Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irlande. Toutefois, selon Facebook, les donn\u00e9es collect\u00e9es sont \u00e9galement transf\u00e9r\u00e9es aux \u00c9tats-Unis et dans d'autres pays tiers.<\/p>\n<p>Si vous d\u00e9cidez de vous inscrire avec Facebook Connect et que vous cliquez sur le bouton \"Login with Facebook\"\/\"Connect with Facebook\", vous serez automatiquement redirig\u00e9 vers la plateforme de Facebook. Vous pouvez vous y connecter avec vos donn\u00e9es d'utilisation. Votre profil Facebook est ainsi reli\u00e9 \u00e0 ce site web ou \u00e0 nos services. Ce lien nous permet d'acc\u00e9der aux donn\u00e9es que vous avez d\u00e9pos\u00e9es sur Facebook. Il s'agit principalement<\/p>\n<ul>\n<li>Nom sur Facebook<\/li>\n<li>Profil Facebook et photo de couverture<\/li>\n<li>Photo de couverture de Facebook<\/li>\n<li>adresse \u00e9lectronique enregistr\u00e9e sur Facebook<\/li>\n<li>ID Facebook<\/li>\n<li>Listes d'amis sur Facebook<\/li>\n<li>Likes Facebook (mentions \"j'aime\")<\/li>\n<li>Anniversaire<\/li>\n<li>Genre<\/li>\n<li>Pays<\/li>\n<li>Langue<\/li>\n<\/ul>\n<p>Ces informations sont utilis\u00e9es pour cr\u00e9er, approvisionner et personnaliser votre compte.<\/p>\n<p>L'enregistrement avec Facebook-Connect et les processus de traitement des donn\u00e9es qui y sont li\u00e9s sont effectu\u00e9s sur la base de votre consentement (article 6, paragraphe 1, point a du RGPD). Vous pouvez r\u00e9voquer ce consentement \u00e0 tout moment avec effet pour l'avenir.<\/p>\n<p>Dans la mesure o\u00f9 des donn\u00e9es personnelles sont collect\u00e9es sur notre site web \u00e0 l'aide de l'outil d\u00e9crit ici et transmises \u00e0 Facebook, nous et Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlande, sommes conjointement responsables de ce traitement de donn\u00e9es (art. 26 RGPD). La responsabilit\u00e9 commune se limite exclusivement \u00e0 la collecte des donn\u00e9es et \u00e0 leur transmission \u00e0 Facebook. Le traitement effectu\u00e9 par Facebook apr\u00e8s la transmission ne fait pas partie de la responsabilit\u00e9 commune. Les obligations qui nous incombent conjointement ont \u00e9t\u00e9 consign\u00e9es dans un accord de traitement conjoint. Le texte de l'accord est disponible \u00e0 l'adresse suivante : <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. En vertu de cet accord, nous sommes responsables de la fourniture des informations relatives \u00e0 la protection des donn\u00e9es lors de l'utilisation de l'outil Facebook et de la mise en \u0153uvre de l'outil sur notre site Web dans le respect de la protection des donn\u00e9es. Facebook est responsable de la s\u00e9curit\u00e9 des donn\u00e9es des produits Facebook. Vous pouvez faire valoir les droits des personnes concern\u00e9es (par ex. demande d'information) concernant les donn\u00e9es trait\u00e9es par Facebook directement aupr\u00e8s de Facebook. Si vous faites valoir les droits des personnes concern\u00e9es aupr\u00e8s de nous, nous sommes tenus de les transmettre \u00e0 Facebook.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a> et <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/policy.php<\/a>.<\/p>\n<p>Pour plus d'informations, veuillez consulter les conditions d'utilisation de Facebook et la politique de confidentialit\u00e9 de Facebook. Vous pouvez les trouver \u00e0 l'adresse suivante : <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a> et <a href=\"https:\/\/de-de.facebook.com\/legal\/terms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/legal\/terms\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>Inscription avec Google<\/h3>\n<p>Au lieu de vous inscrire directement sur ce site, vous pouvez vous inscrire avec Google. Le fournisseur de ce service est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Pour vous inscrire avec Google, vous devez uniquement saisir votre nom Google et votre mot de passe. Google vous identifiera et confirmera votre identit\u00e9 \u00e0 notre site.<\/p>\n<p>Lorsque vous vous connectez avec Google, il est possible que nous utilisions certaines informations de votre compte pour compl\u00e9ter votre profil chez nous. C'est vous qui d\u00e9cidez si et de quelles informations il s'agit dans le cadre de vos param\u00e8tres de s\u00e9curit\u00e9 Google, que vous trouverez ici : <a href=\"https:\/\/myaccount.google.com\/security\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/myaccount.google.com\/security<\/a> et <a href=\"https:\/\/myaccount.google.com\/permissions\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/myaccount.google.com\/permissions<\/a>.<\/p>\n<p>Le traitement des donn\u00e9es qui accompagne l'inscription \u00e0 Google repose sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 permettre \u00e0 nos utilisateurs de s'inscrire le plus facilement possible (article 6, paragraphe 1, point f du RGPD). \u00c9tant donn\u00e9 que l'utilisation de la fonction d'enregistrement est facultative et que les utilisateurs peuvent d\u00e9cider eux-m\u00eames des possibilit\u00e9s d'acc\u00e8s respectives, aucun droit pr\u00e9pond\u00e9rant des personnes concern\u00e9es ne semble s'y opposer.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Fonction de commentaire sur ce site web<\/h3>\n<p>Pour la fonction de commentaire sur cette page, nous enregistrons, outre votre commentaire, les donn\u00e9es relatives au moment de la cr\u00e9ation du commentaire, votre adresse e-mail et, si vous ne publiez pas anonymement, le nom d'utilisateur que vous avez choisi.<\/p>\n<h4>Stockage de l'adresse IP<\/h4>\n<p>Notre fonction de commentaire enregistre les adresses IP des utilisateurs qui r\u00e9digent des commentaires. Comme nous ne v\u00e9rifions pas les commentaires sur ce site avant de les valider, nous avons besoin de ces donn\u00e9es pour pouvoir agir contre leur auteur en cas d'infraction \u00e0 la loi, comme des insultes ou de la propagande.<\/p>\n<h4>S'abonner aux commentaires<\/h4>\n<p>En tant qu'utilisateur du site, vous pouvez vous abonner aux commentaires apr\u00e8s vous \u00eatre inscrit. Vous recevrez un e-mail de confirmation afin de v\u00e9rifier que vous \u00eates bien le propri\u00e9taire de l'adresse e-mail indiqu\u00e9e. Vous pouvez \u00e0 tout moment vous d\u00e9sabonner de cette fonction en cliquant sur un lien dans les e-mails d'information. Dans ce cas, les donn\u00e9es saisies dans le cadre de l'abonnement aux commentaires seront supprim\u00e9es ; si vous nous avez transmis ces donn\u00e9es \u00e0 d'autres fins et \u00e0 un autre endroit (par ex. commande de newsletter), ces donn\u00e9es resteront toutefois chez nous.<\/p>\n<h4>Dur\u00e9e de conservation des observations<\/h4>\n<p>Les commentaires et les donn\u00e9es associ\u00e9es sont enregistr\u00e9s et restent sur ce site jusqu'\u00e0 ce que le contenu comment\u00e9 soit enti\u00e8rement supprim\u00e9 ou que les commentaires doivent \u00eatre supprim\u00e9s pour des raisons juridiques (par exemple, commentaires offensants).<\/p>\n<h4>Base juridique<\/h4>\n<p>L'enregistrement des commentaires se fait sur la base de votre consentement (article 6, paragraphe 1, point a du RGPD). Vous pouvez r\u00e9voquer \u00e0 tout moment le consentement que vous avez donn\u00e9. Il suffit pour cela de nous envoyer un message informel par e-mail. La l\u00e9galit\u00e9 des op\u00e9rations de traitement des donn\u00e9es d\u00e9j\u00e0 effectu\u00e9es n'est pas affect\u00e9e par la r\u00e9vocation.<\/p>\n<h3>ProvenExpert<\/h3>\n<p>Nous avons int\u00e9gr\u00e9 des sceaux d'\u00e9valuation de ProvenExpert sur ce site web. Le fournisseur est Expert Systems AG, Quedlinburger Str. 1, 10589 Berlin, <a href=\"https:\/\/www.provenexpert.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.provenexpert.com<\/a>.<\/p>\n<p>Le sceau ProvenExpert nous permet d'afficher sur notre site Web, sous forme de sceau, les avis de clients qui ont \u00e9t\u00e9 d\u00e9pos\u00e9s aupr\u00e8s de ProvenExpert concernant notre entreprise. Lorsque vous visitez notre site Web, une connexion est \u00e9tablie avec ProvenExpert, ce qui permet \u00e0 ProvenExpert de savoir que vous avez visit\u00e9 notre site Web. ProvenExpert recueille \u00e9galement vos pr\u00e9f\u00e9rences linguistiques afin d'afficher le sceau dans la langue locale que vous avez choisie.<\/p>\n<p>L'utilisation de ProvenExpert est bas\u00e9e sur l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que les \u00e9valuations des clients soient pr\u00e9sent\u00e9es de la mani\u00e8re la plus compr\u00e9hensible possible. Si un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<h2>5. les m\u00e9dias sociaux<\/h2>\n<h3>Facebook<\/h3>\n<p>Des \u00e9l\u00e9ments du r\u00e9seau social Facebook sont int\u00e9gr\u00e9s sur ce site web. Le fournisseur de ce service est Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irlande. Toutefois, selon Facebook, les donn\u00e9es collect\u00e9es sont \u00e9galement transf\u00e9r\u00e9es aux \u00c9tats-Unis et dans d'autres pays tiers.<\/p>\n<p>Vous trouverez ici un aper\u00e7u des \u00e9l\u00e9ments de Facebook Social Media : <a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE<\/a>.<\/p>\n<p>Lorsque l'\u00e9l\u00e9ment de m\u00e9dia social est actif, une connexion directe est \u00e9tablie entre votre terminal et le serveur Facebook. Facebook re\u00e7oit ainsi l'information que vous avez visit\u00e9 ce site web avec votre adresse IP. Si vous cliquez sur le bouton \"J'aime\" de Facebook alors que vous \u00eates connect\u00e9 \u00e0 votre compte Facebook, vous pouvez cr\u00e9er un lien vers le contenu de ce site web sur votre profil Facebook. Facebook peut ainsi attribuer la visite de ce site web \u00e0 votre compte d'utilisateur. Nous attirons votre attention sur le fait qu'en tant que fournisseur des pages, nous n'avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par Facebook. Vous trouverez de plus amples informations \u00e0 ce sujet dans la d\u00e9claration de protection des donn\u00e9es de Facebook sous : <a href=\"https:\/\/de-de.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/privacy\/explanation<\/a>.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Dans la mesure o\u00f9 des donn\u00e9es personnelles sont collect\u00e9es sur notre site web \u00e0 l'aide de l'outil d\u00e9crit ici et transmises \u00e0 Facebook, nous et Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlande, sommes conjointement responsables de ce traitement de donn\u00e9es (art. 26 RGPD). La responsabilit\u00e9 commune se limite exclusivement \u00e0 la collecte des donn\u00e9es et \u00e0 leur transmission \u00e0 Facebook. Le traitement effectu\u00e9 par Facebook apr\u00e8s la transmission ne fait pas partie de la responsabilit\u00e9 commune. Les obligations qui nous incombent conjointement ont \u00e9t\u00e9 consign\u00e9es dans un accord de traitement conjoint. Le texte de l'accord est disponible \u00e0 l'adresse suivante : <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. En vertu de cet accord, nous sommes responsables de la fourniture des informations relatives \u00e0 la protection des donn\u00e9es lors de l'utilisation de l'outil Facebook et de la mise en \u0153uvre de l'outil sur notre site Web dans le respect de la protection des donn\u00e9es. Facebook est responsable de la s\u00e9curit\u00e9 des donn\u00e9es des produits Facebook. Vous pouvez faire valoir les droits des personnes concern\u00e9es (par ex. demande d'information) concernant les donn\u00e9es trait\u00e9es par Facebook directement aupr\u00e8s de Facebook. Si vous faites valoir les droits des personnes concern\u00e9es aupr\u00e8s de nous, nous sommes tenus de les transmettre \u00e0 Facebook.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a> et <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/policy.php<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>X (anciennement Twitter)<\/h3>\n<p>Des fonctions du service X (anciennement Twitter) sont int\u00e9gr\u00e9es sur ce site web. Ces fonctions sont propos\u00e9es par la soci\u00e9t\u00e9 m\u00e8re X Corp., 1355 Market Street, Suite 900, San Francisco, CA 94103, \u00c9tats-Unis. La filiale Twitter International Unlimited Company, One Cumberland Place, Fenian Street, Dublin 2, D02 AX07, Irlande, est responsable du traitement des donn\u00e9es des personnes vivant en dehors des \u00c9tats-Unis.<\/p>\n<p>Lorsque l'\u00e9l\u00e9ment de m\u00e9dia social est actif, une connexion directe entre votre terminal et le serveur X est \u00e9tablie. X (anciennement Twitter) re\u00e7oit ainsi des informations sur la visite de ce site web de votre part. En utilisant X (anciennement Twitter) et la fonction \"Re-Tweet\" ou \"Repost\", les sites web que vous avez visit\u00e9s sont reli\u00e9s \u00e0 votre compte X (anciennement Twitter) et port\u00e9s \u00e0 la connaissance d'autres utilisateurs. Nous attirons votre attention sur le fait qu'en tant que fournisseur des pages, nous n'avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par X (anciennement Twitter). Vous trouverez de plus amples informations \u00e0 ce sujet dans la d\u00e9claration de protection des donn\u00e9es de X (anciennement Twitter) sous : <a href=\"https:\/\/x.com\/de\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/x.com\/de\/privacy<\/a>.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/gdpr.x.com\/en\/controller-to-controller-transfers.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/gdpr.x.com\/en\/controller-to-controller-transfers.html<\/a>.<\/p>\n<p>Vous pouvez modifier vos param\u00e8tres de confidentialit\u00e9 chez X (anciennement Twitter) dans les param\u00e8tres du compte sous <a href=\"https:\/\/x.com\/settings\/account\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/x.com\/settings\/account<\/a> changer.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/2710\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/2710<\/a>.<\/p>\n<h3>Instagram<\/h3>\n<p>Des fonctions du service Instagram sont int\u00e9gr\u00e9es sur ce site web. Ces fonctions sont propos\u00e9es par Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irlande.<\/p>\n<p>Lorsque l'\u00e9l\u00e9ment de m\u00e9dia social est actif, une connexion directe est \u00e9tablie entre votre terminal et le serveur Instagram. Instagram re\u00e7oit ainsi des informations sur la visite de ce site web de votre part.<\/p>\n<p>Si vous \u00eates connect\u00e9 \u00e0 votre compte Instagram, vous pouvez, en cliquant sur le bouton Instagram, relier le contenu de ce site web \u00e0 votre profil Instagram. Instagram peut ainsi associer la visite de ce site web \u00e0 votre compte d'utilisateur. Nous attirons votre attention sur le fait qu'en tant que fournisseur des pages, nous n'avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par Instagram.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Dans la mesure o\u00f9 des donn\u00e9es personnelles sont collect\u00e9es sur notre site web \u00e0 l'aide de l'outil d\u00e9crit ici et transmises \u00e0 Facebook ou Instagram, nous et Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlande, sommes conjointement responsables de ce traitement de donn\u00e9es (art. 26 RGPD). La responsabilit\u00e9 commune se limite exclusivement \u00e0 la collecte des donn\u00e9es et \u00e0 leur transmission \u00e0 Facebook ou Instagram. Le traitement effectu\u00e9 par Facebook ou Instagram apr\u00e8s la transmission ne fait pas partie de la responsabilit\u00e9 commune. Les obligations qui nous incombent conjointement ont \u00e9t\u00e9 consign\u00e9es dans un accord de traitement conjoint. Le texte de l'accord est disponible \u00e0 l'adresse suivante : <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. En vertu de cet accord, nous sommes responsables de la fourniture des informations relatives \u00e0 la protection des donn\u00e9es lors de l'utilisation de l'outil Facebook ou Instagram et de la mise en \u0153uvre de l'outil sur notre site web dans le respect de la protection des donn\u00e9es. Facebook est responsable de la s\u00e9curit\u00e9 des donn\u00e9es des produits Facebook ou Instagram. Vous pouvez faire valoir les droits des personnes concern\u00e9es (par ex. demande d'information) concernant les donn\u00e9es trait\u00e9es par Facebook ou Instagram directement aupr\u00e8s de Facebook. Si vous faites valoir les droits des personnes concern\u00e9es aupr\u00e8s de nous, nous sommes tenus de les transmettre \u00e0 Facebook.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacycenter.instagram.com\/policy\/<\/a> et <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Pour plus d'informations \u00e0 ce sujet, veuillez consulter la d\u00e9claration de confidentialit\u00e9 d'Instagram : <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacycenter.instagram.com\/policy\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>Tumblr<\/h3>\n<p>Ce site web utilise des boutons et d'autres \u00e9l\u00e9ments du service Tumblr. Le fournisseur est Tumblr, Inc, 35 East 21st St, 10th Floor, New York, NY 10010, USA.<\/p>\n<p>Lorsque l'\u00e9l\u00e9ment de m\u00e9dia social est actif, une connexion directe est \u00e9tablie entre votre terminal et le serveur Tumblr. Tumblr re\u00e7oit ainsi des informations sur la visite de ce site web de votre part.<\/p>\n<p>Les boutons Tumblr vous permettent de partager un article ou une page sur Tumblr ou de suivre le fournisseur sur Tumblr. Lorsque vous consultez l'un de nos sites web dot\u00e9 d'un bouton Tumblr, le navigateur \u00e9tablit une connexion directe avec les serveurs de Tumblr. Nous n'avons aucune influence sur l'\u00e9tendue des donn\u00e9es que Tumblr collecte et transmet \u00e0 l'aide de ce plugin. Selon l'\u00e9tat actuel, l'adresse IP de l'utilisateur ainsi que l'URL du site web concern\u00e9 sont transmises.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Pour plus d'informations \u00e0 ce sujet, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Tumblr \u00e0 l'adresse suivante : <a href=\"https:\/\/www.tumblr.com\/privacy\/de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.tumblr.com\/privacy\/de<\/a>.<\/p>\n<h3>LinkedIn<\/h3>\n<p>Ce site web utilise des \u00e9l\u00e9ments du r\u00e9seau LinkedIn. Le fournisseur est LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2, Irlande.<\/p>\n<p>Chaque fois qu'une page de ce site web contenant des \u00e9l\u00e9ments de LinkedIn est consult\u00e9e, une connexion est \u00e9tablie avec les serveurs de LinkedIn. LinkedIn est inform\u00e9 que vous avez visit\u00e9 ce site web avec votre adresse IP. Si vous cliquez sur le bouton \"Recommander\" de LinkedIn et que vous \u00eates connect\u00e9 \u00e0 votre compte LinkedIn, LinkedIn est en mesure d'associer votre visite sur ce site \u00e0 vous et \u00e0 votre compte utilisateur. Nous attirons votre attention sur le fait qu'en tant que fournisseur des pages, nous n'avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par LinkedIn.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.linkedin.com\/help\/linkedin\/answer\/a1343190\/datenubertragung-aus-der-eu-dem-ewr-und-der-schweiz?lang=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/help\/linkedin\/answer\/a1343190\/datenubertragung-aus-der-eu-dem-ewr-und-der-schweiz?lang=de<\/a><\/p>\n<p>Pour plus d'informations, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de LinkedIn \u00e0 l'adresse suivante : <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5448\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5448<\/a>.<\/p>\n<h3>Int\u00e9r\u00eat<\/h3>\n<p>Sur ce site web, nous utilisons des \u00e9l\u00e9ments du r\u00e9seau social Pinterest, qui est exploit\u00e9 par Pinterest Europe Ltd, Palmerston House, 2nd Floor, Fenian Street, Dublin 2, Irlande.<\/p>\n<p>Lorsque vous consultez une page contenant un tel \u00e9l\u00e9ment, votre navigateur \u00e9tablit une connexion directe avec les serveurs de Pinterest. Cet \u00e9l\u00e9ment de m\u00e9dia social transmet alors des donn\u00e9es de protocole au serveur de Pinterest aux \u00c9tats-Unis. Ces donn\u00e9es de protocole peuvent inclure votre adresse IP, l'adresse des sites Web visit\u00e9s qui contiennent \u00e9galement des fonctions Pinterest, le type et les param\u00e8tres du navigateur, la date et l'heure de la demande, votre mode d'utilisation de Pinterest et les cookies.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Pour plus d'informations sur l'objectif, l'\u00e9tendue et le traitement ult\u00e9rieur et l'utilisation des donn\u00e9es par Pinterest, ainsi que sur vos droits et possibilit\u00e9s en mati\u00e8re de protection de votre vie priv\u00e9e, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Pinterest : <a href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.<\/p>\n<h2>6. outils d'analyse et publicit\u00e9<\/h2>\n<h3>Gestionnaire de balises Google<\/h3>\n<p>Nous utilisons le Google Tag Manager. Le fournisseur est Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Le Google Tag Manager est un outil qui nous permet d'int\u00e9grer des outils de suivi ou de statistiques et d'autres technologies sur notre site web. Le Google Tag Manager lui-m\u00eame ne cr\u00e9e pas de profils d'utilisateurs, ne stocke pas de cookies et ne proc\u00e8de pas \u00e0 des analyses ind\u00e9pendantes. Il sert uniquement \u00e0 la gestion et \u00e0 la diffusion des outils qu'il int\u00e8gre. Le Google Tag Manager enregistre toutefois votre adresse IP, qui peut \u00e9galement \u00eatre transmise \u00e0 la soci\u00e9t\u00e9 m\u00e8re de Google aux \u00c9tats-Unis.<\/p>\n<p>L'utilisation de Google Tag Manager est bas\u00e9e sur l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 une int\u00e9gration et une gestion rapides et simples de diff\u00e9rents outils sur son site web. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google Analytics<\/h3>\n<p>Ce site web utilise des fonctions du service d'analyse web Google Analytics. Le fournisseur est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Google Analytics permet \u00e0 l'exploitant du site web d'analyser le comportement des visiteurs du site. Pour ce faire, l'exploitant du site web re\u00e7oit diff\u00e9rentes donn\u00e9es d'utilisation, comme par exemple les pages consult\u00e9es, la dur\u00e9e de la visite, les syst\u00e8mes d'exploitation utilis\u00e9s et l'origine de l'utilisateur. Ces donn\u00e9es sont regroup\u00e9es dans un User-ID et attribu\u00e9es au terminal respectif du visiteur du site web.<\/p>\n<p>En outre, Google Analytics nous permet, entre autres, d'enregistrer vos mouvements de souris et de d\u00e9filement ainsi que vos clics. En outre, Google Analytics utilise diff\u00e9rentes approches de mod\u00e9lisation pour compl\u00e9ter les ensembles de donn\u00e9es collect\u00e9s et utilise des technologies d'apprentissage automatique pour l'analyse des donn\u00e9es.<\/p>\n<p>Google Analytics utilise des technologies qui permettent de reconna\u00eetre l'utilisateur \u00e0 des fins d'analyse du comportement de l'utilisateur (par ex. cookies ou Device-Fingerprinting). Les informations collect\u00e9es par Google sur l'utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h4>Anonymisation des IP<\/h4>\n<p>L'anonymisation IP de Google Analytics est activ\u00e9e. Ainsi, votre adresse IP est abr\u00e9g\u00e9e par Google dans les \u00c9tats membres de l'Union europ\u00e9enne ou dans d'autres \u00c9tats signataires de l'accord sur l'Espace \u00e9conomique europ\u00e9en avant d'\u00eatre transmise aux \u00c9tats-Unis. Ce n'est que dans des cas exceptionnels que l'adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est raccourcie. Google utilisera ces informations pour le compte de l'exploitant de ce site web afin d'\u00e9valuer votre utilisation du site web, de compiler des rapports sur les activit\u00e9s du site web et de fournir \u00e0 l'exploitant du site web d'autres services li\u00e9s \u00e0 l'utilisation du site web et d'Internet. L'adresse IP transmise par votre navigateur dans le cadre de Google Analytics ne sera pas recoup\u00e9e avec d'autres donn\u00e9es de Google.<\/p>\n<h4>plugin de navigateur<\/h4>\n<p>Vous pouvez emp\u00eacher la saisie et le traitement de vos donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant : <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n<p>Vous trouverez plus d'informations sur le traitement des donn\u00e9es des utilisateurs de Google Analytics dans la d\u00e9claration de confidentialit\u00e9 de Google : <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>.<\/p>\n<h4>Signaux Google<\/h4>\n<p>Nous utilisons les signaux de Google. Lorsque vous visitez notre site web, Google Analytics collecte entre autres votre localisation, votre historique de recherche et votre historique YouTube, ainsi que des donn\u00e9es d\u00e9mographiques (donn\u00e9es des visiteurs). Ces donn\u00e9es peuvent \u00eatre utilis\u00e9es pour des publicit\u00e9s personnalis\u00e9es \u00e0 l'aide de Google-Signal. Si vous disposez d'un compte Google, les donn\u00e9es des visiteurs de Google-Signal sont associ\u00e9es \u00e0 votre compte Google et utilis\u00e9es pour des messages publicitaires personnalis\u00e9s. Les donn\u00e9es sont \u00e9galement utilis\u00e9es pour \u00e9tablir des statistiques anonymes sur le comportement de nos utilisateurs.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes avec Google et appliquons int\u00e9gralement les directives strictes des autorit\u00e9s allemandes de protection des donn\u00e9es lors de l'utilisation de Google Analytics.<\/p>\n<h4>Mesure du commerce \u00e9lectronique par Google Analytics<\/h4>\n<p>Ce site web utilise la fonction \"Mesure du commerce \u00e9lectronique\" de Google Analytics. Gr\u00e2ce \u00e0 la mesure du commerce \u00e9lectronique, l'exploitant du site web peut analyser le comportement d'achat des visiteurs du site web afin d'am\u00e9liorer ses campagnes de marketing en ligne. Pour cela, des informations telles que les commandes pass\u00e9es, les valeurs moyennes des commandes, les frais de livraison et le temps \u00e9coul\u00e9 entre la consultation et l'achat d'un produit sont collect\u00e9es. Ces donn\u00e9es peuvent \u00eatre regroup\u00e9es par Google sous un identifiant de transaction qui est attribu\u00e9 \u00e0 l'utilisateur concern\u00e9 ou \u00e0 son appareil.<\/p>\n<h3>Microsoft Publicit\u00e9<\/h3>\n<p>L'exploitant du site utilise Microsoft Advertising. Microsoft Advertising est un programme de publicit\u00e9 en ligne de Microsoft Corporation, One Microsoft Way, Redmond, WA 98052-6399, \u00c9tats-Unis.<\/p>\n<p>Microsoft Advertising nous permet de diffuser des annonces publicitaires dans le moteur de recherche Bing ou sur des sites web tiers lorsque l'utilisateur saisit certains termes de recherche dans Bing (ciblage par mots-cl\u00e9s). En outre, des annonces publicitaires cibl\u00e9es peuvent \u00eatre diffus\u00e9es \u00e0 l'aide des donn\u00e9es utilisateur disponibles chez Microsoft (par ex. donn\u00e9es de localisation et int\u00e9r\u00eats) (ciblage de groupes cibles). En tant qu'exploitant du site, nous pouvons \u00e9valuer ces donn\u00e9es de mani\u00e8re quantitative, par exemple en analysant quels termes de recherche ont conduit \u00e0 la diffusion de nos annonces publicitaires et combien d'annonces ont g\u00e9n\u00e9r\u00e9 des clics correspondants.<\/p>\n<p>Nous utilisons sur ce site le suivi universel des \u00e9v\u00e9nements (UET) de Microsoft Advertising. Dans ce cadre, des donn\u00e9es pseudonymis\u00e9es sont collect\u00e9es afin de suivre les actions que vous effectuez sur nos pages Web apr\u00e8s avoir cliqu\u00e9 sur une annonce publicitaire de Microsoft Advertising. Pour ce faire, UET saisit votre adresse IP (anonymis\u00e9e), les identifiants de l'appareil, les informations sur les param\u00e8tres de l'appareil et du navigateur, l'ID de clic Microsoft (est enregistr\u00e9 dans un cookie), le temps pass\u00e9 sur le site web, les zones du site web qui ont \u00e9t\u00e9 consult\u00e9es, l'annonce par laquelle vous \u00eates arriv\u00e9 sur le site web et le mot-cl\u00e9 cliqu\u00e9.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/learn.microsoft.com\/de-de\/compliance\/regulatory\/offering-eu-model-clauses\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/learn.microsoft.com\/de-de\/compliance\/regulatory\/offering-eu-model-clauses<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/6474\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/6474<\/a>.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h3>Matomo<\/h3>\n<p>Ce site web utilise le service d'analyse web open source Matomo.<\/p>\n<p>Gr\u00e2ce \u00e0 Matomo, nous sommes en mesure de collecter et d'analyser des donn\u00e9es sur l'utilisation de notre site web par les visiteurs. Cela nous permet, entre autres, de savoir quand telle ou telle page a \u00e9t\u00e9 consult\u00e9e et de quelle r\u00e9gion elle provient. Nous collectons \u00e9galement diff\u00e9rents fichiers journaux (par exemple, l'adresse IP, le r\u00e9f\u00e9rent, le navigateur et le syst\u00e8me d'exploitation utilis\u00e9s) et pouvons mesurer si nos visiteurs du site effectuent certaines actions (par exemple, des clics, des achats, etc.).<\/p>\n<p>L'utilisation de cet outil d'analyse est bas\u00e9e sur l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 analyser le comportement des utilisateurs afin d'optimiser \u00e0 la fois son offre web et sa publicit\u00e9. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<h4>Anonymisation des IP<\/h4>\n<p>Pour l'analyse avec Matomo, nous utilisons l'anonymisation IP. Dans ce cas, votre adresse IP est raccourcie avant l'analyse, de sorte qu'elle ne peut plus vous \u00eatre clairement attribu\u00e9e.<\/p>\n<h4>Analyse sans cookie<\/h4>\n<p>Nous avons configur\u00e9 Matomo de mani\u00e8re \u00e0 ce qu'il ne stocke pas de cookies dans votre navigateur.<\/p>\n<h4>H\u00e9bergement<\/h4>\n<p>Nous h\u00e9bergeons Matomo chez le fournisseur tiers suivant :<\/p>\n<p>webhoster.de AG<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h3>Google Ads<\/h3>\n<p>L'exploitant du site web utilise Google Ads. Google Ads est un programme de publicit\u00e9 en ligne de Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Google Ads nous permet de diffuser des annonces publicitaires dans le moteur de recherche Google ou sur des sites web tiers lorsque l'utilisateur saisit certains termes de recherche sur Google (ciblage par mots-cl\u00e9s). En outre, des annonces publicitaires cibl\u00e9es peuvent \u00eatre diffus\u00e9es \u00e0 l'aide des donn\u00e9es utilisateur disponibles chez Google (par ex. donn\u00e9es de localisation et int\u00e9r\u00eats) (ciblage de groupes cibles). En tant qu'exploitant du site, nous pouvons \u00e9valuer ces donn\u00e9es de mani\u00e8re quantitative, par exemple en analysant quels termes de recherche ont conduit \u00e0 la diffusion de nos annonces publicitaires et combien d'annonces ont g\u00e9n\u00e9r\u00e9 des clics correspondants.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/policies.google.com\/privacy\/frameworks\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy\/frameworks<\/a> et <a href=\"https:\/\/business.safety.google\/controllerterms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/business.safety.google\/controllerterms\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google AdSense (non personnalis\u00e9)<\/h3>\n<p>Ce site utilise Google AdSense, un service d'int\u00e9gration d'annonces publicitaires. Le fournisseur est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Nous utilisons Google AdSense en mode \"non personnalis\u00e9\". Contrairement au mode personnalis\u00e9, les annonces publicitaires ne sont donc pas bas\u00e9es sur votre comportement d'utilisateur ant\u00e9rieur et aucun profil d'utilisateur n'est cr\u00e9\u00e9 \u00e0 votre sujet. Au lieu de cela, des informations dites \"contextuelles\" sont utilis\u00e9es pour s\u00e9lectionner les publicit\u00e9s. Les publicit\u00e9s s\u00e9lectionn\u00e9es d\u00e9pendent alors par exemple de votre localisation, du contenu du site web sur lequel vous vous trouvez ou de vos termes de recherche actuels. Pour en savoir plus sur les diff\u00e9rences entre le ciblage personnalis\u00e9 et le ciblage non personnalis\u00e9 avec Google AdSense, voir <a href=\"https:\/\/support.google.com\/adsense\/answer\/9007336\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/adsense\/answer\/9007336<\/a>.<\/p>\n<p>Veuillez noter que m\u00eame si vous utilisez Google Adsense en mode non personnalis\u00e9, des cookies ou des technologies de reconnaissance comparables (par ex. Device-Fingerprinting) peuvent \u00eatre utilis\u00e9s. Selon Google, celles-ci sont utilis\u00e9es pour lutter contre la fraude et les abus.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<p>Vous pouvez adapter vous-m\u00eame vos param\u00e8tres publicitaires dans votre compte d'utilisateur. Pour ce faire, cliquez sur le lien suivant et connectez-vous : <a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/p>\n<p>Pour en savoir plus sur les technologies publicitaires de Google, cliquez ici : <a href=\"https:\/\/policies.google.com\/technologies\/ads\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/technologies\/ads<\/a> et <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google Ads Remarketing<\/h3>\n<p>Ce site web utilise les fonctions de Google Ads Remarketing. Le fournisseur est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Google Ads Remarketing nous permet d'attribuer des personnes qui interagissent avec notre offre en ligne \u00e0 des groupes cibles pr\u00e9cis afin de leur afficher ensuite des publicit\u00e9s bas\u00e9es sur leurs centres d'int\u00e9r\u00eat dans le r\u00e9seau publicitaire de Google (remarketing ou retargeting).<\/p>\n<p>En outre, les groupes cibles publicitaires cr\u00e9\u00e9s avec Google Ads Remarketing peuvent \u00eatre associ\u00e9s aux fonctionnalit\u00e9s inter-appareils de Google. De cette mani\u00e8re, les messages publicitaires personnalis\u00e9s en fonction de vos int\u00e9r\u00eats, qui ont \u00e9t\u00e9 adapt\u00e9s \u00e0 vous en fonction de votre comportement d'utilisation et de navigation ant\u00e9rieur sur un terminal (par ex. t\u00e9l\u00e9phone portable), peuvent \u00e9galement \u00eatre affich\u00e9s sur un autre de vos terminaux (par ex. tablette ou PC).<\/p>\n<p>Si vous disposez d'un compte Google, vous pouvez vous opposer \u00e0 la publicit\u00e9 personnalis\u00e9e en cliquant sur le lien suivant : <a href=\"https:\/\/adssettings.google.com\/anonymous?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/adssettings.google.com\/anonymous?hl=de<\/a>.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Vous trouverez de plus amples informations et les r\u00e8gles de protection des donn\u00e9es dans la d\u00e9claration de confidentialit\u00e9 de Google sous : <a href=\"https:\/\/policies.google.com\/technologies\/ads?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/technologies\/ads?hl=de<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h4>Cr\u00e9ation de groupes cibles avec comparaison des clients<\/h4>\n<p>Pour la cr\u00e9ation de groupes cibles, nous utilisons entre autres la comparaison de clients de Google Ads Remarketing. Pour ce faire, nous transmettons \u00e0 Google certaines donn\u00e9es clients (par ex. des adresses e-mail) issues de nos listes de clients. Si les clients concern\u00e9s sont des utilisateurs de Google et sont connect\u00e9s \u00e0 leur compte Google, des messages publicitaires adapt\u00e9s leur sont pr\u00e9sent\u00e9s au sein du r\u00e9seau Google (par exemple sur YouTube, Gmail ou dans le moteur de recherche).<\/p>\n<h3>Suivi des conversions Google<\/h3>\n<p>Ce site web utilise Google Conversion Tracking. Le fournisseur est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Gr\u00e2ce au suivi des conversions de Google, Google et nous-m\u00eames pouvons savoir si l'utilisateur a effectu\u00e9 certaines actions. Nous pouvons par exemple \u00e9valuer quels boutons de notre site web ont \u00e9t\u00e9 cliqu\u00e9s \u00e0 quelle fr\u00e9quence et quels produits ont \u00e9t\u00e9 particuli\u00e8rement consult\u00e9s ou achet\u00e9s. Ces informations servent \u00e0 \u00e9tablir des statistiques de conversion. Nous apprenons le nombre total d'utilisateurs qui ont cliqu\u00e9 sur nos annonces et les actions qu'ils ont effectu\u00e9es. Nous ne recevons aucune information qui nous permette d'identifier personnellement l'utilisateur. Google lui-m\u00eame utilise des cookies ou des technologies de reconnaissance comparables pour l'identification.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Vous trouverez plus d'informations sur le suivi des conversions de Google dans les r\u00e8gles de confidentialit\u00e9 de Google : <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Meta-Pixel (anciennement Facebook Pixel)<\/h3>\n<p>Ce site web utilise le pixel d'action des visiteurs de Meta pour mesurer la conversion. Le fournisseur de ce service est Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irlande. Toutefois, selon Meta, les donn\u00e9es collect\u00e9es sont \u00e9galement transf\u00e9r\u00e9es aux \u00c9tats-Unis et dans d'autres pays tiers.<\/p>\n<p>Il est ainsi possible de suivre le comportement des visiteurs d'une page apr\u00e8s qu'ils ont \u00e9t\u00e9 redirig\u00e9s vers le site web du fournisseur en cliquant sur une m\u00e9ta-annonce publicitaire. Cela permet d'\u00e9valuer l'efficacit\u00e9 des m\u00e9ta-annonces publicitaires \u00e0 des fins statistiques et d'\u00e9tude de march\u00e9 et d'optimiser les futures mesures publicitaires.<\/p>\n<p>Les donn\u00e9es collect\u00e9es sont anonymes pour nous en tant qu'exploitant de ce site web, nous ne pouvons pas tirer de conclusions sur l'identit\u00e9 des utilisateurs. Les donn\u00e9es sont toutefois enregistr\u00e9es et trait\u00e9es par Meta, de sorte qu'un lien avec le profil d'utilisateur respectif sur Facebook ou Instagram est possible et que Meta utilise les donn\u00e9es \u00e0 ses propres fins publicitaires, conform\u00e9ment \u00e0 la directive d'utilisation des donn\u00e9es de Meta (<a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a>) peut utiliser. Cela permet \u00e0 Meta de diffuser des annonces publicitaires sur les pages de Facebook ou d'Instagram et d'autres canaux publicitaires. En tant qu'exploitant du site, nous n'avons aucune influence sur cette utilisation des donn\u00e9es.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Dans la mesure o\u00f9 des donn\u00e9es personnelles sont collect\u00e9es sur notre site web \u00e0 l'aide de l'outil d\u00e9crit ici et transmises \u00e0 Meta, nous et Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlande, sommes conjointement responsables de ce traitement de donn\u00e9es (art. 26 RGPD). La responsabilit\u00e9 commune se limite exclusivement \u00e0 la collecte des donn\u00e9es et \u00e0 leur transmission \u00e0 Meta. Le traitement effectu\u00e9 par Meta apr\u00e8s le transfert ne fait pas partie de la responsabilit\u00e9 commune. Les obligations qui nous incombent conjointement ont \u00e9t\u00e9 consign\u00e9es dans un accord de traitement conjoint. Le texte de l'accord est disponible \u00e0 l'adresse suivante : <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. En vertu de cet accord, nous sommes responsables de la fourniture des informations relatives \u00e0 la protection des donn\u00e9es lors de l'utilisation de l'outil Meta et de la mise en \u0153uvre de l'outil sur notre site web dans le respect de la protection des donn\u00e9es. Meta est responsable de la s\u00e9curit\u00e9 des donn\u00e9es des produits Meta. Vous pouvez faire valoir les droits des personnes concern\u00e9es (par ex. demande d'information) concernant les donn\u00e9es trait\u00e9es par Facebook ou Instagram directement aupr\u00e8s de Meta. Si vous faites valoir les droits des personnes concern\u00e9es aupr\u00e8s de nous, nous sommes tenus de les transmettre \u00e0 Meta.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> et <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Dans les informations sur la protection des donn\u00e9es de Meta, vous trouverez d'autres indications sur la protection de votre sph\u00e8re priv\u00e9e : <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<p>Vous pouvez \u00e9galement utiliser la fonction de remarketing \"Audiences personnalis\u00e9es\" dans la section Param\u00e8tres des publicit\u00e9s sous <a href=\"https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen<\/a> d\u00e9sactiver la fonctionnalit\u00e9. Pour ce faire, vous devez \u00eatre connect\u00e9 \u00e0 Facebook.<\/p>\n<p>Si vous ne poss\u00e9dez pas de compte Facebook ou Instagram, vous pouvez d\u00e9sactiver la publicit\u00e9 bas\u00e9e sur l'utilisation de Meta sur le site de l'Alliance europ\u00e9enne pour la publicit\u00e9 num\u00e9rique interactive : <a href=\"http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>TikTok Pixel<\/h3>\n<p>Nous avons int\u00e9gr\u00e9 le pixel TikTok sur ce site web. Le fournisseur est TikTok Technology Limited, 10 Earlsfort Terrace, Dublin, D02 T380, Irlande (ci-apr\u00e8s TikTok).<\/p>\n<p>\u00c0 l'aide du pixel TikTok, nous pouvons afficher des publicit\u00e9s adapt\u00e9es aux int\u00e9r\u00eats des visiteurs du site web qui ont consult\u00e9 nos offres sur TikTok (TikTok Ads). En m\u00eame temps, le TikTok Pixel nous permet de d\u00e9terminer l'efficacit\u00e9 de notre publicit\u00e9 sur TikTok. Cela permet d'\u00e9valuer l'efficacit\u00e9 des publicit\u00e9s TikTok \u00e0 des fins statistiques et d'\u00e9tude de march\u00e9 et d'optimiser les futures mesures publicitaires. Pour ce faire, diff\u00e9rentes donn\u00e9es d'utilisation sont trait\u00e9es, telles que l'adresse IP, les pages consult\u00e9es, la dur\u00e9e de la visite, les syst\u00e8mes d'exploitation utilis\u00e9s et l'origine de l'utilisateur, des informations sur l'annonce sur laquelle une personne a cliqu\u00e9 sur TikTok ou un \u00e9v\u00e9nement qui a \u00e9t\u00e9 d\u00e9clench\u00e9 (horodatage). Ces donn\u00e9es sont regroup\u00e9es dans un User-ID et attribu\u00e9es au terminal respectif du visiteur du site.<\/p>\n<p>L'utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a), du RGPD et \u00e0 l'article 25, paragraphe 1, de la TDDDG. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers des pays tiers est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.tiktok.com\/legal\/page\/eea\/privacy-policy\/de-DE\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.tiktok.com\/legal\/page\/eea\/privacy-policy\/de-DE<\/a> et <a href=\"https:\/\/ads.tiktok.com\/i18n\/official\/policy\/controller-to-controller\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/ads.tiktok.com\/i18n\/official\/policy\/controller-to-controller<\/a>.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h3>Tag Pinterest<\/h3>\n<p>Nous avons int\u00e9gr\u00e9 des tags Pinterest sur ce site web. Le fournisseur est Pinterest Europe Ltd, Palmerston House, 2nd Floor, Fenian Street, Dublin 2, Irlande.<\/p>\n<p>Le tag Pinterest sert \u00e0 enregistrer certaines actions que vous effectuez sur notre site web. Ces donn\u00e9es peuvent ensuite \u00eatre utilis\u00e9es pour vous proposer des publicit\u00e9s adapt\u00e9es \u00e0 vos centres d'int\u00e9r\u00eat sur notre site ou sur une autre page du r\u00e9seau publicitaire Pinterest Tag.<\/p>\n<p>\u00c0 cette fin, le tag Pinterest collecte, entre autres, un identifiant de tag, votre localisation et l'URL de r\u00e9f\u00e9rence. En outre, des donn\u00e9es sp\u00e9cifiques \u00e0 l'action, telles que la valeur de la commande, la quantit\u00e9 command\u00e9e, le num\u00e9ro de commande, la cat\u00e9gorie des articles achet\u00e9s et les vues vid\u00e9o peuvent \u00eatre collect\u00e9es.<\/p>\n<p>Pinterest-Tag utilise des technologies qui permettent la reconnaissance de l'utilisateur sur toutes les pages pour analyser le comportement de l'utilisateur (par ex. cookies ou Device-Fingerprinting).<\/p>\n<p>Dans la mesure o\u00f9 un consentement a \u00e9t\u00e9 obtenu, l'utilisation du service susmentionn\u00e9 se fait exclusivement sur la base de l'article 6, paragraphe 1, point a) du RGPD et de l'article 25 de la TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment. Dans la mesure o\u00f9 aucun consentement n'a \u00e9t\u00e9 obtenu, l'utilisation de ce service se fait sur la base de l'article 6, paragraphe 1, point f) du RGPD ; l'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 prendre des mesures de marketing aussi efficaces que possible.<\/p>\n<p>Pinterest est une entreprise mondiale, de sorte qu'un transfert de donn\u00e9es vers les \u00c9tats-Unis peut \u00e9galement avoir lieu. Selon Pinterest, ce transfert de donn\u00e9es est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici : <a href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.<\/p>\n<p>Pour en savoir plus sur Pinterest Tag, cliquez ici : <a href=\"https:\/\/help.pinterest.com\/de\/business\/article\/track-conversions-with-pinterest-tag\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/help.pinterest.com\/de\/business\/article\/track-conversions-with-pinterest-tag<\/a>.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h2>7e bulletin d'information<\/h2>\n<h3>Donn\u00e9es de la newsletter<\/h3>\n<p>Si vous souhaitez recevoir la newsletter propos\u00e9e sur le site, nous avons besoin d'une adresse e-mail ainsi que d'informations qui nous permettent de v\u00e9rifier que vous \u00eates bien le propri\u00e9taire de l'adresse e-mail indiqu\u00e9e et que vous acceptez de recevoir la newsletter. D'autres donn\u00e9es ne sont pas collect\u00e9es ou uniquement sur une base volontaire. Nous utilisons ces donn\u00e9es exclusivement pour l'envoi des informations demand\u00e9es et ne les transmettons pas \u00e0 des tiers.<\/p>\n<p>Le traitement des donn\u00e9es saisies dans le formulaire d'inscription \u00e0 la newsletter s'effectue exclusivement sur la base de votre consentement (article 6, paragraphe 1, point a) du RGPD). Vous pouvez r\u00e9voquer \u00e0 tout moment votre consentement \u00e0 l'enregistrement des donn\u00e9es, de l'adresse e-mail et de leur utilisation pour l'envoi de la newsletter, par exemple en cliquant sur le lien \"se d\u00e9sinscrire\" dans la newsletter. La l\u00e9galit\u00e9 des op\u00e9rations de traitement des donn\u00e9es d\u00e9j\u00e0 effectu\u00e9es n'est pas affect\u00e9e par la r\u00e9vocation.<\/p>\n<p>Les donn\u00e9es que vous avez d\u00e9pos\u00e9es chez nous dans le but de recevoir la newsletter sont enregistr\u00e9es par nous ou par le fournisseur de services de la newsletter jusqu'\u00e0 ce que vous vous d\u00e9sabonniez de la newsletter et sont supprim\u00e9es de la liste de distribution de la newsletter apr\u00e8s le d\u00e9sabonnement de la newsletter ou si la finalit\u00e9 n'est plus respect\u00e9e. Nous nous r\u00e9servons le droit de supprimer ou de bloquer des adresses e-mail de notre liste de diffusion de la newsletter, \u00e0 notre discr\u00e9tion, dans le cadre de notre int\u00e9r\u00eat l\u00e9gitime selon l'article 6, paragraphe 1, point f) du RGPD.<\/p>\n<p>Les donn\u00e9es qui ont \u00e9t\u00e9 enregistr\u00e9es chez nous \u00e0 d'autres fins n'en sont pas affect\u00e9es.<\/p>\n<p>Apr\u00e8s votre d\u00e9sinscription de la liste de distribution de la newsletter, votre adresse e-mail sera \u00e9ventuellement enregistr\u00e9e dans une liste noire chez nous ou chez le fournisseur de services de la newsletter, dans la mesure o\u00f9 cela est n\u00e9cessaire pour emp\u00eacher de futurs mailings. Les donn\u00e9es de la liste noire ne sont utilis\u00e9es qu'\u00e0 cette fin et ne sont pas recoup\u00e9es avec d'autres donn\u00e9es. Cela sert \u00e0 la fois votre int\u00e9r\u00eat et notre int\u00e9r\u00eat \u00e0 respecter les exigences l\u00e9gales lors de l'envoi de newsletters (int\u00e9r\u00eat l\u00e9gitime au sens de l'article 6, paragraphe 1, point f du RGPD). L'enregistrement dans la liste noire n'est pas limit\u00e9 dans le temps. <strong>Vous pouvez vous opposer \u00e0 l'enregistrement si vos int\u00e9r\u00eats pr\u00e9valent sur notre int\u00e9r\u00eat l\u00e9gitime.<\/strong><\/p>\n<h2>8. plugins et outils<\/h2>\n<h3>YouTube avec une protection des donn\u00e9es \u00e9tendue<\/h3>\n<p>Ce site web int\u00e8gre des vid\u00e9os du site web YouTube. L'exploitant du site est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>Lorsque vous visitez l'un de ces sites web sur lesquels YouTube est int\u00e9gr\u00e9, une connexion est \u00e9tablie avec les serveurs de YouTube. Le serveur YouTube est alors inform\u00e9 des pages que vous avez visit\u00e9es. Si vous \u00eates connect\u00e9 \u00e0 votre compte YouTube, vous permettez \u00e0 YouTube d'associer votre comportement de navigation directement \u00e0 votre profil personnel. Vous pouvez emp\u00eacher cela en vous d\u00e9connectant de votre compte YouTube.<\/p>\n<p>Nous utilisons YouTube en mode de protection \u00e9tendue des donn\u00e9es. Selon YouTube, les vid\u00e9os lues en mode de confidentialit\u00e9 \u00e9tendu ne sont pas utilis\u00e9es pour personnaliser la navigation sur YouTube. Les annonces diffus\u00e9es en mode de confidentialit\u00e9 \u00e9tendu ne sont pas non plus personnalis\u00e9es. Aucun cookie n'est plac\u00e9 en mode de confidentialit\u00e9 \u00e9tendu. \u00c0 la place, des \u00e9l\u00e9ments de stockage local sont enregistr\u00e9s dans le navigateur de l'utilisateur, qui contiennent des donn\u00e9es personnelles similaires aux cookies et peuvent \u00eatre utilis\u00e9s pour la reconnaissance. Vous trouverez ici des d\u00e9tails sur le mode de protection des donn\u00e9es \u00e9tendu : <a href=\"https:\/\/support.google.com\/youtube\/answer\/171780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/youtube\/answer\/171780<\/a>.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, d'autres processus de traitement des donn\u00e9es peuvent \u00eatre d\u00e9clench\u00e9s apr\u00e8s l'activation d'une vid\u00e9o YouTube, sur lesquels nous n'avons aucune influence.<\/p>\n<p>L'utilisation de YouTube a lieu dans l'int\u00e9r\u00eat d'une pr\u00e9sentation attrayante de nos offres en ligne. Cela constitue un int\u00e9r\u00eat l\u00e9gitime au sens de l'article 6, paragraphe 1, point f), du RGPD. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Pour plus d'informations sur la protection des donn\u00e9es par YouTube, veuillez consulter leur d\u00e9claration de confidentialit\u00e9 \u00e0 l'adresse suivante : <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Vimeo sans tracking (Do-Not-Track)<\/h3>\n<p>Ce site web utilise des plugins du portail vid\u00e9o Vimeo. Le fournisseur est Vimeo Inc., 555 West 18th Street, New York, New York 10011, USA.<\/p>\n<p>Lorsque vous visitez l'une de nos pages \u00e9quip\u00e9es de vid\u00e9os Vimeo, une connexion est \u00e9tablie avec les serveurs de Vimeo. Le serveur Vimeo est alors inform\u00e9 des pages que vous avez visit\u00e9es. De plus, Vimeo obtient votre adresse IP. Nous avons toutefois configur\u00e9 Vimeo de mani\u00e8re \u00e0 ce qu'il ne suive pas vos activit\u00e9s d'utilisateur et ne place pas de cookies.<\/p>\n<p>L'utilisation de Vimeo a lieu dans l'int\u00e9r\u00eat d'une pr\u00e9sentation attrayante de nos offres en ligne. Cela constitue un int\u00e9r\u00eat l\u00e9gitime au sens de l'article 6, paragraphe 1, point f) du RGPD. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a) du RGPD ; le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne ainsi que, selon Vimeo, sur des \"int\u00e9r\u00eats commerciaux l\u00e9gitimes\". Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/vimeo.com\/privacy<\/a>.<\/p>\n<p>Pour plus d'informations sur le traitement des donn\u00e9es des utilisateurs, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Vimeo \u00e0 l'adresse suivante : <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/vimeo.com\/privacy<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5711\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5711<\/a>.<\/p>\n<h3>Google Fonts (h\u00e9bergement local)<\/h3>\n<p>Ce site utilise ce que l'on appelle les Google Fonts, mis \u00e0 disposition par Google, pour la repr\u00e9sentation homog\u00e8ne des polices de caract\u00e8res. Les Google Fonts sont install\u00e9s localement. Une connexion aux serveurs de Google n'a pas lieu.<\/p>\n<p>Pour plus d'informations sur Google Fonts, voir <a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.google.com\/fonts\/faq<\/a> et dans la d\u00e9claration de confidentialit\u00e9 de Google : <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Google Maps<\/h3>\n<p>Ce site utilise le service de cartographie Google Maps. Le fournisseur est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande. Ce service nous permet d'int\u00e9grer des cartes sur notre site.<\/p>\n<p>Pour utiliser les fonctions de Google Maps, il est n\u00e9cessaire d'enregistrer votre adresse IP. Cette information est g\u00e9n\u00e9ralement transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est enregistr\u00e9e. Le fournisseur de ce site n'a aucune influence sur cette transmission de donn\u00e9es. Si Google Maps est activ\u00e9, Google peut utiliser les polices de caract\u00e8res Google Fonts \u00e0 des fins d'affichage uniforme. Lors de l'appel de Google Maps, votre navigateur charge les Web Fonts n\u00e9cessaires dans le cache de votre navigateur afin d'afficher correctement les textes et les polices.<\/p>\n<p>L'utilisation de Google Maps a lieu dans l'int\u00e9r\u00eat d'une pr\u00e9sentation attrayante de nos offres en ligne et d'un rep\u00e9rage facile des lieux que nous avons indiqu\u00e9s sur le site web. Cela constitue un int\u00e9r\u00eat l\u00e9gitime au sens de l'article 6, paragraphe 1, point f) du RGPD. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/<\/a> et <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/<\/a>.<\/p>\n<p>Vous trouverez plus d'informations sur le traitement des donn\u00e9es des utilisateurs dans la d\u00e9claration de confidentialit\u00e9 de Google : <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google reCAPTCHA<\/h3>\n<p>Nous utilisons \"Google reCAPTCHA\" (ci-apr\u00e8s \"reCAPTCHA\") sur ce site web. Le fournisseur est Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlande.<\/p>\n<p>L'objectif de reCAPTCHA est de v\u00e9rifier si la saisie de donn\u00e9es sur ce site web (par exemple dans un formulaire de contact) est effectu\u00e9e par un \u00eatre humain ou par un programme automatis\u00e9. Pour ce faire, reCAPTCHA analyse le comportement du visiteur du site web \u00e0 l'aide de diff\u00e9rentes caract\u00e9ristiques. Cette analyse commence automatiquement d\u00e8s que le visiteur du site web entre sur le site. Pour l'analyse, reCAPTCHA \u00e9value diff\u00e9rentes informations (par exemple l'adresse IP, le temps pass\u00e9 par le visiteur sur le site web ou les mouvements de souris effectu\u00e9s par l'utilisateur). Les donn\u00e9es collect\u00e9es lors de l'analyse sont transmises \u00e0 Google.<\/p>\n<p>Les analyses reCAPTCHA s'effectuent enti\u00e8rement en arri\u00e8re-plan. Les visiteurs du site web ne sont pas inform\u00e9s qu'une analyse est en cours.<\/p>\n<p>Le stockage et l'analyse des donn\u00e9es sont effectu\u00e9s sur la base de l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 prot\u00e9ger ses offres web contre l'espionnage automatis\u00e9 abusif et les <a href=\"https:\/\/webhosting.de\/fr\/srs-mit-postfix-unter-centos\/\">SPAM<\/a> de la protection des donn\u00e9es. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par exemple, empreintes digitales de l'appareil) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Pour plus d'informations sur Google reCAPTCHA, veuillez consulter les r\u00e8gles de confidentialit\u00e9 de Google et les conditions d'utilisation de Google en cliquant sur les liens suivants : <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a> et <a href=\"https:\/\/policies.google.com\/terms?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/terms?hl=de<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Wordfence<\/h3>\n<p>Nous avons int\u00e9gr\u00e9 Wordfence sur ce site web. Le fournisseur est Defiant Inc., Defiant, Inc., 800 5th Ave Ste 4100, Seattle, WA 98104, USA (ci-apr\u00e8s \"Wordfence\").<\/p>\n<p>Wordfence sert \u00e0 prot\u00e9ger notre site web contre les acc\u00e8s ind\u00e9sirables ou les cyberattaques malveillantes. \u00c0 cette fin, notre site web \u00e9tablit une connexion permanente avec les serveurs de Wordfence afin que ce dernier puisse comparer ses bases de donn\u00e9es avec les acc\u00e8s effectu\u00e9s sur notre site web et les bloquer le cas \u00e9ch\u00e9ant.<\/p>\n<p>L'utilisation de Wordfence est bas\u00e9e sur l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 prot\u00e9ger son site web le plus efficacement possible contre les cyberattaques. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/<\/a>.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h3>SoundCloud<\/h3>\n<p>Des plugins du r\u00e9seau social SoundCloud (SoundCloud Limited, Berners House, 47-48 Berners Street, London W1T 3NF, Royaume-Uni.) peuvent \u00eatre int\u00e9gr\u00e9s \u00e0 ce site web. Les plugins SoundCloud sont reconnaissables au logo SoundCloud sur les pages concern\u00e9es.<\/p>\n<p>Lorsque vous visitez ce site web, une connexion directe entre votre navigateur et le serveur SoundCloud est \u00e9tablie apr\u00e8s l'activation du plugin. SoundCloud re\u00e7oit ainsi l'information que vous avez visit\u00e9 ce site web avec votre adresse IP. Si vous cliquez sur le \"bouton J'aime\" ou le \"bouton Partager\" alors que vous \u00eates connect\u00e9 \u00e0 votre compte utilisateur SoundCloud, vous pouvez lier et\/ou partager le contenu de ce site web avec votre profil SoundCloud. Cela permet \u00e0 SoundCloud d'associer la visite de ce site web \u00e0 votre compte d'utilisateur. Nous attirons votre attention sur le fait qu'en tant que fournisseur des pages, nous n'avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par SoundCloud.<\/p>\n<p>Le stockage et l'analyse des donn\u00e9es sont effectu\u00e9s sur la base de l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 une visibilit\u00e9 aussi large que possible dans les m\u00e9dias sociaux. Si un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement est effectu\u00e9 exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans l'\u00e9quipement terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>La Grande-Bretagne est consid\u00e9r\u00e9e comme un pays tiers s\u00fbr en mati\u00e8re de protection des donn\u00e9es. Cela signifie que la Grande-Bretagne pr\u00e9sente un niveau de protection des donn\u00e9es \u00e9quivalent \u00e0 celui de l'Union europ\u00e9enne.<\/p>\n<p>Pour plus d'informations \u00e0 ce sujet, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de SoundCloud \u00e0 l'adresse suivante : <a href=\"https:\/\/soundcloud.com\/pages\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/soundcloud.com\/pages\/privacy<\/a>.<\/p>\n<p>Si vous ne souhaitez pas que SoundCloud associe la visite de ce site web \u00e0 votre compte utilisateur SoundCloud, veuillez vous d\u00e9connecter de votre compte utilisateur SoundCloud avant d'activer le contenu du plug-in SoundCloud.<\/p>\n<h3>Spotify<\/h3>\n<p>Ce site web int\u00e8gre des fonctions du service musical Spotify. Le fournisseur est Spotify AB, Birger Jarlsgatan 61, 113 56 Stockholm en Su\u00e8de. Les plug-ins Spotify sont reconnaissables au logo vert sur ce site web. Vous trouverez un aper\u00e7u des plugins Spotify sous : <a href=\"https:\/\/developer.spotify.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developer.spotify.com<\/a>.<\/p>\n<p>Ainsi, lorsque vous visitez ce site web, une connexion directe entre votre navigateur et le serveur Spotify peut \u00eatre \u00e9tablie via le plugin. Spotify re\u00e7oit ainsi l'information que vous avez visit\u00e9 ce site web avec votre adresse IP. Si vous cliquez sur le bouton Spotify alors que vous \u00eates connect\u00e9 \u00e0 votre compte Spotify, vous pouvez lier le contenu de ce site web \u00e0 votre profil Spotify. Cela permet \u00e0 Spotify d'attribuer la visite de ce site web \u00e0 votre compte d'utilisateur.<\/p>\n<p>Nous attirons votre attention sur le fait que des cookies de Google Analytics sont utilis\u00e9s lors de l'utilisation de Spotify, de sorte que vos donn\u00e9es d'utilisation peuvent \u00e9galement \u00eatre transmises \u00e0 Google lors de l'utilisation de Spotify. Google Analytics est un outil d'analyse du comportement des utilisateurs du groupe Google, dont le si\u00e8ge se trouve aux \u00c9tats-Unis. Spotify est seul responsable de cette int\u00e9gration. En tant qu'exploitant du site, nous n'avons aucune influence sur ce traitement.<\/p>\n<p>Le stockage et l'analyse des donn\u00e9es sont effectu\u00e9s sur la base de l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que son site web soit dot\u00e9 d'une acoustique attrayante. Si un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement est effectu\u00e9 exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans l'\u00e9quipement terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Pour plus d'informations \u00e0 ce sujet, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Spotify : <a href=\"https:\/\/www.spotify.com\/de\/legal\/privacy-policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.spotify.com\/de\/legal\/privacy-policy\/<\/a>.<\/p>\n<p>Si vous ne souhaitez pas que Spotify puisse associer la visite de ce site web \u00e0 votre compte d'utilisateur Spotify, veuillez vous d\u00e9connecter de votre compte d'utilisateur Spotify.<\/p>\n<h3>ChatGPT<\/h3>\n<p>Nous utilisons ChatGPT pour notre communication avec les clients. Le fournisseur est OpenAI, 3180 18th St, San Francisco, CA 94110, USA, <a href=\"https:\/\/openai.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/openai.com<\/a>.<\/p>\n<p>Lorsque vous entamez une conversation avec nous via notre site web et que ChatGPT est activ\u00e9, vos saisies, y compris les m\u00e9tadonn\u00e9es, sont transmises aux serveurs de ChatGPT et y sont trait\u00e9es afin de g\u00e9n\u00e9rer une r\u00e9ponse appropri\u00e9e.<\/p>\n<p>Nous avons configur\u00e9 ChatGPT de mani\u00e8re \u00e0 ce que les donn\u00e9es personnelles saisies ne soient pas utilis\u00e9es pour entra\u00eener l'algorithme de ChatGPT.<\/p>\n<p>L'utilisation de ChatGPT est bas\u00e9e sur l'article 6, paragraphe 1, point f du RGPD. L'exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que la communication avec les clients soit la plus efficace possible en utilisant des solutions techniques modernes. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Pour plus d'informations, cliquez ici : <a href=\"https:\/\/openai.com\/policies\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/openai.com\/policies\/privacy-policy<\/a>.<\/p>\n<h4>Traitement des commandes<\/h4>\n<p>Nous avons conclu un contrat de traitement des commandes (CTP) pour l'utilisation du service susmentionn\u00e9. Il s'agit d'un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que selon nos instructions et dans le respect du RGPD.<\/p>\n<h2>9. marketing en ligne et programmes d'affiliation<\/h2>\n<h3>Programmes d'affiliation sur ce site<\/h3>\n<p>Nous participons \u00e0 des programmes de partenariat d'affiliation. Dans les programmes de partenariat d'affiliation, des annonces publicitaires d'une entreprise sont plac\u00e9es sur des sites web ou d'autres supports d'autres entreprises du r\u00e9seau de partenaires d'affiliation. Si vous cliquez sur l'une de ces publicit\u00e9s d'affiliation, vous serez redirig\u00e9 vers l'offre promue. Si vous effectuez ensuite une certaine transaction (conversion), l'affili\u00e9 et, le cas \u00e9ch\u00e9ant, le propri\u00e9taire du support sur lequel la publicit\u00e9 est plac\u00e9e \u00e0 cet effet, re\u00e7oivent une r\u00e9mun\u00e9ration. Pour calculer cette r\u00e9mun\u00e9ration, il est n\u00e9cessaire que l'exploitant du r\u00e9seau d'affiliation puisse savoir par quelle annonce publicitaire vous \u00eates arriv\u00e9 sur l'offre en question et que vous avez effectu\u00e9 la transaction pr\u00e9d\u00e9finie. Pour ce faire, des cookies ou des technologies de reconnaissance comparables (par ex. Device-Fingerprinting) sont utilis\u00e9s.<\/p>\n<p>Le stockage et l'analyse des donn\u00e9es sont effectu\u00e9s sur la base de l'article 6, paragraphe 1, point f du RGPD. Les participants au programme d'affiliation ont un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que la r\u00e9mun\u00e9ration des affili\u00e9s soit calcul\u00e9e correctement. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l'acc\u00e8s \u00e0 des informations dans l'\u00e9quipement terminal de l'utilisateur (par exemple, empreintes digitales de l'appareil) au sens de la loi TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Nous participons aux programmes d'affiliation suivants :<\/p>\n<h4>Programme d'affiliation Amazon<\/h4>\n<p>Le fournisseur est Amazon Europe Core S.\u00e0.r.l. Pour plus de d\u00e9tails, veuillez consulter la d\u00e9claration de protection des donn\u00e9es d'Amazon sous : <a href=\"https:\/\/www.amazon.de\/gp\/help\/customer\/display.html?nodeId=201909010\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.amazon.de\/gp\/help\/customer\/display.html?nodeId=201909010<\/a>.<\/p>\n<p>L'entreprise dispose d'une certification selon le \"EU-US Data Privacy Framework\" (DPF). Le DPF est un accord entre l'Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement des donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e selon le DPF s'engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d'informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5776\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5776<\/a>.<\/p>\n<h2>10. Commerce \u00e9lectronique et fournisseurs de paiement<\/h2>\n<h3>Traitement des donn\u00e9es clients et des donn\u00e9es contractuelles<\/h3>\n<p>Nous collectons, traitons et utilisons les donn\u00e9es personnelles des clients et les donn\u00e9es contractuelles pour justifier, d\u00e9finir le contenu et modifier nos relations contractuelles. Nous ne collectons, traitons et utilisons les donn\u00e9es personnelles relatives \u00e0 l'utilisation de ce site web (donn\u00e9es d'utilisation) que dans la mesure o\u00f9 cela est n\u00e9cessaire pour permettre \u00e0 l'utilisateur d'utiliser le service ou de le facturer. L'article 6, paragraphe 1, point b) du RGPD constitue la base juridique de ces donn\u00e9es.<\/p>\n<p>Les donn\u00e9es clients collect\u00e9es sont supprim\u00e9es apr\u00e8s l'ach\u00e8vement de la commande ou la fin de la relation commerciale et l'expiration des d\u00e9lais de conservation l\u00e9gaux \u00e9ventuellement existants. Les d\u00e9lais de conservation l\u00e9gaux ne sont pas affect\u00e9s.<\/p>\n<h3>Transmission de donn\u00e9es lors de la conclusion de contrats pour les boutiques en ligne, les commer\u00e7ants et l'exp\u00e9dition de marchandises<\/h3>\n<p>Lorsque vous commandez des marchandises chez nous, nous transmettons vos donn\u00e9es personnelles \u00e0 l'entreprise de transport charg\u00e9e de la livraison ainsi qu'au prestataire de services de paiement charg\u00e9 du traitement des paiements. Seules les donn\u00e9es dont le prestataire de services concern\u00e9 a besoin pour remplir sa mission sont transmises. La base juridique est l'article 6, paragraphe 1, point b) du RGPD, qui autorise le traitement des donn\u00e9es pour l'ex\u00e9cution d'un contrat ou de mesures pr\u00e9contractuelles. Si vous avez donn\u00e9 votre consentement conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point a) du RGPD, nous transmettrons votre adresse e-mail \u00e0 l'entreprise de transport charg\u00e9e de la livraison afin qu'elle puisse vous informer par e-mail du statut d'exp\u00e9dition de votre commande ; vous pouvez r\u00e9voquer votre consentement \u00e0 tout moment.<\/p>\n<h3>Transmission de donn\u00e9es lors de la conclusion de contrats de services et de contenus num\u00e9riques<\/h3>\n<p>Nous ne transmettons des donn\u00e9es personnelles \u00e0 des tiers que si cela est n\u00e9cessaire dans le cadre de l'ex\u00e9cution du contrat, par exemple \u00e0 l'institut de cr\u00e9dit charg\u00e9 de l'ex\u00e9cution des paiements.<\/p>\n<p>Une transmission ult\u00e9rieure des donn\u00e9es n'a pas lieu ou seulement si vous avez express\u00e9ment consenti \u00e0 cette transmission. Vos donn\u00e9es ne seront pas transmises \u00e0 des tiers sans votre consentement expr\u00e8s, par exemple \u00e0 des fins publicitaires.<\/p>\n<p>Le traitement des donn\u00e9es se fonde sur l'article 6, paragraphe 1, point b), du RGPD, qui autorise le traitement des donn\u00e9es pour l'ex\u00e9cution d'un contrat ou de mesures pr\u00e9contractuelles.<\/p>\n<h3>Services de paiement<\/h3>\n<p>Nous int\u00e9grons des services de paiement de soci\u00e9t\u00e9s tierces sur notre site web. Lorsque vous effectuez un achat chez nous, vos donn\u00e9es de paiement (par ex. nom, montant du paiement, coordonn\u00e9es bancaires, num\u00e9ro de carte de cr\u00e9dit) sont trait\u00e9es par le prestataire de services de paiement aux fins du traitement du paiement. Les dispositions contractuelles et de protection des donn\u00e9es respectives des prestataires concern\u00e9s s'appliquent \u00e0 ces transactions. L'utilisation des prestataires de services de paiement se fait sur la base de l'article 6, paragraphe 1, point b), du RGPD (ex\u00e9cution du contrat) ainsi que dans l'int\u00e9r\u00eat d'un processus de paiement aussi fluide, confortable et s\u00fbr que possible (article 6, paragraphe 1, point f), du RGPD). Dans la mesure o\u00f9 votre consentement est demand\u00e9 pour certaines actions, l'article 6, paragraphe 1, point a) du RGPD constitue la base juridique du traitement des donn\u00e9es ; les consentements peuvent \u00eatre r\u00e9voqu\u00e9s \u00e0 tout moment pour l'avenir.<\/p>\n<p>Nous utilisons les services de paiement \/ prestataires de services de paiement suivants dans le cadre de ce site web :<\/p>\n<h4>PayPal<\/h4>\n<p>Le fournisseur de ce service de paiement est PayPal (Europe) S.\u00e0.r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxembourg (ci-apr\u00e8s \"PayPal\").<\/p>\n<p>Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez les d\u00e9tails ici : <a href=\"https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/pocpsa-full\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/pocpsa-full<\/a>.<\/p>\n<p>Pour plus de d\u00e9tails, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de PayPal : <a href=\"https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full<\/a>.<\/p>\n<h4>Klarna<\/h4>\n<p>Le fournisseur est Klarna AB, Sveav\u00e4gen 46, 111 34 Stockholm, Su\u00e8de (ci-apr\u00e8s \"Klarna\"). Klarna propose diff\u00e9rentes options de paiement (par exemple l'achat en plusieurs fois). Si vous choisissez de payer avec Klarna (solution Klarna Checkout), Klarna collectera diff\u00e9rentes donn\u00e9es personnelles vous concernant. Klarna utilise des cookies afin d'optimiser l'utilisation de la solution Klarna Checkout. Pour plus de d\u00e9tails sur l'utilisation des cookies Klarna, veuillez consulter le lien suivant : <a href=\"https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/cookie\/de_de\/checkout.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/cookie\/de_de\/checkout.pdf<\/a>.<\/p>\n<p>Vous pouvez lire les d\u00e9tails \u00e0 ce sujet dans la d\u00e9claration de protection des donn\u00e9es de Klarna en cliquant sur le lien suivant : <a href=\"https:\/\/www.klarna.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.klarna.com\/de\/datenschutz\/<\/a>.<\/p>\n<h4>Paydirekt<\/h4>\n<p>Le fournisseur de ce service de paiement est la soci\u00e9t\u00e9 Paydirekt GmbH, Hamburger Allee 26-28, 60486 Francfort-sur-le-Main, Allemagne (ci-apr\u00e8s \"Paydirekt\"). Lorsque vous effectuez le paiement au moyen de Paydirekt, Paydirekt collecte diff\u00e9rentes donn\u00e9es de transaction et les transmet \u00e0 la banque aupr\u00e8s de laquelle vous \u00eates enregistr\u00e9 avec Paydirekt. Outre les donn\u00e9es n\u00e9cessaires au paiement, Paydirekt collecte \u00e9ventuellement d'autres donn\u00e9es dans le cadre du traitement de la transaction, comme par exemple l'adresse de livraison ou les diff\u00e9rentes positions du panier d'achat. Paydirekt authentifie ensuite la transaction \u00e0 l'aide de la proc\u00e9dure d'authentification d\u00e9pos\u00e9e \u00e0 cet effet aupr\u00e8s de la banque. Le montant du paiement est ensuite transf\u00e9r\u00e9 de votre compte \u00e0 notre compte. Ni nous ni des tiers n'ont acc\u00e8s \u00e0 vos donn\u00e9es de compte. Pour plus de d\u00e9tails sur le paiement avec Paydirekt, veuillez consulter les CGV et les dispositions relatives \u00e0 la protection des donn\u00e9es de Paydirekt sous : <a href=\"https:\/\/www.paydirekt.de\/agb\/index.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.paydirekt.de\/agb\/index.html<\/a>.<\/p>\n<h4>Virement imm\u00e9diat<\/h4>\n<p>Le fournisseur de ce service de paiement est la soci\u00e9t\u00e9 Sofort GmbH, Theresienh\u00f6he 12, 80339 Munich (ci-apr\u00e8s \"Sofort GmbH\"). Gr\u00e2ce \u00e0 la proc\u00e9dure \"Sofort\u00fcberweisung\", nous recevons en temps r\u00e9el une confirmation de paiement de la part de Sofort GmbH et pouvons commencer imm\u00e9diatement \u00e0 honorer nos engagements. Si vous avez opt\u00e9 pour le mode de paiement \"Sofort\u00fcberweisung\", vous transmettez le code PIN et un TAN valable \u00e0 Sofort GmbH, avec lequel elle peut se connecter \u00e0 votre compte de banque en ligne. Apr\u00e8s s'\u00eatre connect\u00e9, Sofort GmbH v\u00e9rifie automatiquement le solde de votre compte et effectue le virement en notre faveur \u00e0 l'aide du TAN que vous lui avez transmis. Ensuite, elle nous transmet imm\u00e9diatement une confirmation de transaction. Apr\u00e8s la connexion, vos transactions, le plafond de cr\u00e9dit du d\u00e9couvert et l'existence d'autres comptes ainsi que leurs avoirs sont \u00e9galement contr\u00f4l\u00e9s automatiquement. Outre le code PIN et le TAN, les donn\u00e9es de paiement que vous avez saisies ainsi que des donn\u00e9es vous concernant sont \u00e9galement transmises \u00e0 Sofort GmbH. Les donn\u00e9es relatives \u00e0 votre personne sont votre pr\u00e9nom et votre nom, votre adresse, votre ou vos num\u00e9ros de t\u00e9l\u00e9phone, votre adresse e-mail, votre adresse IP et, le cas \u00e9ch\u00e9ant, d'autres donn\u00e9es n\u00e9cessaires au traitement du paiement. La transmission de ces donn\u00e9es est n\u00e9cessaire pour \u00e9tablir votre identit\u00e9 sans aucun doute et pour pr\u00e9venir les tentatives de fraude. Pour plus de d\u00e9tails sur le paiement avec Sofort\u00fcberweisung, veuillez consulter le lien suivant : <a href=\"https:\/\/www.klarna.com\/sofort\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.klarna.com\/sofort\/<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Datenschutz&shy;erkl&auml;rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen &Uuml;berblick dar&uuml;ber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers&ouml;nlich identifiziert werden k&ouml;nnen. Ausf&uuml;hrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef&uuml;hrten Datenschutzerkl&auml;rung. Datenerfassung auf dieser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-41","page","type-page","status-publish","hentry"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":null,"_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":"1","_edit_lock":"1740235828:1","_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"9391","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"andmekaitse","_trp_automatically_translated_slug_lv":"datu-aizsardziba","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"tietosuoja","_trp_automatically_translated_slug_ja":"%e3%83%87%e3%83%bc%e3%82%bf%e4%bf%9d%e8%ad%b7","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":[],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"1084","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":"8","rank_math_contentai_score":{"keywords":"74.51","wordCount":"0","linkCount":"0","headingCount":"0","mediaCount":"0"},"ilj_limitincominglinks":"","ilj_maxincominglinks":"1","ilj_limitoutgoinglinks":"","ilj_maxoutgoinglinks":"1","ilj_limitlinksperparagraph":"","ilj_linksperparagraph":"1","ilj_blacklistdefinition":[],"ilj_linkdefinition":[],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":null,"rank_math_og_content_image":null,"_yoast_wpseo_metadesc":null,"_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":null,"footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":1,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":8800,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/pages\/41\/revisions\/8800"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}