{"id":4368,"date":"2020-10-30T21:37:10","date_gmt":"2020-10-30T20:37:10","guid":{"rendered":"https:\/\/webhosting.de\/?p=4368"},"modified":"2020-10-30T21:37:10","modified_gmt":"2020-10-30T20:37:10","slug":"quelle-plate-forme-medias-sociaux-est-la-plate-forme-droite-pour-mon-entreprise","status":"publish","type":"post","link":"https:\/\/webhosting.de\/fr\/welche-social-media-plattform-ist-die-richtige-plattform-fuer-mein-geschaeft\/","title":{"rendered":"Quelle est la plate-forme de m\u00e9dias sociaux qui convient \u00e0 mon entreprise ?"},"content":{"rendered":"<p>Il existe aujourd'hui d'innombrables plateformes de m\u00e9dias sociaux. L'\u00e9poque o\u00f9 vous ne pouviez trouver que <a href=\"https:\/\/webhosting.de\/fr\/facebook-likes-kaufen-der-koenigsweg-zur-kundenvertreibung\/\">Facebook<\/a> sont enfin termin\u00e9s. Bien que la plupart des utilisateurs s'y trouvent encore, il existe \u00e9galement d'autres plateformes pour des groupes particuliers. Xing et LinkedIn, par exemple, sont davantage destin\u00e9s \u00e0 \u00e9tablir des contacts commerciaux. Sur Instagram, en revanche, de nombreuses jeunes filles affichent des photos des derni\u00e8res tendances en mati\u00e8re de mode et de maquillage.<\/p>\n<p>Mais d'une certaine mani\u00e8re, les utilisateurs auxquels vous vous adressez avec vos produits sont partout. Vous avez le sentiment de manquer quelque chose si vous n'\u00eates pas pr\u00e9sent sur toutes les plateformes et que vous ne publiez pas votre contenu. Apr\u00e8s tout, vous voulez gagner de nouveaux clients gr\u00e2ce au marketing des m\u00e9dias sociaux.<br \/>\nJe vous le promets : Si vous ne pouvez pas employer quelqu'un pour s'occuper de vos campagnes de m\u00e9dias sociaux huit heures par jour, vous ne pourrez pas servir tous les canaux de la m\u00eame mani\u00e8re. Cette id\u00e9e n'est pas seulement incroyablement \u00e9puisante. Cela signifie aussi que t\u00f4t ou tard, vous allez jeter l'\u00e9ponge. Apr\u00e8s tout, qui peut passer des heures par jour dans les m\u00e9dias sociaux en dehors de son activit\u00e9 principale ?<br \/>\nDe plus, la port\u00e9e est assez faible si vous ne postez sur une plateforme qu'une fois de temps en temps.<br \/>\nSi, en revanche, vous limitez toutes les activit\u00e9s \u00e0 une seule plateforme, vous pouvez toucher plus de personnes et \u00e9tablir une meilleure relation avec elles, notamment parce qu'elles s'int\u00e9ressent toujours \u00e0 vous et \u00e0 votre <a href=\"https:\/\/webhosting.de\/fr\/existenzgruendung-online-chancen-und-stolpersteine\/\">Boutique<\/a> et pas seulement \u00e0 l'occasion.<\/p>\n<p>Le marketing des m\u00e9dias sociaux - mais cibl\u00e9 !<\/p>\n<p>Comme vous ne pouvez pas \u00eatre repr\u00e9sent\u00e9 de mani\u00e8re \u00e9gale sur toutes les plateformes, vous devez faire une s\u00e9lection. Et la s\u00e9lection ne doit pas d\u00e9passer le nombre un ou deux. Car ici, clairement, moins c'est plus. La principale question que vous devez vous poser est la suivante : o\u00f9 mes clients sont-ils le plus souvent repr\u00e9sent\u00e9s ? Si votre public cible est \u00e2g\u00e9 de 50 ans et plus en moyenne, vous n'aurez pas n\u00e9cessairement acc\u00e8s \u00e0 Instagram, et si vous ciblez les jeunes jusqu'\u00e0 20 ans, Xing ou LinkedIn ne devraient pas non plus \u00eatre votre plateforme de choix.<br \/>\nLa premi\u00e8re chose qui importe vraiment est donc de savoir o\u00f9 vous pensez que votre groupe cible se trouve. Et lorsque vous aurez enfin fait votre choix, vous devriez voir ce que votre groupe cible y fait.<\/p>\n<p>Vous ne pouvez pas vous tromper avec Facebook. Parce que Facebook compte plusieurs milliards d'utilisateurs et que c'est presque impossible si votre groupe cible ne s'y trouve pas.<br \/>\nPar cons\u00e9quent : si vous ne savez pas par o\u00f9 commencer, Facebook est l'endroit id\u00e9al.<\/p>\n<p>Comment \u00e9tablir des contacts maintenant ?<\/p>\n<p>Sur les diff\u00e9rentes plateformes, c'est comme dans la vie normale. Si vous vous levez et criez que vous \u00eates la bonne personne \u00e0 qui parler de vos probl\u00e8mes, vous n'aurez pas beaucoup d'\u00e9loges.<br \/>\nIl s'agit plut\u00f4t d'\u00e9tablir des contacts.<br \/>\nVous publiez des contenus utiles ou r\u00e9pondez aux questions des utilisateurs et devenez indispensable au fil du temps. En un rien de temps, les gens commencent \u00e0 vous chercher si vous avez une question ou une \u00e9tiquette dans leurs messages afin que vous receviez un e-mail.<br \/>\nSur Facebook, vous pouvez rejoindre des groupes et y participer activement. Encore une fois, ne passez pas \u00e0 travers les mailles du filet et ne publiez des annonces qu'en votre nom propre. Les personnes qui s'int\u00e9ressent \u00e0 vous examineront votre profil et essaieront d'en savoir plus sur vous et, bien s\u00fbr, sur votre entreprise. Sur presque toutes les plateformes de m\u00e9dias sociaux, vous pouvez partager votre profil avec votre <a href=\"https:\/\/webhosting.de\/fr\/eine-eigene-webseite-fuer-ihr-unternehmen-ja-oder-nein\/\">site web<\/a> lien. Le client n'est donc qu'\u00e0 un clic de votre boutique et de nombreuses personnes l'utilisent.<\/p>\n<p>Etre l\u00e0, c'est tout !<\/p>\n<p>Ainsi, l'id\u00e9e olympique de \"\u00eatre l\u00e0, c'est tout\" ne s'applique pas aux m\u00e9dias sociaux. Il s'applique plut\u00f4t ici que vous \u00eates un participant r\u00e9gulier. Pour s'en tenir \u00e0 une comparaison sportive pour une fois : La transpiration et l'exercice des muscles n'aident pas du tout. Ici aussi, tout est question de r\u00e9gularit\u00e9 et c'est ainsi que cela se passe dans les m\u00e9dias sociaux. Vous devez apporter une contribution une ou deux fois par jour pour \u00eatre vu. Et aussi \"participer\", en d'autres termes, aider.<br \/>\nSi vous avez d\u00e9cid\u00e9 d'utiliser Facebook, recherchez un ou deux groupes qui conviennent \u00e0 votre entreprise. Dites que vous \u00eates fleuriste. Alors peut-\u00eatre qu'un groupe qui s'occupe de d\u00e9coration int\u00e9rieure ou de jardinage conviendra \u00e0 votre entreprise. Votre expertise est certainement recherch\u00e9e ici. Quand plantez-vous quelle fleur ? De quelle quantit\u00e9 d'eau a-t-elle besoin ? Il y a une infinit\u00e9 de questions auxquelles vous pouvez r\u00e9pondre. Alors, faites-le. Soyez simplement utile sans vous r\u00e9f\u00e9rer \u00e0 votre magasin ou \u00e0 votre site web.<br \/>\nLes autres membres du groupe vous inscriront, et beaucoup plus de personnes que vous ne le pensez se perdront sur votre profil.<br \/>\nBien s\u00fbr, vous avez li\u00e9 votre profil \u00e0 votre site web ou au moins \u00e0 votre page de fans sur Facebook.<br \/>\nEt c'est ainsi que les personnes que vous avez aid\u00e9es finissent par se retrouver sur votre site web et par conna\u00eetre votre entreprise.<\/p>\n<p>Si vous essayez maintenant de promouvoir votre entreprise sur Facebook, YouTube, Xing et Google+, pour n'en citer que quelques-uns, vous ne pourrez tr\u00e8s probablement publier du contenu pertinent qu'une fois par semaine, voire pas du tout. Votre profil semble r\u00e9f\u00e9renc\u00e9 et il l'est - car cela fait probablement plusieurs semaines depuis le dernier post.<br \/>\nLorsque vous posterez enfin quelque chose, personne ne se souviendra de vous.<br \/>\nPar cons\u00e9quent, la r\u00e8gle suivante s'applique dans tous les cas : moins, c'est plus. Car vous n'avez rien \u00e0 gagner si vous \u00eates repr\u00e9sent\u00e9 sur de nombreuses plateformes mais que vous ne nouez aucun contact.<\/p>\n<p>Quel est le r\u00e9seau social le mieux adapt\u00e9 \u00e0 votre entreprise ?<\/p>\n<p>Comme le montrent les exemples ici, il s'agit bien s\u00fbr d'un cas particulier. Il est souvent judicieux de commencer par Facebook, de s'y implanter et de trouver des personnes qui s'int\u00e9ressent \u00e0 vous et \u00e0 votre entreprise.<br \/>\nN\u00e9anmoins, on est autoris\u00e9 \u00e0 regarder au-del\u00e0 de son propre nez. Apr\u00e8s tout, les autres r\u00e9seaux sociaux ont bien s\u00fbr aussi le droit d'exister et peuvent vous permettre de gagner de nouveaux clients.<br \/>\nEn retour, vous devriez vous renseigner sur ce que votre entreprise a \u00e0 offrir. Si vous \u00eates boulanger et que vous faites des g\u00e2teaux et des p\u00e2tisseries, Pinterest est l'endroit qu'il vous faut. Parce que c'est l\u00e0 que tout le monde cherche l'inspiration et les id\u00e9es.<br \/>\nEn revanche, en tant qu'avocat, vous ne pouvez pas poster trop de photos de vos cr\u00e9ations et vous \u00eates donc probablement mieux sur Twitter ou Xing. Les d\u00e9cisions de justice actuelles pourraient \u00eatre bien mieux sur Twitter. Apr\u00e8s tout, comment voulez-vous les pr\u00e9senter visuellement ?<\/p>\n<p>Conclusion<\/p>\n<p>Votre entreprise d\u00e9termine donc largement la place de vos activit\u00e9s dans les r\u00e9seaux sociaux. Examinez d'abord ce que vous avez \u00e0 offrir et choisissez ensuite un canal en cons\u00e9quence.<br \/>\nSi vous ne savez pas comment et par o\u00f9 commencer, Facebook devrait \u00eatre l'endroit de votre choix, car c'est l\u00e0 que votre public cible est garanti.<br \/>\nProc\u00e9dez de mani\u00e8re tr\u00e8s cibl\u00e9e et veillez \u00e0 limiter vos activit\u00e9s \u00e0 une ou deux plateformes au maximum. C'est la seule fa\u00e7on de voir rapidement les premi\u00e8res r\u00e9actions et de s'adresser aux nouveaux clients de mani\u00e8re cibl\u00e9e. Mais ne soyez pas des attrapeurs de clients \u00e9vidents dans les m\u00e9dias sociaux. Nous sommes tous bombard\u00e9s de publicit\u00e9 tous les jours et nous pouvons la sentir \u00e0 des kilom\u00e8tres de distance. D'autre part, si quelqu'un est juste l\u00e0 pour aider et comprendre son utilisateur, vous avez beaucoup plus de chances de lui commander et, surtout, de lui faire confiance.<br \/>\nUn bon conseil est donc : amusez-vous dans les r\u00e9seaux sociaux. Car les utilisateurs remarqueront aussi si vous \u00eates l\u00e0, pr\u00e9cis\u00e9ment parce que vous \u00eates \u00e0 l'aff\u00fbt des clients. Aidez et brillez par votre savoir.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mittlerweile gibt es unz\u00e4hlige Social Media Plattformen. Die Zeiten, in denen man sich nur auf Facebook getummelt hat, sind endg\u00fcltig vorbei. Obwohl dort nach wie vor die meisten User zu finden sind, gibt es f\u00fcr spezielle Gruppen auch andere Plattformen. So sind Xing und LinkedIn eher f\u00fcr den Aufbau von Gesch\u00e4ftskontakten gedacht. Auf Instagram dagegen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4368","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":"","_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":null,"_edit_lock":null,"_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"4321","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"milline-sotsiaalmeedia-platvorm-on-minu-ettevotte-jaoks-oige-platvorm","_trp_automatically_translated_slug_lv":"kura-socialo-mediju-platforma-ir-pareiza-platforma-manam-uznemumam","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"mikae-sosiaalisen-median-foorumi-on-oikea-foorumi-yritykselleni","_trp_automatically_translated_slug_ja":"%e3%81%a9%e3%81%ae%e3%82%bd%e3%83%bc%e3%82%b7%e3%83%a3%e3%83%ab%e3%83%a1%e3%83%87%e3%82%a3%e3%82%a2%e3%83%97%e3%83%a9%e3%83%83%e3%83%88%e3%83%95%e3%82%a9%e3%83%bc%e3%83%a0%e3%81%8c%e7%a7%81%e3%81%ae","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":["tp-video-player"],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"889","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":null,"rank_math_contentai_score":null,"ilj_limitincominglinks":null,"ilj_maxincominglinks":null,"ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":null,"ilj_linkdefinition":["welche social media plattform ist die richtige plattform f\u00fcr mein gesch\u00e4ft?"],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":null,"rank_math_og_content_image":null,"_yoast_wpseo_metadesc":"","_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":null,"footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts\/4368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/comments?post=4368"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts\/4368\/revisions"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/media?parent=4368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/categories?post=4368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/tags?post=4368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}