{"id":7973,"date":"2021-09-03T12:07:11","date_gmt":"2021-09-03T11:07:11","guid":{"rendered":"https:\/\/webhosting.de\/?p=7973"},"modified":"2021-08-19T09:33:02","modified_gmt":"2021-08-19T08:33:02","slug":"managed-hosting-company-navisite-buy-velocity-technology-solutions","status":"publish","type":"post","link":"https:\/\/webhosting.de\/fr\/managed-hosting-company-navisite-kauft-velocity-technology-solutions\/","title":{"rendered":"La soci\u00e9t\u00e9 d'h\u00e9bergement g\u00e9r\u00e9 Navisite rach\u00e8te Velocity Technology Solutions"},"content":{"rendered":"<h2><b>La soci\u00e9t\u00e9 d'h\u00e9bergement g\u00e9r\u00e9 Navisite rach\u00e8te Velocity Technology Solutions<\/b><\/h2>\n<p>&nbsp;<\/p>\n<div>\n<div class=\"preview\">Navisite a annonc\u00e9 d\u00e9but janvier l'acquisition de Velocity Technology Solutions, Inc (\"Velocity\"), un fournisseur mondial de services g\u00e9r\u00e9s en nuage (MSP). Avec cette acquisition, Navisite renforce sa position de leader dans le domaine des services g\u00e9r\u00e9s de cloud et de <a href=\"https:\/\/webhosting.de\/fr\/was-ist-enterprise-cloud-computing\/\">Entreprise<\/a> Resource Planning (ERP) pour les moyennes entreprises et les entreprises clientes, y compris une base \u00e0 la fois de marques mondiales \u00e0 croissance rapide et \u00e9tablies. Velocity am\u00e9liorera le portefeuille de services de Navisite en ajoutant une expertise approfondie dans les applications d'entreprise et une plateforme cloud robuste qui simplifie la migration et la gestion des environnements des clients dans les clouds publics, priv\u00e9s et hybrides. Navisite met en \u0153uvre sa strat\u00e9gie de croissance ax\u00e9e sur le client avec le soutien d'investissement continu de Madison Dearborn Partners, une soci\u00e9t\u00e9 d'investissement priv\u00e9e de premier plan bas\u00e9e \u00e0 Chicago.<\/div>\n<h3 class=\"preview\">Quels sont les besoins r\u00e9els des entreprises modernes ?<\/h3>\n<div class=\"preview\">\n<p>\"Les entreprises ont besoin d'un partenaire technologique qui non seulement fournit des services et une expertise cloud modernes pour soutenir leurs objectifs de transformation num\u00e9rique, mais qui est \u00e9galement capable de fournir des solutions avec des droits\", a d\u00e9clar\u00e9 Mark Clayman, PDG de Navisite. \"Chaque \u00e9tape que nous avons franchie en tant que soci\u00e9t\u00e9, y compris cette acquisition, a consist\u00e9 \u00e0 \u00eatre ce partenaire de confiance et \u00e0 construire un portefeuille de solutions ax\u00e9es sur le client.\"<\/p>\n<p>Fond\u00e9e en 2003, Velocity a son si\u00e8ge social \u00e0 Charlotte, en Caroline du Nord, et des bureaux en Am\u00e9rique du Nord, en Am\u00e9rique du Sud, en Europe et en Asie. L'entreprise offre des environnements infonuagiques s\u00e9curis\u00e9s et enti\u00e8rement g\u00e9r\u00e9s gr\u00e2ce \u00e0 un portefeuille de services infonuagiques g\u00e9r\u00e9s ax\u00e9s sur les applications et de services professionnels avec analyse des donn\u00e9es. L'expertise de Velocity dans la gestion des principales applications ERP et l'utilisation de la plateforme Velocity Cloud Application Management Platform (VCAMP) permet \u00e0 ses clients d'optimiser la performance des applications sur site et dans le nuage avec la disponibilit\u00e9, la s\u00e9curit\u00e9, la visibilit\u00e9 et le contr\u00f4le n\u00e9cessaires \u00e0 un co\u00fbt total de possession r\u00e9duit. Les produits de services g\u00e9r\u00e9s en nuage de Velocity comprennent l'infrastructure de gestion en nuage, les bases de donn\u00e9es, la r\u00e9cup\u00e9ration apr\u00e8s sinistre, les lacs de donn\u00e9es et le soutien pour les conteneurs g\u00e9r\u00e9s. Velocity est un partenaire AWS Premier, certifi\u00e9 \u00e0 la fois comme migrateur et comme MSP, qui prend en charge les applications Microsoft, SAP et Oracle, ainsi qu'un partenaire Oracle Platinum et un MSP certifi\u00e9.<\/p>\n<\/div>\n<h3 class=\"preview\">Les avantages pour Navisite<\/h3>\n<div class=\"preview\">\n<p>\"Avec Velocity, nous avons consid\u00e9rablement \u00e9largi nos capacit\u00e9s, notre empreinte mondiale, notre expertise en mati\u00e8re de centres de donn\u00e9es et de cloud public pour aider les clients \u00e0 relever les d\u00e9fis d'aujourd'hui et de demain sur l'ensemble de la pile technologique - de la migration vers le cloud \u00e0 la gestion du cloud en passant par les services d'infrastructure, d'applications d'entreprise et de gestion des donn\u00e9es \", a ajout\u00e9 M. Clayman.<\/p>\n<p>L'acquisition de Velocity permettra \u00e9galement d'\u00e9tendre les services g\u00e9r\u00e9s de Navisite pour les applications Oracle et SAP et de prendre en charge les ERP sp\u00e9cifiques \u00e0 l'industrie, notamment Oracle E-Business Suite (EBS), JD Edwards, PeopleSoft, Infor et Epic ainsi que <a href=\"https:\/\/webhosting.de\/fr\/business\/\">Entreprises<\/a> solutions d'intelligence comme Hyperion , OneStream et Qlik.<\/p>\n<p>Navisite a r\u00e9cemment annonc\u00e9 l'acquisition de Dickinson + Associates, un partenaire Gold SAP de premier plan. Les forces de Velocity dans le domaine de SAP vont encore am\u00e9liorer les solutions SAP de Navisite et permettre \u00e0 Navisite de fournir des services de conseil technique et fonctionnel, de mise en \u0153uvre et de support pour aider les clients \u00e0 adopter les technologies SAP en nuage et \u00e0 migrer vers SAP S \/ 4HANA, l'ERP de SAP pour les grandes entreprises. En s'associant \u00e0 Velocity, Navisite renforcera ses capacit\u00e9s dans les secteurs de la fabrication, des soins de sant\u00e9 et d'autres industries pour aider les clients \u00e0 migrer, moderniser et g\u00e9rer les d\u00e9ploiements existants dans des environnements de cloud priv\u00e9, hybride et public tels que AWS, Google Cloud et Azure.<\/p>\n<p>\" Nous sommes impatients de voir ce que nous pouvons accomplir ensemble avec Navisite \", a d\u00e9clar\u00e9 Steve Kloeblen, PDG de Velocity Technology Solutions. \"Avec les ressources, les capacit\u00e9s mondiales et l'expertise compl\u00e9mentaire de Navisite, Velocity est en mesure de devenir un partenaire encore plus fort pour nos clients qui se d\u00e9veloppent et sont en concurrence dans l'\u00e9conomie num\u00e9rique. Plus important encore, nos clients peuvent s'attendre \u00e0 une plus grande vari\u00e9t\u00e9 et profondeur de services pour \u00e9liminer la complexit\u00e9 informatique, r\u00e9duire les co\u00fbts et am\u00e9liorer l'efficacit\u00e9. <a href=\"https:\/\/webhosting.de\/fr\/webhosting-wie-viel-darf-es-kosten\/\">Co\u00fbts<\/a> dans le contexte des d\u00e9ploiements de logiciels monolithiques et de la migration et de la transformation de leurs entreprises dans le cloud. \"<\/p>\n<p>Stifel, Nicolaus &amp; Company ont agi en tant que conseillers financiers de Velocity, et Weil, Gotshal &amp; Manges LLP ont fourni des conseils juridiques \u00e0 Velocity. Jefferies LLC et TD Securities LLC ont agi en tant que conseillers financiers de Navisite, et Kirkland &amp; Ellis LLP a fourni des conseils juridiques \u00e0 Navisite.<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Managed Hosting Company Navisite kauft Velocity Technology Solutions &nbsp; Navisite gab Anfang Januar bekannt, dass es Velocity Technology Solutions, Inc. (&#8222;Velocity&#8220;), einen globalen Cloud Managed Service Provider (MSP), \u00fcbernommen hat. Mit diesem Ankauf st\u00e4rkt Navisite seine Position als f\u00fchrender Anbieter von Managed Cloud- und Enterprise Resource Planning (ERP) -Diensten f\u00fcr mittelst\u00e4ndische und Unternehmenskunden, einschlie\u00dflich einer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[996],"tags":[1059,1057,1058],"class_list":["post-7973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hosting-news","tag-hosting-company","tag-navisite","tag-velocity-technology-solutions"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":"996","rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":null,"_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":"1","_edit_lock":"1629361844:1","_oembed_e7b913c6c84084ed9702cb4feb012ddd":"{{unknown}}","_oembed_bfde9e10f59a17b85fc8917fa7edf782":"<iframe title=\"Theming Nextcloud in 37 seconds\" width=\"368\" height=\"207\" src=\"https:\/\/www.youtube.com\/embed\/wqRgeFXYUys?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":"1628680312","_oembed_03514b67990db061d7c4672de26dc514":"<iframe title=\"Gaia X\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/NhqLt_NJ6FA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_03514b67990db061d7c4672de26dc514":"1628680305","rank_math_news_sitemap_robots":null,"rank_math_robots":null,"_eael_post_view_count":"4350","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"managed-hosting-company-navisite-buy-velocity-technology-solutions","_trp_automatically_translated_slug_lv":"parvalditas-hostinga-kompanijas-navisite-pirkt-velocity-tehnologiju-risinajumus","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"managed-hosting-company-navisite-buy-velocity-technology-solutions","_trp_automatically_translated_slug_ja":"%e3%83%9e%e3%83%8d%e3%83%bc%e3%82%b8%e3%83%89%e3%83%bb%e3%83%9b%e3%82%b9%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0%e3%83%bb%e3%82%ab%e3%83%b3%e3%83%91%e3%83%8b%e3%83%bc%e3%83%bb%e3%83%8a%e3%83%b4%e3%82%a3","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":"{{unknown}}","_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":"<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/BREAKING?src=hash&amp;ref_src=twsrc%5Etfw\">#BREAKING<\/a>: Texas takes the lead once more! Today, we\u2019re filing a lawsuit against <a href=\"https:\/\/twitter.com\/hashtag\/Google?src=hash&amp;ref_src=twsrc%5Etfw\">#Google<\/a> for anticompetitive conduct.<br><br>This internet Goliath used its power to manipulate the market, destroy competition, and harm YOU, the consumer. Stay tuned\u2026 <a href=\"https:\/\/t.co\/fdEVEWQb0e\">pic.twitter.com\/fdEVEWQb0e<\/a><\/p>&mdash; Texas Attorney General (@TXAG) <a href=\"https:\/\/twitter.com\/TXAG\/status\/1339283520099856384?ref_src=twsrc%5Etfw\">December 16, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>","_oembed_time_3efb2c3e76a18143e7207993a2a6939a":"1628680298","_oembed_59808117857ddf57e478a31d79f76e4d":"<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Happy to follow-on report that a huge chunk of <a href=\"https:\/\/twitter.com\/Flickr?ref_src=twsrc%5Etfw\">@Flickr<\/a> compute just successfully made the transition to Graviton2 <a href=\"https:\/\/twitter.com\/Arm?ref_src=twsrc%5Etfw\">@ARM<\/a> in <a href=\"https:\/\/twitter.com\/awscloud?ref_src=twsrc%5Etfw\">@awscloud<\/a> this afternoon. More services coming shortly. My aim is to get to 100% of non-GPU <a href=\"https:\/\/twitter.com\/SmugMug?ref_src=twsrc%5Etfw\">@SmugMug<\/a> and <a href=\"https:\/\/twitter.com\/Flickr?ref_src=twsrc%5Etfw\">@Flickr<\/a> compute on ARM within the year. <a href=\"https:\/\/t.co\/fwXWdg06xx\">https:\/\/t.co\/fwXWdg06xx<\/a><\/p>&mdash; Don MacAskill (@DonMacAskill) <a href=\"https:\/\/twitter.com\/DonMacAskill\/status\/1314050996486561792?ref_src=twsrc%5Etfw\">October 8, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>","_oembed_time_59808117857ddf57e478a31d79f76e4d":"1628680300","_oembed_965c5b49aa8d22ce37dfb3bde0268600":"<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"de\" dir=\"ltr\">Der <a href=\"https:\/\/twitter.com\/hashtag\/Finanzausschuss?src=hash&amp;ref_src=twsrc%5Etfw\">#Finanzausschuss<\/a> im <a href=\"https:\/\/twitter.com\/hashtag\/Bundestag?src=hash&amp;ref_src=twsrc%5Etfw\">#Bundestag<\/a> hat das <a href=\"https:\/\/twitter.com\/hashtag\/Jahressteuergesetz?src=hash&amp;ref_src=twsrc%5Etfw\">#Jahressteuergesetz<\/a> beschlossen. Damit wurde auch die <a href=\"https:\/\/twitter.com\/hashtag\/Gemeinn%C3%BCtzigkeit?src=hash&amp;ref_src=twsrc%5Etfw\">#Gemeinn\u00fctzigkeit<\/a> f\u00fcr <a href=\"https:\/\/twitter.com\/hashtag\/Freifunk?src=hash&amp;ref_src=twsrc%5Etfw\">#Freifunk<\/a> Initiativen beschlossen. Das ganze geht jetzt in der kommenden Woche ins Plenum zur Abstimmung und direkt in den <a href=\"https:\/\/twitter.com\/hashtag\/Bundesrat?src=hash&amp;ref_src=twsrc%5Etfw\">#Bundesrat<\/a><\/p>&mdash; Jens Zimmermann (@JensZSPD) <a href=\"https:\/\/twitter.com\/JensZSPD\/status\/1336581821706989568?ref_src=twsrc%5Etfw\">December 9, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>","_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":"1628680301","_oembed_81002f7ee3604f645db4ebcfd1912acf":"<iframe title=\"Netzetag bei der Telekom: Antennen, Breitband, Glasfaser\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/6_NTa3VCRFo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_81002f7ee3604f645db4ebcfd1912acf":"1628680301","_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":"<iframe title=\"Firewall: Wie du die Web Application Firewall im Plesk Men\u00fc verwendest und deine Website sch\u00fctzt.\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/CzAjqyJtEaw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_7ea3429961cf98fa85da9747683af827":"1628680285","_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":null,"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":null,"rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":"62","rank_math_contentai_score":null,"ilj_limitincominglinks":"","ilj_maxincominglinks":"1","ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":[],"ilj_linkdefinition":["navisite","Velocity Technology Solutions","hosting company"],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":"Navisite","rank_math_og_content_image":null,"_yoast_wpseo_metadesc":null,"_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":"7974","footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts\/7973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/comments?post=7973"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts\/7973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/media\/7974"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/media?parent=7973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/categories?post=7973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/tags?post=7973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}