{"id":8017,"date":"2021-09-14T14:01:12","date_gmt":"2021-09-14T13:01:12","guid":{"rendered":"https:\/\/webhosting.de\/?p=8017"},"modified":"2021-08-19T09:31:31","modified_gmt":"2021-08-19T08:31:31","slug":"cybersecurite-services-compagnie-intraprise-sante-erwirbt-hipaa-one","status":"publish","type":"post","link":"https:\/\/webhosting.de\/fr\/cybersecurity-services-company-intraprise-health-erwirbt-hipaa-one\/","title":{"rendered":"La soci\u00e9t\u00e9 de services de cybers\u00e9curit\u00e9 Intraprise Health acquiert HIPAA One"},"content":{"rendered":"<h2><b>La soci\u00e9t\u00e9 de services de cybers\u00e9curit\u00e9 Intraprise Health acquiert HIPAA One<\/b><\/h2>\n<p>&nbsp;<\/p>\n<div>\n<div class=\"preview\">\n<p>La soci\u00e9t\u00e9 de services de cybers\u00e9curit\u00e9 Intraprise Health, l'un des principaux fournisseurs de services et de solutions de cybers\u00e9curit\u00e9 et de la plateforme logicielle de gestion des risques Protect (TM), a annonc\u00e9 aujourd'hui l'acquisition de HIPAA One, fournisseur d'un logiciel d'automatisation de la conformit\u00e9 HIPAA de pointe. Cette fusion permet \u00e0 Intraprise Health d'offrir au march\u00e9 des soins de sant\u00e9 une suite int\u00e9gr\u00e9e de solutions logicielles de cybers\u00e9curit\u00e9 et de conformit\u00e9. Avec l'aide de cette nouvelle <a href=\"https:\/\/webhosting.de\/fr\/nextcloud-launcht-open-source-projekt-fuer-deutsche-behoerden\/\">Suite<\/a> Gr\u00e2ce \u00e0 ces produits int\u00e9gr\u00e9s, les RSSI et les \u00e9quipes de s\u00e9curit\u00e9 peuvent d\u00e9sormais aborder de mani\u00e8re holistique la gestion des risques de s\u00e9curit\u00e9 et la conformit\u00e9 HIPAA dans l'ensemble de leur syst\u00e8me ou r\u00e9seau de sant\u00e9. Bluff Point Associates a dirig\u00e9 le financement avec l'investisseur existant Health <a href=\"https:\/\/webhosting.de\/fr\/was-ist-enterprise-cloud-computing\/\">Entreprise<\/a> Partners, L.P. y participent \u00e9galement.<\/p>\n<p>Les produits de s\u00e9curit\u00e9, de confidentialit\u00e9 et de conformit\u00e9 \u00e9prouv\u00e9s de HIPAA One, combin\u00e9s \u00e0 la plateforme de gestion des risques Protect (TM) d'Intraprise Health, constituent une solution de pointe qui r\u00e9pond \u00e0 certains des probl\u00e8mes les plus importants du secteur. \" En combinant la plateforme logicielle d'\u00e9valuation automatis\u00e9e des risques de s\u00e9curit\u00e9 de HIPAA One avec les capacit\u00e9s existantes d'Intraprise Health en mati\u00e8re de cybers\u00e9curit\u00e9, nous offrons \u00e0 nos clients une solution compl\u00e8te de s\u00e9curit\u00e9 et de conformit\u00e9 qui renforce notre engagement \u00e0 s\u00e9curiser les donn\u00e9es de nos clients \", a d\u00e9clar\u00e9 Sean Friel, PDG d'Intraprise Health.<\/p>\n<p>La suite de produits combin\u00e9e Protect (TM) et HIPAA One offre une gamme compl\u00e8te de fonctionnalit\u00e9s de s\u00e9curit\u00e9 et de conformit\u00e9 pour les syst\u00e8mes, applications, r\u00e9seaux et dispositifs des organismes de sant\u00e9 et des tiers. Ces fonctionnalit\u00e9s logicielles, notamment l'automatisation des flux de travail, la gestion des politiques et des proc\u00e9dures, la collaboration, la gestion des t\u00e2ches et l'\u00e9tablissement de rapports automatis\u00e9s, sont mises en \u0153uvre et soutenues par une \u00e9quipe de services professionnels exp\u00e9riment\u00e9e, compos\u00e9e d'experts en s\u00e9curit\u00e9, confidentialit\u00e9 et conformit\u00e9 des soins de sant\u00e9.<\/p>\n<p>Selon Steve Marco, pr\u00e9sident de HIPAA One, \"notre formule centr\u00e9e sur le client, qui tire parti de l'automatisation pour simplifier et r\u00e9duire la charge administrative de l'\u00e9valuation des risques HIPAA, compl\u00e8te parfaitement les services de s\u00e9curit\u00e9 d'Intraprise Health, notamment les services d'\u00e9valuateur certifi\u00e9 HITRUST. La plateforme logicielle Protect (TM) d'Intraprise Health r\u00e9pond \u00e9galement aux besoins croissants de notre \u00e9cosyst\u00e8me de clients et de partenaires. Ensemble, nous sommes impatients de continuer \u00e0 stimuler l'innovation en mati\u00e8re de s\u00e9curit\u00e9 et de conformit\u00e9. \"<\/p>\n<p>\"La cybers\u00e9curit\u00e9 est une composante essentielle des soins de sant\u00e9 aujourd'hui\", a d\u00e9clar\u00e9 Kevin Fahey, directeur g\u00e9n\u00e9ral de Bluff Point Associates. \"Nous sommes impatients d'aider Intraprise Health \u00e0 d\u00e9velopper ses produits et services pour se d\u00e9fendre contre les cybermenaces en croissance exponentielle.\" Fahey est \u00e9galement membre du conseil d'administration d'Intraprise Health.<\/p>\n<\/div>\n<h3 class=\"preview\">\u00c0 propos d'Intraprise Health<\/h3>\n<div class=\"preview\">Intraprise Health est une soci\u00e9t\u00e9 de services et de solutions de s\u00e9curit\u00e9 ax\u00e9e sur les soins de sant\u00e9 qui fournit des logiciels et des services pour la mise en \u0153uvre des cadres NIST et HITRUST, l'optimisation de la gestion des risques, l'\u00e9valuation des risques de s\u00e9curit\u00e9, la gestion des mesures correctives, la gestion des risques li\u00e9s aux tiers, la planification de la continuit\u00e9 des activit\u00e9s et la gouvernance des programmes de s\u00e9curit\u00e9 (vCISO). La plateforme de gestion des risques Protect (TM) d'Intraprise Health aide les organisations \u00e0 automatiser, g\u00e9rer et surveiller les fonctions cl\u00e9s du bureau de la s\u00e9curit\u00e9 de l'information. Il en r\u00e9sulte une vision globale des risques li\u00e9s \u00e0 l'entreprise et aux tiers. Intraprise Health est l'un des \u00e9valuateurs certifi\u00e9s HITRUST les plus anciens et de la plus haute qualit\u00e9. Hautement cot\u00e9e par KLAS, l'\u00e9quipe d'Intraprise Health se compose de professionnels de la s\u00e9curit\u00e9 exp\u00e9riment\u00e9s et de technologues de l'information sanitaire \u00e9prouv\u00e9s.<\/div>\n<h3 class=\"preview\">\u00c0 propos de HIPAA One<\/h3>\n<div class=\"preview\">HIPAA One est une suite logicielle de conformit\u00e9 HIPAA bas\u00e9e sur le cloud qui simplifie et automatise la conformit\u00e9 HIPAA pour les prestataires de soins de sant\u00e9, les plans de sant\u00e9 et les partenaires commerciaux de toutes tailles. Les solutions HIPAA One comprennent l'analyse des risques de s\u00e9curit\u00e9, l'analyse de la protection des donn\u00e9es et des infractions, les solutions de cybers\u00e9curit\u00e9, les tests d'intrusion, la formation du personnel HIPAA, la gestion des fournisseurs et la validation par des tiers. Le logiciel a \u00e9t\u00e9 con\u00e7u pour les auditeurs \u00e0 la recherche de fonctionnalit\u00e9s avanc\u00e9es, les partenaires et les chefs de bureau. Il va des documents individuels aux organisations d'entreprise qui doivent simplifier les probl\u00e8mes complexes, fournir des analyses macro et des contr\u00f4les HIPAA \"toujours \u00e0 jour\". Pour plus d'informations sur HIPAA One(R), veuillez consulter le site https:\/\/www.hipaaone.com.<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cybersecurity Services Company Intraprise Health erwirbt HIPAA One &nbsp; Cybersecurity Services Company Intraprise Health, ein f\u00fchrender Anbieter von Cybersicherheitsdiensten und -l\u00f6sungen und der Protect (TM) -Risikomanagement-Softwareplattform, gab heute bekannt, dass HIPAA One, Anbieter branchenf\u00fchrender HIPAA-Konformit\u00e4t, \u00fcbernommen wurde Automatisierungssoftware. Durch den Zusammenschluss kann Intraprise Health dem Gesundheitsmarkt eine integrierte Reihe von Cybersicherheits- und Compliance-Softwarel\u00f6sungen anbieten. Mithilfe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[996],"tags":[1030,1086,1087],"class_list":["post-8017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hosting-news","tag-cybersecurity","tag-hipaa-one","tag-intraprise-health"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":"996","rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":null,"_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":"1","_edit_lock":"1629361753:1","_oembed_e7b913c6c84084ed9702cb4feb012ddd":"{{unknown}}","_oembed_bfde9e10f59a17b85fc8917fa7edf782":"<iframe title=\"Theming Nextcloud in 37 seconds\" width=\"368\" height=\"207\" src=\"https:\/\/www.youtube.com\/embed\/wqRgeFXYUys?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":"1628687167","_oembed_03514b67990db061d7c4672de26dc514":"<iframe title=\"Gaia X\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/NhqLt_NJ6FA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_03514b67990db061d7c4672de26dc514":"1628687160","rank_math_news_sitemap_robots":null,"rank_math_robots":null,"_eael_post_view_count":"3992","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"cybersecurity-services-company-intraprise-health-erwirbt-hipaa-one","_trp_automatically_translated_slug_lv":"cybersecurity-services-company-intraprise-health-erwirbt-hipaa-one","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"kyberturvallisuus-palvelut-yritys-intraprise-terveys-erwirbt-hipaa-one","_trp_automatically_translated_slug_ja":"%e3%82%b5%e3%82%a4%e3%83%90%e3%83%bc%e3%82%bb%e3%82%ad%e3%83%a5%e3%83%aa%e3%83%86%e3%82%a3%e3%83%bb%e3%82%b5%e3%83%bc%e3%83%93%e3%82%b9%e3%83%bb%e3%82%b3%e3%83%b3%e3%83%91%e3%83%8b%e3%82%aa%e3%83%b3","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":"{{unknown}}","_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":"<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/BREAKING?src=hash&amp;ref_src=twsrc%5Etfw\">#BREAKING<\/a>: Texas takes the lead once more! Today, we\u2019re filing a lawsuit against <a href=\"https:\/\/twitter.com\/hashtag\/Google?src=hash&amp;ref_src=twsrc%5Etfw\">#Google<\/a> for anticompetitive conduct.<br><br>This internet Goliath used its power to manipulate the market, destroy competition, and harm YOU, the consumer. Stay tuned\u2026 <a href=\"https:\/\/t.co\/fdEVEWQb0e\">pic.twitter.com\/fdEVEWQb0e<\/a><\/p>&mdash; Texas Attorney General (@TXAG) <a href=\"https:\/\/twitter.com\/TXAG\/status\/1339283520099856384?ref_src=twsrc%5Etfw\">December 16, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>","_oembed_time_3efb2c3e76a18143e7207993a2a6939a":"1628687153","_oembed_59808117857ddf57e478a31d79f76e4d":"<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Happy to follow-on report that a huge chunk of <a href=\"https:\/\/twitter.com\/Flickr?ref_src=twsrc%5Etfw\">@Flickr<\/a> compute just successfully made the transition to Graviton2 <a href=\"https:\/\/twitter.com\/Arm?ref_src=twsrc%5Etfw\">@ARM<\/a> in <a href=\"https:\/\/twitter.com\/awscloud?ref_src=twsrc%5Etfw\">@awscloud<\/a> this afternoon. More services coming shortly. My aim is to get to 100% of non-GPU <a href=\"https:\/\/twitter.com\/SmugMug?ref_src=twsrc%5Etfw\">@SmugMug<\/a> and <a href=\"https:\/\/twitter.com\/Flickr?ref_src=twsrc%5Etfw\">@Flickr<\/a> compute on ARM within the year. <a href=\"https:\/\/t.co\/fwXWdg06xx\">https:\/\/t.co\/fwXWdg06xx<\/a><\/p>&mdash; Don MacAskill (@DonMacAskill) <a href=\"https:\/\/twitter.com\/DonMacAskill\/status\/1314050996486561792?ref_src=twsrc%5Etfw\">October 8, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>","_oembed_time_59808117857ddf57e478a31d79f76e4d":"1628687155","_oembed_965c5b49aa8d22ce37dfb3bde0268600":"<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"de\" dir=\"ltr\">Der <a href=\"https:\/\/twitter.com\/hashtag\/Finanzausschuss?src=hash&amp;ref_src=twsrc%5Etfw\">#Finanzausschuss<\/a> im <a href=\"https:\/\/twitter.com\/hashtag\/Bundestag?src=hash&amp;ref_src=twsrc%5Etfw\">#Bundestag<\/a> hat das <a href=\"https:\/\/twitter.com\/hashtag\/Jahressteuergesetz?src=hash&amp;ref_src=twsrc%5Etfw\">#Jahressteuergesetz<\/a> beschlossen. Damit wurde auch die <a href=\"https:\/\/twitter.com\/hashtag\/Gemeinn%C3%BCtzigkeit?src=hash&amp;ref_src=twsrc%5Etfw\">#Gemeinn\u00fctzigkeit<\/a> f\u00fcr <a href=\"https:\/\/twitter.com\/hashtag\/Freifunk?src=hash&amp;ref_src=twsrc%5Etfw\">#Freifunk<\/a> Initiativen beschlossen. Das ganze geht jetzt in der kommenden Woche ins Plenum zur Abstimmung und direkt in den <a href=\"https:\/\/twitter.com\/hashtag\/Bundesrat?src=hash&amp;ref_src=twsrc%5Etfw\">#Bundesrat<\/a><\/p>&mdash; Jens Zimmermann (@JensZSPD) <a href=\"https:\/\/twitter.com\/JensZSPD\/status\/1336581821706989568?ref_src=twsrc%5Etfw\">December 9, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>","_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":"1628687156","_oembed_81002f7ee3604f645db4ebcfd1912acf":"<iframe title=\"Netzetag bei der Telekom: Antennen, Breitband, Glasfaser\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/6_NTa3VCRFo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_81002f7ee3604f645db4ebcfd1912acf":"1628687156","_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":"<iframe title=\"Firewall: Wie du die Web Application Firewall im Plesk Men\u00fc verwendest und deine Website sch\u00fctzt.\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/CzAjqyJtEaw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>","_oembed_time_7ea3429961cf98fa85da9747683af827":"1628687139","_elementor_controls_usage":null,"_elementor_page_assets":null,"_elementor_screenshot_failed":null,"theplus_transient_widgets":null,"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":null,"rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":"63","rank_math_contentai_score":null,"ilj_limitincominglinks":"","ilj_maxincominglinks":"1","ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":[],"ilj_linkdefinition":["HIPAA one","cybersecurity","intraprise health"],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":"HIPAA One","rank_math_og_content_image":null,"_yoast_wpseo_metadesc":null,"_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":"8018","footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts\/8017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/comments?post=8017"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/posts\/8017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/media\/8018"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/media?parent=8017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/categories?post=8017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webhosting.de\/fr\/wp-json\/wp\/v2\/tags?post=8017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}