{"id":41,"date":"2020-10-30T17:29:39","date_gmt":"2020-10-30T16:29:39","guid":{"rendered":"https:\/\/webhosting.de\/datenschutz\/"},"modified":"2025-02-22T15:52:46","modified_gmt":"2025-02-22T14:52:46","slug":"confidencialidade-dos-dados","status":"publish","type":"page","link":"https:\/\/webhosting.de\/pt\/datenschutz\/","title":{"rendered":"Prote\u00e7\u00e3o de dados"},"content":{"rendered":"<h1>Pol\u00edtica de privacidade<\/h1>\n<h2>1. prote\u00e7\u00e3o de dados em um relance<\/h2>\n<h3>Notas gerais<\/h3>\n<p>As informa\u00e7\u00f5es que se seguem fornecem uma vis\u00e3o geral simples do que acontece aos seus dados pessoais quando visita este s\u00edtio Web. Os dados pessoais s\u00e3o quaisquer dados que possam ser utilizados para o identificar pessoalmente. Pode encontrar informa\u00e7\u00f5es pormenorizadas sobre o tema da prote\u00e7\u00e3o de dados na nossa declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados, que se encontra abaixo deste texto.<\/p>\n<h3>Recolha de dados neste s\u00edtio Web<\/h3>\n<h4>Quem \u00e9 respons\u00e1vel pela recolha de dados neste s\u00edtio Web?<\/h4>\n<p>O tratamento dos dados neste s\u00edtio Web \u00e9 efectuado pelo operador do s\u00edtio Web. Pode encontrar os dados de contacto do operador na sec\u00e7\u00e3o \"Informa\u00e7\u00f5es sobre o respons\u00e1vel pelo tratamento\" da presente pol\u00edtica de privacidade.<\/p>\n<h4>Como \u00e9 que recolhemos os seus dados?<\/h4>\n<p>Por um lado, os dados do utilizador s\u00e3o recolhidos quando este os fornece. Podem ser, por exemplo, os dados que introduz num formul\u00e1rio de contacto.<\/p>\n<p>Outros dados s\u00e3o recolhidos automaticamente ou com o seu consentimento pelos nossos sistemas inform\u00e1ticos quando visita o s\u00edtio Web. Trata-se principalmente de dados t\u00e9cnicos (por exemplo, navegador da Internet, sistema operativo ou tempo de visualiza\u00e7\u00e3o da p\u00e1gina). Estes dados s\u00e3o recolhidos automaticamente assim que o utilizador entra neste s\u00edtio Web.<\/p>\n<h4>Para que \u00e9 que utilizamos os seus dados?<\/h4>\n<p>Alguns dos dados s\u00e3o recolhidos para garantir que o s\u00edtio Web \u00e9 fornecido sem erros. Outros dados podem ser utilizados para analisar o comportamento do utilizador. Se for poss\u00edvel celebrar ou iniciar contratos atrav\u00e9s do s\u00edtio Web, os dados transmitidos tamb\u00e9m ser\u00e3o processados para ofertas de contratos, encomendas ou outros pedidos de encomenda.<\/p>\n<h4>Que direitos tem relativamente aos seus dados?<\/h4>\n<p>O utilizador tem o direito de receber, em qualquer altura e gratuitamente, informa\u00e7\u00f5es sobre a origem, o destinat\u00e1rio e a finalidade dos seus dados pessoais armazenados. Tem tamb\u00e9m o direito de solicitar a corre\u00e7\u00e3o ou elimina\u00e7\u00e3o destes dados. Se tiver dado o seu consentimento para o processamento de dados, pode revogar esse consentimento em qualquer altura para o futuro. Tem tamb\u00e9m o direito de solicitar a restri\u00e7\u00e3o do tratamento dos seus dados pessoais em determinadas circunst\u00e2ncias. Al\u00e9m disso, tem o direito de apresentar uma queixa junto da autoridade de controlo competente.<\/p>\n<p>Pode contactar-nos em qualquer altura se tiver mais perguntas sobre a prote\u00e7\u00e3o de dados.<\/p>\n<h3>Ferramentas de an\u00e1lise e ferramentas de fornecedores terceiros<\/h3>\n<p>Quando o utilizador visita este s\u00edtio Web, o seu comportamento de navega\u00e7\u00e3o pode ser avaliado estatisticamente. Isto \u00e9 feito principalmente com os chamados programas de an\u00e1lise.<\/p>\n<p>Para informa\u00e7\u00f5es pormenorizadas sobre estes programas de an\u00e1lise, consultar a seguinte pol\u00edtica de privacidade.<\/p>\n<h2>2. alojamento e redes de distribui\u00e7\u00e3o de conte\u00fados (CDN)<\/h2>\n<p>O conte\u00fado do nosso s\u00edtio Web \u00e9 alojado no seguinte fornecedor:<\/p>\n<h3>Alojamento externo<\/h3>\n<p>Este s\u00edtio Web \u00e9 alojado externamente. Os dados pessoais recolhidos neste s\u00edtio Web s\u00e3o armazenados nos servidores do(s) anfitri\u00e3o(\u00f5es). Estes dados podem incluir endere\u00e7os IP, pedidos de contacto, metadados e dados de comunica\u00e7\u00e3o, dados contratuais, dados de contacto, nomes, acessos ao s\u00edtio Web e outros dados gerados atrav\u00e9s de um s\u00edtio Web.<\/p>\n<p>O alojamento externo \u00e9 efectuado para efeitos de cumprimento de contratos com os nossos clientes potenciais e actuais (art. 6, par. 1 lit. b do RGPD) e no interesse de uma disponibiliza\u00e7\u00e3o segura, r\u00e1pida e eficiente da nossa oferta online por um fornecedor profissional (art. 6, par. 1 lit. f do RGPD). Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo terminal do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>O(s) nosso(s) anfitri\u00e3o(\u00f5es) s\u00f3 processar\u00e1(\u00e3o) os seus dados na medida do necess\u00e1rio para cumprir as suas obriga\u00e7\u00f5es de desempenho e seguir as nossas instru\u00e7\u00f5es relativamente a esses dados.<\/p>\n<p>Utilizamos o(s) seguinte(s) hoster(s):<\/p>\n<p>webhoster.de AG<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Temos um <a href=\"https:\/\/webhosting.de\/pt\/webhosting-webdesign-und-asp-vertrag-was-sind-die-unterschiede\/\">Contrato<\/a> sobre o processamento de encomendas (AVV) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante que o servi\u00e7o apenas processa os dados pessoais dos visitantes do nosso s\u00edtio Web de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h3>Cloudflare<\/h3>\n<p>Utilizamos o servi\u00e7o \"Cloudflare\". O fornecedor \u00e9 a Cloudflare Inc, 101 Townsend St., San Francisco, CA 94107, EUA (a seguir designada por \"Cloudflare\").<\/p>\n<p>A Cloudflare oferece uma rede de distribui\u00e7\u00e3o de conte\u00fados distribu\u00edda globalmente com DNS. Tecnicamente, a transfer\u00eancia de informa\u00e7\u00f5es entre o seu browser e o nosso s\u00edtio Web \u00e9 encaminhada atrav\u00e9s da rede da Cloudflare. Isto permite \u00e0 Cloudflare analisar o tr\u00e1fego de dados entre o seu browser e o nosso s\u00edtio Web e atuar como um filtro entre os nossos servidores e o tr\u00e1fego de dados potencialmente malicioso da Internet. A Cloudflare pode tamb\u00e9m utilizar cookies ou outras tecnologias para reconhecer os utilizadores da Internet, mas estas s\u00e3o utilizadas apenas para os fins aqui descritos.<\/p>\n<p>A utiliza\u00e7\u00e3o do Cloudflare baseia-se no nosso interesse leg\u00edtimo em disponibilizar o nosso s\u00edtio Web da forma mais segura e isenta de erros poss\u00edvel (Art. 6, n.\u00ba 1, al\u00ednea f) do RGPD).<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Detalhes e mais informa\u00e7\u00f5es sobre seguran\u00e7a e prote\u00e7\u00e3o de dados na Cloudflare podem ser encontrados aqui: <a href=\"https:\/\/www.cloudflare.com\/privacypolicy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.cloudflare.com\/privacypolicy\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5666\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5666<\/a>.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h2>3 Notas gerais e informa\u00e7\u00f5es obrigat\u00f3rias<\/h2>\n<h3>Prote\u00e7\u00e3o de dados<\/h3>\n<p>Os operadores destas p\u00e1ginas levam muito a s\u00e9rio a prote\u00e7\u00e3o dos seus dados pessoais. Tratamos os seus dados pessoais de forma confidencial e de acordo com os regulamentos legais de prote\u00e7\u00e3o de dados e com esta pol\u00edtica de privacidade.<\/p>\n<p>Quando o utilizador utiliza este s\u00edtio Web, s\u00e3o recolhidos v\u00e1rios dados pessoais. Os dados pessoais s\u00e3o dados que podem ser utilizados para o identificar pessoalmente. Esta pol\u00edtica de privacidade explica quais os dados que recolhemos e para que os utilizamos. Explica tamb\u00e9m como e com que objetivo o fazemos.<\/p>\n<p>Gostar\u00edamos de salientar que a transmiss\u00e3o de dados atrav\u00e9s da Internet (por exemplo, ao comunicar por correio eletr\u00f3nico) pode estar sujeita a vulnerabilidades de seguran\u00e7a. N\u00e3o \u00e9 poss\u00edvel uma prote\u00e7\u00e3o completa dos dados contra o acesso de terceiros.<\/p>\n<h3>Nota sobre o organismo respons\u00e1vel<\/h3>\n<p>O respons\u00e1vel pelo tratamento dos dados neste s\u00edtio Web \u00e9<\/p>\n<p>Jan Schumacher<br \/>\niSearch GmbH<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<p>telefone: 02924 84154<br \/>\ne-mail: info@isearch.de<\/p>\n<p>O respons\u00e1vel pelo tratamento \u00e9 a pessoa singular ou colectiva que, individualmente ou em conjunto com outras, determina as finalidades e os meios de tratamento dos dados pessoais (por exemplo, nomes, endere\u00e7os de correio eletr\u00f3nico, etc.).<\/p>\n<h3>Dura\u00e7\u00e3o do armazenamento<\/h3>\n<p>A menos que tenha sido especificado um per\u00edodo de armazenamento mais espec\u00edfico na presente pol\u00edtica de privacidade, os seus dados pessoais permanecer\u00e3o connosco at\u00e9 que a finalidade do processamento de dados deixe de se aplicar. Se fizer um pedido justificado de apagamento ou revogar o seu consentimento para o tratamento de dados, os seus dados ser\u00e3o apagados, a menos que tenhamos outros motivos legalmente admiss\u00edveis para armazenar os seus dados pessoais (por exemplo, per\u00edodos de reten\u00e7\u00e3o ao abrigo da legisla\u00e7\u00e3o fiscal ou comercial); neste \u00faltimo caso, o apagamento ter\u00e1 lugar depois de esses motivos deixarem de se aplicar.<\/p>\n<h3>Informa\u00e7\u00f5es gerais sobre a base jur\u00eddica do tratamento de dados neste s\u00edtio Web<\/h3>\n<p>Se tiver dado o seu consentimento para o processamento de dados, processamos os seus dados pessoais com base no art. 6, n.\u00ba 1 lit. a do RGPD ou no art. 9, n.\u00ba 2 lit. a do RGPD, na medida em que categorias especiais de dados s\u00e3o processadas de acordo com o art. 9, n.\u00ba 1 do RGPD. No caso de um consentimento expresso para a transfer\u00eancia de dados pessoais para pa\u00edses terceiros, o processamento de dados \u00e9 tamb\u00e9m efectuado com base no Art. 49\u00ba, n\u00ba 1 lit. a do RGPD. Se tiver dado o seu consentimento para o armazenamento de cookies ou para o acesso a informa\u00e7\u00f5es no seu dispositivo final (por exemplo, atrav\u00e9s da impress\u00e3o digital do dispositivo), o processamento de dados tamb\u00e9m \u00e9 efectuado com base no \u00a7 25 (1) do TDDDG. O consentimento pode ser revogado em qualquer altura. Se os seus dados forem necess\u00e1rios para o cumprimento de um contrato ou para a implementa\u00e7\u00e3o de medidas pr\u00e9-contratuais, processamos os seus dados com base no Art. 6, par\u00e1grafo 1 lit. b do RGPD. Al\u00e9m disso, processamos os seus dados se tal for necess\u00e1rio para o cumprimento de uma obriga\u00e7\u00e3o legal com base no Art. 6, n.\u00ba 1, al\u00ednea c) do RGPD. O processamento de dados tamb\u00e9m pode ser efectuado com base no nosso interesse leg\u00edtimo, de acordo com o Art. 6, par. 1 lit. f do RGPD. As informa\u00e7\u00f5es sobre as bases jur\u00eddicas relevantes em cada caso individual s\u00e3o fornecidas nos par\u00e1grafos seguintes desta pol\u00edtica de privacidade.<\/p>\n<h3>Respons\u00e1vel pela prote\u00e7\u00e3o de dados<\/h3>\n<p>Nome\u00e1mos um respons\u00e1vel pela prote\u00e7\u00e3o de dados.<\/p>\n<p>Jan Schumacher<br \/>\niSearch GmbH<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<p>telefone: 02924 84154<br \/>\ne-mail: info@isearch.de<\/p>\n<h3>Nota sobre a transfer\u00eancia de dados para pa\u00edses terceiros que n\u00e3o est\u00e3o seguros ao abrigo da legisla\u00e7\u00e3o de prote\u00e7\u00e3o de dados e a transfer\u00eancia para empresas dos EUA que n\u00e3o s\u00e3o certificadas pela DPF<\/h3>\n<p>Entre outras coisas, utilizamos ferramentas de empresas sediadas em pa\u00edses terceiros que n\u00e3o est\u00e3o seguras ao abrigo da legisla\u00e7\u00e3o de prote\u00e7\u00e3o de dados e ferramentas dos EUA cujos fornecedores n\u00e3o est\u00e3o certificados ao abrigo do Quadro de Privacidade de Dados UE-EUA (DPF). Se estas ferramentas estiverem activas, os seus dados pessoais podem ser transferidos para esses pa\u00edses e a\u00ed tratados. Gostar\u00edamos de salientar que um n\u00edvel de prote\u00e7\u00e3o de dados compar\u00e1vel ao da UE n\u00e3o pode ser garantido em pa\u00edses terceiros que n\u00e3o s\u00e3o seguros ao abrigo da legisla\u00e7\u00e3o de prote\u00e7\u00e3o de dados.<\/p>\n<p>Gostar\u00edamos de salientar que os EUA, enquanto pa\u00eds terceiro seguro, t\u00eam geralmente um n\u00edvel de prote\u00e7\u00e3o de dados compar\u00e1vel ao da UE. Por conseguinte, a transfer\u00eancia de dados para os EUA \u00e9 permitida se o destinat\u00e1rio estiver certificado ao abrigo do \"Quadro de Privacidade de Dados UE-EUA\" (DPF) ou se tiver garantias adicionais adequadas. As informa\u00e7\u00f5es sobre as transfer\u00eancias para pa\u00edses terceiros, incluindo os destinat\u00e1rios dos dados, podem ser consultadas na presente pol\u00edtica de privacidade.<\/p>\n<h3>Destinat\u00e1rios dos dados pessoais<\/h3>\n<p>No \u00e2mbito das nossas actividades comerciais, trabalhamos em conjunto com v\u00e1rias organiza\u00e7\u00f5es externas. Nalguns casos, tamb\u00e9m \u00e9 necess\u00e1rio transferir dados pessoais para estas organiza\u00e7\u00f5es externas. Apenas transmitimos dados pessoais a entidades externas se tal for necess\u00e1rio para o cumprimento de um contrato, se formos legalmente obrigados a faz\u00ea-lo (por exemplo, transmiss\u00e3o de dados \u00e0s autoridades fiscais), se tivermos um interesse leg\u00edtimo na transmiss\u00e3o, de acordo com o Art. 6, n.\u00ba 1, al\u00ednea f) do RGPD, ou se outra base legal permitir a transmiss\u00e3o de dados. Quando recorremos a subcontratantes, apenas transmitimos os dados pessoais dos nossos clientes com base num contrato v\u00e1lido para o processamento de encomendas. No caso de processamento conjunto, \u00e9 celebrado um acordo de processamento conjunto.<\/p>\n<h3>Revoga\u00e7\u00e3o do seu consentimento para o processamento de dados<\/h3>\n<p>Muitas opera\u00e7\u00f5es de tratamento de dados s\u00f3 s\u00e3o poss\u00edveis com o seu consentimento expresso. O utilizador pode retirar o seu consentimento em qualquer altura. A legalidade do tratamento de dados efectuado at\u00e9 \u00e0 revoga\u00e7\u00e3o n\u00e3o \u00e9 afetada pela revoga\u00e7\u00e3o.<\/p>\n<h3>Direito de oposi\u00e7\u00e3o \u00e0 recolha de dados em casos especiais e ao marketing direto (art. 21.\u00ba do RGPD)<\/h3>\n<p>SE O TRATAMENTO DE DADOS SE BASEAR NO ART. 6 ABS. 1 LIT. E OU F DO RGPD, TEM O DIREITO DE SE OPOR AO TRATAMENTO DOS SEUS DADOS PESSOAIS EM QUALQUER ALTURA POR MOTIVOS RELACIONADOS COM A SUA SITUA\u00c7\u00c3O PARTICULAR; ISTO TAMB\u00c9M SE APLICA \u00c0 DEFINI\u00c7\u00c3O DE PERFIS COM BASE NESTAS DISPOSI\u00c7\u00d5ES. A RESPECTIVA BASE LEGAL EM QUE SE BASEIA O PROCESSAMENTO PODE SER ENCONTRADA NESTA POL\u00cdTICA DE PRIVACIDADE. SE SE OPUSER, DEIXAREMOS DE TRATAR OS SEUS DADOS PESSOAIS EM CAUSA, A MENOS QUE POSSAMOS DEMONSTRAR MOTIVOS LEG\u00cdTIMOS IMPERIOSOS PARA O TRATAMENTO QUE SE SOBREPONHAM AOS SEUS INTERESSES, DIREITOS E LIBERDADES, OU QUE O TRATAMENTO SIRVA PARA A DECLARA\u00c7\u00c3O, O EXERC\u00cdCIO OU A DEFESA DE UM DIREITO NUM PROCESSO JUDICIAL (OBJEC\u00c7\u00c3O NOS TERMOS DO ART. 21\u00ba, N\u00ba 1, DO RGPD).<\/p>\n<p>SE OS SEUS DADOS PESSOAIS FOREM TRATADOS PARA EFEITOS DE COMERCIALIZA\u00c7\u00c3O DIRECTA, TEM O DIREITO DE SE OPOR, EM QUALQUER MOMENTO, AO TRATAMENTO DOS DADOS PESSOAIS QUE LHE DIGAM RESPEITO PARA EFEITOS DESSA COMERCIALIZA\u00c7\u00c3O; O MESMO SE APLICA \u00c0 DEFINI\u00c7\u00c3O DE PERFIS, NA MEDIDA EM QUE ESTEJA RELACIONADA COM ESSA COMERCIALIZA\u00c7\u00c3O DIRECTA. SE SE OPUSER, OS SEUS DADOS PESSOAIS DEIXAR\u00c3O DE SER UTILIZADOS PARA EFEITOS DE COMERCIALIZA\u00c7\u00c3O DIRECTA (OBJEC\u00c7\u00c3O NOS TERMOS DO ART. 21\u00ba, N\u00ba 2 DO RGPD).<\/p>\n<h3>Direito de apresentar uma queixa \u00e0 autoridade de controlo competente<\/h3>\n<p>Em caso de infra\u00e7\u00e3o ao RGPD, as pessoas em causa t\u00eam o direito de apresentar uma queixa a uma autoridade de controlo, nomeadamente no Estado-Membro da sua resid\u00eancia habitual, do seu local de trabalho ou do local da alegada infra\u00e7\u00e3o. O direito de apresentar uma queixa n\u00e3o prejudica quaisquer outras vias de recurso administrativo ou judicial.<\/p>\n<h3>Direito \u00e0 portabilidade dos dados<\/h3>\n<p>O utilizador tem o direito a que os dados que tratamos automaticamente com base no seu consentimento ou no cumprimento de um contrato lhe sejam transmitidos, a si ou a terceiros, num formato comummente utilizado e leg\u00edvel por m\u00e1quina. Se solicitar a transfer\u00eancia direta dos dados para outro respons\u00e1vel pelo tratamento, esta s\u00f3 ter\u00e1 lugar se for tecnicamente vi\u00e1vel.<\/p>\n<h3>Informa\u00e7\u00e3o, corre\u00e7\u00e3o e supress\u00e3o<\/h3>\n<p>No \u00e2mbito das disposi\u00e7\u00f5es legais aplic\u00e1veis, tem o direito de, a qualquer momento, obter informa\u00e7\u00f5es gratuitas sobre os seus dados pessoais armazenados, a sua origem e destinat\u00e1rio e a finalidade do tratamento de dados e, se necess\u00e1rio, o direito de corrigir ou apagar esses dados. Pode contactar-nos a qualquer momento se tiver mais perguntas sobre a quest\u00e3o dos dados pessoais.<\/p>\n<h3>Direito \u00e0 limita\u00e7\u00e3o do tratamento<\/h3>\n<p>O utilizador tem o direito de solicitar a limita\u00e7\u00e3o do tratamento dos seus dados pessoais. Para tal, pode contactar-nos em qualquer altura. O direito \u00e0 limita\u00e7\u00e3o do tratamento existe nos seguintes casos:<\/p>\n<ul>\n<li>Se contestar a exatid\u00e3o dos seus dados pessoais armazenados por n\u00f3s, geralmente precisamos de tempo para os verificar. Durante o per\u00edodo de revis\u00e3o, o utilizador tem o direito de solicitar que o processamento dos seus dados pessoais seja restringido.<\/li>\n<li>Se o tratamento dos seus dados pessoais foi\/\u00e9 ilegal, pode solicitar a restri\u00e7\u00e3o do tratamento dos dados em vez do seu apagamento.<\/li>\n<li>Se j\u00e1 n\u00e3o precisarmos dos seus dados pessoais, mas precisarmos deles para o exerc\u00edcio, defesa ou reivindica\u00e7\u00e3o de ac\u00e7\u00f5es judiciais, tem o direito de solicitar a restri\u00e7\u00e3o do tratamento dos seus dados pessoais em vez do seu apagamento.<\/li>\n<li>Se apresentou uma obje\u00e7\u00e3o em conformidade com o Art. 21 (1) do RGPD, deve ser estabelecido um equil\u00edbrio entre os seus interesses e os nossos. Enquanto n\u00e3o for determinado quais os interesses que prevalecem, o utilizador tem o direito de solicitar a restri\u00e7\u00e3o do tratamento dos seus dados pessoais.<\/li>\n<\/ul>\n<p>Se tiver restringido o tratamento dos seus dados pessoais, estes dados - para al\u00e9m da sua conserva\u00e7\u00e3o - s\u00f3 podem ser tratados com o seu consentimento ou para a declara\u00e7\u00e3o, o exerc\u00edcio ou a defesa de um direito num processo judicial ou para a prote\u00e7\u00e3o dos direitos de outra pessoa singular ou colectiva ou por motivos de interesse p\u00fablico importante da Uni\u00e3o Europeia ou de um Estado-Membro.<\/p>\n<h3>Encripta\u00e7\u00e3o SSL ou TLS<\/h3>\n<p>Este s\u00edtio utiliza a encripta\u00e7\u00e3o SSL ou TLS por raz\u00f5es de seguran\u00e7a e para proteger a transmiss\u00e3o de conte\u00fados confidenciais, tais como encomendas ou pedidos de informa\u00e7\u00e3o que nos envia enquanto operador do s\u00edtio. Pode reconhecer uma liga\u00e7\u00e3o encriptada pelo facto de a linha de endere\u00e7o do navegador mudar de \"http:\/\/\" para \"https:\/\/\" e pelo s\u00edmbolo de cadeado na linha do seu navegador.<\/p>\n<p>Se a encripta\u00e7\u00e3o SSL ou TLS estiver activada, os dados que nos transmite n\u00e3o podem ser lidos por terceiros.<\/p>\n<h3>Transac\u00e7\u00f5es de pagamento encriptadas neste s\u00edtio Web<\/h3>\n<p>Se houver uma obriga\u00e7\u00e3o de nos fornecer os seus dados de pagamento (por exemplo, n\u00famero de conta para autoriza\u00e7\u00e3o de d\u00e9bito direto) ap\u00f3s a celebra\u00e7\u00e3o de um contrato a t\u00edtulo oneroso, estes dados s\u00e3o necess\u00e1rios para o processamento do pagamento.<\/p>\n<p>As opera\u00e7\u00f5es de pagamento atrav\u00e9s dos meios de pagamento habituais (Visa\/MasterCard, d\u00e9bito direto) s\u00e3o efectuadas exclusivamente atrav\u00e9s de uma liga\u00e7\u00e3o encriptada SSL ou TLS. \u00c9 poss\u00edvel reconhecer uma liga\u00e7\u00e3o encriptada pelo facto de a linha de endere\u00e7o do browser mudar de \"http:\/\/\" para \"https:\/\/\" e pelo s\u00edmbolo de cadeado na linha do browser.<\/p>\n<p>Com uma comunica\u00e7\u00e3o encriptada, os dados de pagamento que nos transmite n\u00e3o podem ser lidos por terceiros.<\/p>\n<h3>Obje\u00e7\u00e3o a mensagens electr\u00f3nicas publicit\u00e1rias<\/h3>\n<p>Opomo-nos \u00e0 utiliza\u00e7\u00e3o dos dados de contacto publicados no \u00e2mbito da nossa obriga\u00e7\u00e3o de notifica\u00e7\u00e3o legal para efeitos de envio de material publicit\u00e1rio e informativo n\u00e3o solicitado. Os operadores deste s\u00edtio Web reservam-se expressamente o direito de tomar medidas legais em caso de envio n\u00e3o solicitado de informa\u00e7\u00f5es publicit\u00e1rias, tais como mensagens de correio eletr\u00f3nico n\u00e3o solicitadas.<\/p>\n<h2>4. recolha de dados neste s\u00edtio Web<\/h2>\n<h3>Biscoitos<\/h3>\n<p>As nossas p\u00e1ginas da Internet utilizam os chamados \"cookies\". Os cookies s\u00e3o pequenos pacotes de dados e n\u00e3o causam qualquer dano ao seu dispositivo final. S\u00e3o armazenados no seu dispositivo temporariamente durante uma sess\u00e3o (cookies de sess\u00e3o) ou permanentemente (cookies permanentes). Os cookies de sess\u00e3o s\u00e3o automaticamente eliminados no final da sua visita. Os cookies permanentes permanecem armazenados no seu dispositivo final at\u00e9 que os apague ou at\u00e9 que sejam automaticamente apagados pelo seu navegador Web.<\/p>\n<p>Os cookies podem ser originados por n\u00f3s (cookies prim\u00e1rios) ou por empresas terceiras (os chamados cookies de terceiros). Os cookies de terceiros permitem a integra\u00e7\u00e3o de determinados servi\u00e7os de empresas terceiras nos s\u00edtios Web (por exemplo, cookies para o processamento de servi\u00e7os de pagamento).<\/p>\n<p>Os cookies t\u00eam v\u00e1rias fun\u00e7\u00f5es. Muitos cookies s\u00e3o tecnicamente necess\u00e1rios, uma vez que certas fun\u00e7\u00f5es do s\u00edtio Web n\u00e3o funcionariam sem eles (por exemplo, a fun\u00e7\u00e3o de cesto de compras ou a apresenta\u00e7\u00e3o de v\u00eddeos). Outros cookies podem ser utilizados para analisar o comportamento dos utilizadores ou para fins publicit\u00e1rios.<\/p>\n<p>Os cookies que s\u00e3o necess\u00e1rios para realizar o processo de comunica\u00e7\u00e3o eletr\u00f3nica, para fornecer determinadas fun\u00e7\u00f5es que tenha solicitado (por exemplo, para a fun\u00e7\u00e3o de cesto de compras) ou para otimizar o s\u00edtio Web (por exemplo, cookies para medir a audi\u00eancia da Web) (cookies necess\u00e1rios) s\u00e3o armazenados com base no Art. 6, n.\u00ba 1 lit. f do RGPD, a menos que seja especificada outra base jur\u00eddica. O operador do s\u00edtio Web tem um interesse leg\u00edtimo no armazenamento dos cookies necess\u00e1rios para a presta\u00e7\u00e3o tecnicamente sem erros e optimizada dos seus servi\u00e7os. Se tiver sido solicitado o consentimento para o armazenamento de cookies e tecnologias de reconhecimento compar\u00e1veis, o processamento \u00e9 efectuado exclusivamente com base neste consentimento (Art. 6, par. 1 lit. a RGPD e \u00a7 25, par. 1 TDDDG); o consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Pode configurar o seu browser de modo a ser informado sobre a defini\u00e7\u00e3o de cookies e permitir cookies apenas em casos individuais, excluir a aceita\u00e7\u00e3o de cookies em determinados casos ou em geral e ativar a elimina\u00e7\u00e3o autom\u00e1tica de cookies ao fechar o browser. Se os cookies forem desactivados, a funcionalidade deste s\u00edtio Web pode ser limitada.<\/p>\n<p>Pode saber que cookies e servi\u00e7os s\u00e3o utilizados neste s\u00edtio Web na presente pol\u00edtica de privacidade.<\/p>\n<h3>Consentimento com os usocentristas<\/h3>\n<p>Este s\u00edtio Web utiliza a tecnologia de consentimento da Usercentrics para obter o seu consentimento para o armazenamento de determinados cookies no seu dispositivo final ou para a utiliza\u00e7\u00e3o de determinadas tecnologias e para as documentar em conformidade com os regulamentos de prote\u00e7\u00e3o de dados. O fornecedor desta tecnologia \u00e9 a Usercentrics GmbH, Sendlinger Stra\u00dfe 7, 80331 Munique, Alemanha, s\u00edtio Web: <a href=\"https:\/\/usercentrics.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/usercentrics.com\/de\/<\/a> (a seguir designados por \"Usercentrics\").<\/p>\n<p>Quando entra no nosso s\u00edtio Web, os seguintes dados pessoais s\u00e3o transmitidos \u00e0 Usercentrics:<\/p>\n<ul>\n<li>O(s) seu(s) consentimento(s) ou a revoga\u00e7\u00e3o do(s) seu(s) consentimento(s)<\/li>\n<li>O seu endere\u00e7o IP<\/li>\n<li>Informa\u00e7\u00f5es sobre o seu browser<\/li>\n<li>Informa\u00e7\u00f5es sobre o seu dispositivo final<\/li>\n<li>Hora da sua visita ao s\u00edtio Web<\/li>\n<li>Geolocaliza\u00e7\u00e3o<\/li>\n<\/ul>\n<p>Al\u00e9m disso, a Usercentrics armazena um cookie no seu browser para poder atribuir os consentimentos que deu ou revog\u00e1-los. Os dados recolhidos desta forma s\u00e3o armazenados at\u00e9 que o utilizador nos pe\u00e7a para os apagar, apague o cookie da Usercentrics ou a finalidade do armazenamento dos dados deixe de se aplicar. As obriga\u00e7\u00f5es legais obrigat\u00f3rias de reten\u00e7\u00e3o n\u00e3o s\u00e3o afectadas.<\/p>\n<p>A Usercentrics \u00e9 utilizada para obter o consentimento legalmente exigido para a utiliza\u00e7\u00e3o de determinadas tecnologias. A base legal para tal \u00e9 o Art. 6, par\u00e1grafo 1, al\u00ednea c) do RGPD.<\/p>\n<h3>Consentimento com o cookie da Borlabs<\/h3>\n<p>O nosso site utiliza a tecnologia de consentimento de cookies da Borlabs para obter o seu consentimento para o armazenamento de determinados cookies no seu browser ou para a utiliza\u00e7\u00e3o de determinadas tecnologias e para as documentar em conformidade com os regulamentos de prote\u00e7\u00e3o de dados. O fornecedor desta tecnologia \u00e9 a Borlabs GmbH, R\u00fcbenkamp 32, 22305 Hamburgo, Alemanha (doravante designada por Borlabs).<\/p>\n<p>Quando entra no nosso s\u00edtio Web, \u00e9 armazenado no seu navegador um cookie Borlabs, no qual s\u00e3o armazenados os consentimentos que deu ou a revoga\u00e7\u00e3o desses consentimentos. Estes dados n\u00e3o s\u00e3o transmitidos ao fornecedor do cookie Borlabs.<\/p>\n<p>Os dados coletados ser\u00e3o armazenados at\u00e9 que voc\u00ea nos pe\u00e7a para exclu\u00ed-los ou exclua o cookie da Borlabs ou at\u00e9 que a finalidade do armazenamento dos dados n\u00e3o se aplique mais. Os per\u00edodos de reten\u00e7\u00e3o estatut\u00e1rios obrigat\u00f3rios n\u00e3o s\u00e3o afectados. Detalhes sobre o processamento de dados pelo Cookie da Borlabs podem ser encontrados em <a href=\"https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/<\/a>.<\/p>\n<p>A tecnologia de consentimento de cookies da Borlabs \u00e9 usada para obter o consentimento legalmente exigido para o uso de cookies. A base legal para isso \u00e9 o Art. 6, par\u00e1grafo 1 lit. c do GDPR.<\/p>\n<h3>Consentimento com Cookiebot<\/h3>\n<p>O nosso s\u00edtio Web utiliza a tecnologia de consentimento da Cookiebot para obter o seu consentimento para o armazenamento de determinados cookies no seu dispositivo final ou para a utiliza\u00e7\u00e3o de determinadas tecnologias e para documentar isto em conformidade com os regulamentos de prote\u00e7\u00e3o de dados. O fornecedor desta tecnologia \u00e9 a Cybot A\/S, Havnegade 39, 1058 Copenhaga, Dinamarca (a seguir designada por \"Cookiebot\").<\/p>\n<p>Quando entra no nosso site, \u00e9 estabelecida uma liga\u00e7\u00e3o aos servidores de Cookiebot para obter o seu consentimento e outras declara\u00e7\u00f5es relativas \u00e0 utiliza\u00e7\u00e3o de cookies. Cookiebot armazena ent\u00e3o um cookie no seu navegador para poder atribuir-lhe os consentimentos dados ou a sua revoga\u00e7\u00e3o. Os dados recolhidos desta forma s\u00e3o armazenados at\u00e9 que nos pe\u00e7a para os apagar, at\u00e9 que apague o cookie Cookiebot ou at\u00e9 que a finalidade do armazenamento de dados deixe de se aplicar. As obriga\u00e7\u00f5es legais obrigat\u00f3rias de conserva\u00e7\u00e3o n\u00e3o s\u00e3o afectadas.<\/p>\n<p>Cookiebot \u00e9 utilizado para obter o consentimento legalmente exigido para a utiliza\u00e7\u00e3o de cookies. A base legal para tal \u00e9 o art. 6, n.\u00ba 1, al\u00ednea c) do RGPD.<\/p>\n<h3>Ficheiros de registo do servidor<\/h3>\n<p>O fornecedor das p\u00e1ginas recolhe e armazena automaticamente informa\u00e7\u00f5es nos chamados ficheiros de registo do servidor, que o seu browser nos transmite automaticamente. Estes ficheiros s\u00e3o<\/p>\n<ul>\n<li>Tipo e vers\u00e3o do navegador<\/li>\n<li>Sistema operacional utilizado<\/li>\n<li>URL de refer\u00eancia<\/li>\n<li>Nome do anfitri\u00e3o do computador de acesso<\/li>\n<li>Hora do pedido do servidor<\/li>\n<li>endere\u00e7o IP<\/li>\n<\/ul>\n<p>Estes dados n\u00e3o s\u00e3o fundidos com outras fontes de dados.<\/p>\n<p>Estes dados s\u00e3o recolhidos com base no art. 6, n.\u00ba 1, al\u00ednea f) do RGPD. O operador do site tem um interesse leg\u00edtimo na apresenta\u00e7\u00e3o e otimiza\u00e7\u00e3o tecnicamente sem erros do seu site - os ficheiros de registo do servidor devem ser registados para este fim.<\/p>\n<h3>Formul\u00e1rio de contato<\/h3>\n<p>Se nos enviar pedidos de informa\u00e7\u00e3o atrav\u00e9s do formul\u00e1rio de contacto, os seus dados do formul\u00e1rio de pedido de informa\u00e7\u00e3o, incluindo os dados de contacto que a\u00ed fornecer, ser\u00e3o armazenados por n\u00f3s para efeitos de processamento do pedido de informa\u00e7\u00e3o e em caso de perguntas subsequentes. N\u00e3o transmitiremos estes dados sem o seu consentimento.<\/p>\n<p>Estes dados s\u00e3o processados com base no art. 6, n.\u00ba 1, al\u00ednea b) do RGPD, se o seu pedido de informa\u00e7\u00e3o estiver relacionado com o cumprimento de um contrato ou for necess\u00e1rio para a implementa\u00e7\u00e3o de medidas pr\u00e9-contratuais. Em todos os outros casos, o tratamento baseia-se no nosso interesse leg\u00edtimo no tratamento efetivo dos pedidos de informa\u00e7\u00e3o que nos s\u00e3o dirigidos (art. 6.\u00ba, n.\u00ba 1, al\u00ednea f) do RGPD) ou no seu consentimento (art. 6.\u00ba, n.\u00ba 1, al\u00ednea a) do RGPD), se este tiver sido solicitado; o consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Conservaremos os dados que fornecer no formul\u00e1rio de contacto at\u00e9 que solicite a sua elimina\u00e7\u00e3o, revogue o seu consentimento para a sua conserva\u00e7\u00e3o ou a finalidade da sua conserva\u00e7\u00e3o deixe de ser relevante (por exemplo, ap\u00f3s a satisfa\u00e7\u00e3o do seu pedido). As disposi\u00e7\u00f5es legais obrigat\u00f3rias - em particular os per\u00edodos de reten\u00e7\u00e3o - n\u00e3o s\u00e3o afectadas.<\/p>\n<h3>Inscri\u00e7\u00e3o neste site<\/h3>\n<p>Pode registar-se neste s\u00edtio Web para poder utilizar fun\u00e7\u00f5es adicionais do s\u00edtio. Apenas utilizaremos os dados introduzidos para efeitos de utiliza\u00e7\u00e3o da respectiva oferta ou servi\u00e7o para o qual se registou. As informa\u00e7\u00f5es obrigat\u00f3rias solicitadas durante o registo devem ser fornecidas na \u00edntegra. Caso contr\u00e1rio, recusaremos o seu registo.<\/p>\n<p>No caso de altera\u00e7\u00f5es importantes, por exemplo, no \u00e2mbito da oferta ou de altera\u00e7\u00f5es tecnicamente necess\u00e1rias, utilizaremos o endere\u00e7o de correio eletr\u00f3nico fornecido durante o registo para o informar desta forma.<\/p>\n<p>Os dados introduzidos durante o registo s\u00e3o processados com o objetivo de implementar a rela\u00e7\u00e3o de utilizador estabelecida pelo registo e, se necess\u00e1rio, para a inicia\u00e7\u00e3o de outros contratos (Art. 6, n.\u00ba 1, al\u00ednea b) do RGPD).<\/p>\n<p>Os dados recolhidos durante o registo ser\u00e3o guardados por n\u00f3s durante o tempo em que estiver registado neste s\u00edtio Web e ser\u00e3o depois apagados. Os per\u00edodos de reten\u00e7\u00e3o legais n\u00e3o s\u00e3o afectados.<\/p>\n<h3>Registro no Facebook Connect<\/h3>\n<p>Em vez de se registar diretamente neste s\u00edtio Web, pode registar-se em <a href=\"https:\/\/webhosting.de\/pt\/facebook-likes-kaufen-der-koenigsweg-zur-kundenvertreibung\/\">Facebook<\/a> Ligar. O fornecedor deste servi\u00e7o \u00e9 a Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irlanda. No entanto, de acordo com o Facebook, os dados recolhidos s\u00e3o tamb\u00e9m transferidos para os EUA e outros pa\u00edses terceiros.<\/p>\n<p>Se decidir registar-se no Facebook Connect e clicar no bot\u00e3o \"Iniciar sess\u00e3o com o Facebook\"\/\"Ligar ao Facebook\", ser\u00e1 automaticamente redireccionado para a plataforma do Facebook. A\u00ed poder\u00e1 iniciar sess\u00e3o com os seus dados de utilizador. Isto ir\u00e1 ligar o seu perfil do Facebook a este s\u00edtio Web ou aos nossos servi\u00e7os. Esta liga\u00e7\u00e3o d\u00e1-nos acesso aos seus dados armazenados no Facebook. Estes s\u00e3o, acima de tudo<\/p>\n<ul>\n<li>nome no Facebook<\/li>\n<li>Perfil no Facebook e foto da capa<\/li>\n<li>foto de capa do Facebook<\/li>\n<li>endere\u00e7o de e-mail cadastrado no Facebook<\/li>\n<li>ID do Facebook<\/li>\n<li>listas de amigos no Facebook<\/li>\n<li>Gostos do Facebook (informa\u00e7\u00f5es de \"Gosto\")<\/li>\n<li>Anivers\u00e1rio<\/li>\n<li>G\u00eanero<\/li>\n<li>Pa\u00eds<\/li>\n<li>Idioma<\/li>\n<\/ul>\n<p>Esta informa\u00e7\u00e3o \u00e9 utilizada para configurar, aprovisionar e personalizar a sua conta.<\/p>\n<p>O registo no Facebook Connect e as opera\u00e7\u00f5es de processamento de dados associadas baseiam-se no seu consentimento (Art. 6, n.\u00ba 1, al\u00ednea a) do RGPD). Pode revogar este consentimento em qualquer altura, com efeitos para o futuro.<\/p>\n<p>Na medida em que os dados pessoais s\u00e3o recolhidos no nosso s\u00edtio Web com a ajuda da ferramenta aqui descrita e transmitidos ao Facebook, n\u00f3s e a Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlanda, somos conjuntamente respons\u00e1veis por este processamento de dados (Art. 26.\u00ba do RGPD). A responsabilidade conjunta limita-se exclusivamente \u00e0 recolha dos dados e \u00e0 sua transmiss\u00e3o ao Facebook. O processamento efectuado pelo Facebook ap\u00f3s a transmiss\u00e3o n\u00e3o faz parte da responsabilidade conjunta. As obriga\u00e7\u00f5es que nos incumbem em conjunto foram definidas num acordo sobre o processamento conjunto. Pode encontrar o texto do acordo em <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. De acordo com este acordo, somos respons\u00e1veis por fornecer as informa\u00e7\u00f5es de prote\u00e7\u00e3o de dados ao utilizar a ferramenta do Facebook e pela implementa\u00e7\u00e3o segura da ferramenta no nosso s\u00edtio Web, de acordo com a lei de prote\u00e7\u00e3o de dados. O Facebook \u00e9 respons\u00e1vel pela seguran\u00e7a dos dados dos produtos do Facebook. Pode fazer valer os direitos do titular dos dados (por exemplo, pedidos de informa\u00e7\u00e3o) relativamente aos dados processados pelo Facebook diretamente junto do Facebook. Se fizer valer os seus direitos de titular de dados junto de n\u00f3s, somos obrigados a transmiti-los ao Facebook.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a> e <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/policy.php<\/a>.<\/p>\n<p>Para mais informa\u00e7\u00f5es, consulte os Termos de Uso do Facebook e a Pol\u00edtica de Privacidade do Facebook. Estes podem ser encontrados em: <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a> e <a href=\"https:\/\/de-de.facebook.com\/legal\/terms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/legal\/terms\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>Registo no Google<\/h3>\n<p>Em vez de se registar diretamente neste s\u00edtio Web, o utilizador pode registar-se junto da Google. O fornecedor deste servi\u00e7o \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>Para se registar no Google, basta introduzir o seu nome Google e a sua palavra-passe. A Google identific\u00e1-lo-\u00e1 e confirmar\u00e1 a sua identidade no nosso s\u00edtio Web.<\/p>\n<p>Quando o utilizador inicia sess\u00e3o no Google, poderemos utilizar determinadas informa\u00e7\u00f5es da sua conta para completar o seu perfil connosco. O utilizador pode decidir se e que informa\u00e7\u00f5es s\u00e3o estas, como parte das suas defini\u00e7\u00f5es de seguran\u00e7a do Google, que pode encontrar aqui: <a href=\"https:\/\/myaccount.google.com\/security\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/myaccount.google.com\/security<\/a> e <a href=\"https:\/\/myaccount.google.com\/permissions\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/myaccount.google.com\/permissions<\/a>.<\/p>\n<p>O processamento de dados associado ao registo no Google baseia-se no nosso interesse leg\u00edtimo em tornar o processo de registo o mais simples poss\u00edvel para os nossos utilizadores (Art. 6, n.\u00ba 1, al\u00ednea f) do RGPD). Uma vez que a utiliza\u00e7\u00e3o da fun\u00e7\u00e3o de registo \u00e9 volunt\u00e1ria e que os pr\u00f3prios utilizadores podem decidir sobre as respectivas op\u00e7\u00f5es de acesso, n\u00e3o se vislumbram quaisquer direitos de preval\u00eancia conflituantes dos titulares dos dados.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Fun\u00e7\u00e3o de coment\u00e1rio neste s\u00edtio Web<\/h3>\n<p>Para a fun\u00e7\u00e3o de coment\u00e1rio nesta p\u00e1gina, para al\u00e9m do seu coment\u00e1rio, ser\u00e3o guardadas informa\u00e7\u00f5es sobre a hora a que o coment\u00e1rio foi criado, o seu endere\u00e7o de correio eletr\u00f3nico e, se n\u00e3o estiver a publicar anonimamente, o nome de utilizador que escolheu.<\/p>\n<h4>Armazenamento do endere\u00e7o IP<\/h4>\n<p>A nossa fun\u00e7\u00e3o de coment\u00e1rios armazena os endere\u00e7os IP dos utilizadores que publicam coment\u00e1rios. Como n\u00e3o verificamos os coment\u00e1rios neste s\u00edtio Web antes de serem activados, precisamos destes dados para podermos tomar medidas contra o autor em caso de viola\u00e7\u00f5es legais, como insultos ou propaganda.<\/p>\n<h4>Subscreva os coment\u00e1rios<\/h4>\n<p>Como utilizador do s\u00edtio, pode subscrever coment\u00e1rios depois de se registar. Receber\u00e1 uma mensagem de correio eletr\u00f3nico de confirma\u00e7\u00e3o para verificar se \u00e9 o propriet\u00e1rio do endere\u00e7o de correio eletr\u00f3nico fornecido. Pode anular a subscri\u00e7\u00e3o desta fun\u00e7\u00e3o em qualquer altura atrav\u00e9s de uma liga\u00e7\u00e3o nos e-mails de informa\u00e7\u00e3o. Neste caso, os dados introduzidos aquando da subscri\u00e7\u00e3o dos coment\u00e1rios ser\u00e3o eliminados; no entanto, se nos tiver transmitido estes dados para outros fins e noutro local (por exemplo, subscri\u00e7\u00e3o da newsletter), estes dados permanecer\u00e3o connosco.<\/p>\n<h4>Dura\u00e7\u00e3o de armazenamento dos coment\u00e1rios<\/h4>\n<p>Os coment\u00e1rios e os dados associados s\u00e3o armazenados e permanecem neste s\u00edtio Web at\u00e9 que o conte\u00fado comentado tenha sido completamente apagado ou os coment\u00e1rios tenham de ser apagados por raz\u00f5es legais (por exemplo, coment\u00e1rios ofensivos).<\/p>\n<h4>Base legal<\/h4>\n<p>Os coment\u00e1rios s\u00e3o armazenados com base no seu consentimento (art. 6.\u00ba, n.\u00ba 1, al\u00ednea a) do RGPD). Pode revogar o seu consentimento em qualquer altura. Para tal, basta enviar-nos um e-mail informal. A legalidade das opera\u00e7\u00f5es de tratamento de dados j\u00e1 efectuadas n\u00e3o \u00e9 afetada pela revoga\u00e7\u00e3o.<\/p>\n<h3>Especialista comprovado<\/h3>\n<p>Integr\u00e1mos selos de classifica\u00e7\u00e3o da ProvenExpert neste s\u00edtio Web. O fornecedor \u00e9 a Expert Systems AG, Quedlinburger Str. 1, 10589 Berlin, <a href=\"https:\/\/www.provenexpert.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.provenexpert.com<\/a>.<\/p>\n<p>O selo ProvenExpert permite-nos apresentar no nosso s\u00edtio Web as opini\u00f5es dos clientes que foram submetidas \u00e0 ProvenExpert sobre a nossa empresa num selo. Quando visita o nosso website, \u00e9 estabelecida uma liga\u00e7\u00e3o com a ProvenExpert para que esta possa reconhecer que visitou o nosso website. A ProvenExpert tamb\u00e9m regista as suas defini\u00e7\u00f5es de idioma para apresentar o selo no idioma nacional selecionado.<\/p>\n<p>ProvenExpert \u00e9 utilizado com base no Art. 6, par\u00e1grafo 1 lit. f do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo em apresentar as opini\u00f5es dos clientes de uma forma t\u00e3o compreens\u00edvel quanto poss\u00edvel. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no art. 6, n.\u00ba 1, al\u00ednea a) do RGPD e no \u00a7 25, n.\u00ba 1 da TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo final do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o da TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<h2>5. M\u00eddias sociais<\/h2>\n<h3>Facebook<\/h3>\n<p>Os elementos da rede social Facebook est\u00e3o integrados neste s\u00edtio Web. O fornecedor deste servi\u00e7o \u00e9 a Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irlanda. No entanto, de acordo com o Facebook, os dados recolhidos s\u00e3o tamb\u00e9m transferidos para os EUA e outros pa\u00edses terceiros.<\/p>\n<p>Pode encontrar uma vis\u00e3o geral dos elementos das redes sociais do Facebook aqui: <a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE<\/a>.<\/p>\n<p>Quando o elemento de rede social est\u00e1 ativo, \u00e9 estabelecida uma liga\u00e7\u00e3o direta entre o seu dispositivo final e o servidor do Facebook. O Facebook recebe a informa\u00e7\u00e3o de que o utilizador visitou este s\u00edtio Web com o seu endere\u00e7o IP. Se clicar no bot\u00e3o \"Gosto\" do Facebook enquanto estiver ligado \u00e0 sua conta do Facebook, pode associar o conte\u00fado deste s\u00edtio Web ao seu perfil do Facebook. Isto permite ao Facebook associar a sua visita a este s\u00edtio Web \u00e0 sua conta de utilizador. Gostar\u00edamos de salientar que, enquanto fornecedor das p\u00e1ginas, n\u00e3o temos conhecimento do conte\u00fado dos dados transmitidos ou da sua utiliza\u00e7\u00e3o pelo Facebook. Para mais informa\u00e7\u00f5es sobre este assunto, consultar a pol\u00edtica de privacidade do Facebook em <a href=\"https:\/\/de-de.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/privacy\/explanation<\/a>.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Na medida em que os dados pessoais s\u00e3o recolhidos no nosso s\u00edtio Web com a ajuda da ferramenta aqui descrita e transmitidos ao Facebook, n\u00f3s e a Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlanda, somos conjuntamente respons\u00e1veis por este processamento de dados (Art. 26.\u00ba do RGPD). A responsabilidade conjunta limita-se exclusivamente \u00e0 recolha dos dados e \u00e0 sua transmiss\u00e3o ao Facebook. O processamento efectuado pelo Facebook ap\u00f3s a transmiss\u00e3o n\u00e3o faz parte da responsabilidade conjunta. As obriga\u00e7\u00f5es que nos incumbem em conjunto foram definidas num acordo sobre o processamento conjunto. Pode encontrar o texto do acordo em <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. De acordo com este acordo, somos respons\u00e1veis por fornecer as informa\u00e7\u00f5es de prote\u00e7\u00e3o de dados ao utilizar a ferramenta do Facebook e pela implementa\u00e7\u00e3o segura da ferramenta no nosso s\u00edtio Web, de acordo com a lei de prote\u00e7\u00e3o de dados. O Facebook \u00e9 respons\u00e1vel pela seguran\u00e7a dos dados dos produtos do Facebook. Pode fazer valer os direitos do titular dos dados (por exemplo, pedidos de informa\u00e7\u00e3o) relativamente aos dados processados pelo Facebook diretamente junto do Facebook. Se fizer valer os seus direitos de titular de dados junto de n\u00f3s, somos obrigados a transmiti-los ao Facebook.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a> e <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/policy.php<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>X (anteriormente Twitter)<\/h3>\n<p>As fun\u00e7\u00f5es do servi\u00e7o X (anteriormente Twitter) est\u00e3o integradas neste s\u00edtio Web. Estas fun\u00e7\u00f5es s\u00e3o oferecidas pela empresa-m\u00e3e X Corp, 1355 Market Street, Suite 900, S\u00e3o Francisco, CA 94103, EUA. A Twitter International Unlimited Company, One Cumberland Place, Fenian Street, Dublin 2, D02 AX07, Irlanda, \u00e9 respons\u00e1vel pelo processamento de dados de pessoas que vivem fora dos EUA.<\/p>\n<p>Quando o elemento das redes sociais est\u00e1 ativo, \u00e9 estabelecida uma liga\u00e7\u00e3o direta entre o seu dispositivo final e o servidor X. O X (antigo Twitter) recebe assim informa\u00e7\u00f5es sobre a sua visita a este s\u00edtio Web. Ao utilizar o X (antigo Twitter) e a fun\u00e7\u00e3o \"Re-Tweet\" ou \"Repost\", os s\u00edtios Web que visita s\u00e3o ligados \u00e0 sua conta X (antigo Twitter) e dados a conhecer a outros utilizadores. Gostar\u00edamos de salientar que, enquanto fornecedor das p\u00e1ginas, n\u00e3o temos conhecimento do conte\u00fado dos dados transmitidos ou da sua utiliza\u00e7\u00e3o pelo X (anteriormente Twitter). Mais informa\u00e7\u00f5es sobre este assunto podem ser encontradas na pol\u00edtica de privacidade do X (antigo Twitter) em <a href=\"https:\/\/x.com\/de\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/x.com\/de\/privacy<\/a>.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/gdpr.x.com\/en\/controller-to-controller-transfers.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/gdpr.x.com\/en\/controller-to-controller-transfers.html<\/a>.<\/p>\n<p>Pode alterar as suas defini\u00e7\u00f5es de privacidade para o X (antigo Twitter) nas defini\u00e7\u00f5es da conta em <a href=\"https:\/\/x.com\/settings\/account\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/x.com\/settings\/account<\/a> mudan\u00e7a.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/2710\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/2710<\/a>.<\/p>\n<h3>Instagram<\/h3>\n<p>As fun\u00e7\u00f5es do servi\u00e7o Instagram est\u00e3o integradas neste s\u00edtio Web. Estas fun\u00e7\u00f5es s\u00e3o oferecidas pela Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irlanda.<\/p>\n<p>Quando o elemento de rede social est\u00e1 ativo, \u00e9 estabelecida uma liga\u00e7\u00e3o direta entre o seu dispositivo e o servidor do Instagram. O Instagram recebe assim informa\u00e7\u00f5es sobre a sua visita a este s\u00edtio Web.<\/p>\n<p>Se tiver sess\u00e3o iniciada na sua conta Instagram, pode associar o conte\u00fado deste s\u00edtio Web ao seu perfil Instagram clicando no bot\u00e3o Instagram. Isto permite ao Instagram associar a sua visita a este s\u00edtio Web \u00e0 sua conta de utilizador. Gostar\u00edamos de salientar que, enquanto fornecedor das p\u00e1ginas, n\u00e3o temos conhecimento do conte\u00fado dos dados transmitidos ou da sua utiliza\u00e7\u00e3o pelo Instagram.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Na medida em que os dados pessoais s\u00e3o recolhidos no nosso s\u00edtio Web atrav\u00e9s da ferramenta aqui descrita e transmitidos ao Facebook ou ao Instagram, n\u00f3s e a Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlanda, somos solidariamente respons\u00e1veis por este tratamento de dados (art. 26.\u00ba do RGPD). A responsabilidade conjunta limita-se exclusivamente \u00e0 recolha dos dados e \u00e0 sua transmiss\u00e3o ao Facebook ou ao Instagram. O tratamento efectuado pelo Facebook ou pelo Instagram ap\u00f3s a transmiss\u00e3o n\u00e3o faz parte da responsabilidade conjunta. As obriga\u00e7\u00f5es conjuntas que nos incumbem foram definidas num acordo de processamento conjunto. Pode encontrar o texto do acordo em <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. Nos termos deste acordo, somos respons\u00e1veis por fornecer as informa\u00e7\u00f5es de prote\u00e7\u00e3o de dados ao utilizar a ferramenta do Facebook ou do Instagram e pela implementa\u00e7\u00e3o segura da ferramenta no nosso s\u00edtio Web, em conformidade com a lei de prote\u00e7\u00e3o de dados. O Facebook \u00e9 respons\u00e1vel pela seguran\u00e7a dos dados dos produtos do Facebook e do Instagram. Pode fazer valer os direitos dos titulares dos dados (por exemplo, pedidos de informa\u00e7\u00e3o) relativamente aos dados processados pelo Facebook ou pelo Instagram diretamente junto do Facebook. Se fizer valer os seus direitos de titular de dados junto de n\u00f3s, somos obrigados a transmiti-los ao Facebook.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacycenter.instagram.com\/policy\/<\/a> e <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre este assunto, consultar a pol\u00edtica de privacidade do Instagram: <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacycenter.instagram.com\/policy\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>Tumblr<\/h3>\n<p>Este s\u00edtio Web utiliza bot\u00f5es e outros elementos do servi\u00e7o Tumblr. O fornecedor \u00e9 a Tumblr, Inc, 35 East 21st St, 10th Floor, Nova Iorque, NY 10010, EUA.<\/p>\n<p>Quando o elemento de redes sociais est\u00e1 ativo, \u00e9 estabelecida uma liga\u00e7\u00e3o direta entre o seu dispositivo e o servidor do Tumblr. O Tumblr recebe assim informa\u00e7\u00f5es sobre a sua visita a este s\u00edtio Web.<\/p>\n<p>Os bot\u00f5es do Tumblr permitem-lhe partilhar um post ou uma p\u00e1gina no Tumblr ou seguir o fornecedor no Tumblr. Quando visita um dos nossos s\u00edtios Web com um bot\u00e3o do Tumblr, o navegador estabelece uma liga\u00e7\u00e3o direta aos servidores do Tumblr. N\u00e3o temos qualquer influ\u00eancia sobre o \u00e2mbito dos dados que o Tumblr recolhe e transmite com a ajuda deste plugin. De acordo com o estado atual, s\u00e3o transmitidos o endere\u00e7o IP do utilizador e o URL do respetivo s\u00edtio Web.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre este assunto, consultar a pol\u00edtica de privacidade do Tumblr em: <a href=\"https:\/\/www.tumblr.com\/privacy\/de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.tumblr.com\/privacy\/de<\/a>.<\/p>\n<h3>LinkedIn<\/h3>\n<p>Este s\u00edtio Web utiliza elementos da rede LinkedIn. O fornecedor \u00e9 a LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2, Irlanda.<\/p>\n<p>Sempre que aceder a uma p\u00e1gina deste s\u00edtio Web que contenha elementos do LinkedIn, \u00e9 estabelecida uma liga\u00e7\u00e3o aos servidores do LinkedIn. O LinkedIn \u00e9 informado de que o utilizador visitou este s\u00edtio Web atrav\u00e9s do seu endere\u00e7o IP. Se clicar no bot\u00e3o \"Recomendar\" do LinkedIn e tiver sess\u00e3o iniciada na sua conta LinkedIn, o LinkedIn pode associar a sua visita a este s\u00edtio Web a si e \u00e0 sua conta de utilizador. Gostar\u00edamos de salientar que, enquanto fornecedor das p\u00e1ginas, n\u00e3o temos conhecimento do conte\u00fado dos dados transmitidos ou da sua utiliza\u00e7\u00e3o pelo LinkedIn.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.linkedin.com\/help\/linkedin\/answer\/a1343190\/datenubertragung-aus-der-eu-dem-ewr-und-der-schweiz?lang=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/help\/linkedin\/answer\/a1343190\/datenubertragung-aus-der-eu-dem-ewr-und-der-schweiz?lang=de<\/a><\/p>\n<p>Para mais informa\u00e7\u00f5es sobre este assunto, consultar a pol\u00edtica de privacidade do LinkedIn em: <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5448\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5448<\/a>.<\/p>\n<h3>Pinterest<\/h3>\n<p>Neste s\u00edtio Web, utilizamos elementos da rede social Pinterest, que \u00e9 gerida pela Pinterest Europe Ltd, Palmerston House, 2nd Floor, Fenian Street, Dublin 2, Irlanda.<\/p>\n<p>Quando acede a uma p\u00e1gina que cont\u00e9m um elemento deste tipo, o seu navegador estabelece uma liga\u00e7\u00e3o direta aos servidores do Pinterest. Este elemento de rede social transmite dados de registo para o servidor do Pinterest nos EUA. Estes dados de registo podem conter o seu endere\u00e7o IP, o endere\u00e7o dos s\u00edtios Web visitados que tamb\u00e9m cont\u00eam fun\u00e7\u00f5es do Pinterest, o tipo e as defini\u00e7\u00f5es do navegador, a data e a hora do pedido, a sua utiliza\u00e7\u00e3o do Pinterest e dos cookies.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre a finalidade, o \u00e2mbito e o posterior tratamento e utiliza\u00e7\u00e3o dos dados pelo Pinterest, bem como sobre os seus direitos e op\u00e7\u00f5es para proteger a sua privacidade a este respeito, consulte a pol\u00edtica de privacidade do Pinterest: <a href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.<\/p>\n<h2>6. ferramentas de an\u00e1lise e publicidade<\/h2>\n<h3>Gestor de tags do Google<\/h3>\n<p>Utilizamos o Google Tag Manager. O fornecedor \u00e9 a Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>O Google Tag Manager \u00e9 uma ferramenta que nos permite integrar ferramentas de rastreio ou estat\u00edsticas e outras tecnologias no nosso s\u00edtio Web. O Google Tag Manager em si n\u00e3o cria nenhum perfil de utilizador, n\u00e3o armazena nenhum cookie e n\u00e3o efectua nenhuma an\u00e1lise independente. Apenas \u00e9 utilizado para gerir e apresentar as ferramentas integradas atrav\u00e9s do mesmo. No entanto, o Google Tag Manager regista o seu endere\u00e7o IP, que tamb\u00e9m pode ser transmitido \u00e0 empresa-m\u00e3e da Google nos Estados Unidos.<\/p>\n<p>O Google Tag Manager \u00e9 utilizado com base no Art. 6, par\u00e1grafo 1 lit. f do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo na integra\u00e7\u00e3o e gest\u00e3o r\u00e1pidas e descomplicadas de v\u00e1rias ferramentas no seu s\u00edtio Web. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo terminal do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google Analytics<\/h3>\n<p>Este s\u00edtio Web utiliza fun\u00e7\u00f5es do servi\u00e7o de an\u00e1lise da Web Google Analytics. O fornecedor \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>O Google Analytics permite ao operador do s\u00edtio Web analisar o comportamento dos visitantes do s\u00edtio Web. O operador do s\u00edtio Web recebe v\u00e1rios dados de utiliza\u00e7\u00e3o, tais como visualiza\u00e7\u00f5es de p\u00e1ginas, dura\u00e7\u00e3o da visita, sistemas operativos utilizados e origem do utilizador. Estes dados s\u00e3o resumidos num ID de utilizador e atribu\u00eddos ao respetivo dispositivo final do visitante do s\u00edtio Web.<\/p>\n<p>Tamb\u00e9m podemos utilizar o Google Analytics para registar os movimentos e cliques do rato e do scroll, entre outros. O Google Analytics tamb\u00e9m utiliza v\u00e1rias abordagens de modela\u00e7\u00e3o para complementar os registos de dados gravados e utiliza tecnologias de aprendizagem autom\u00e1tica para a an\u00e1lise de dados.<\/p>\n<p>O Google Analytics utiliza tecnologias que permitem o reconhecimento do utilizador para efeitos de an\u00e1lise do seu comportamento (por exemplo, cookies ou impress\u00f5es digitais do dispositivo). As informa\u00e7\u00f5es recolhidas pela Google sobre a utiliza\u00e7\u00e3o deste s\u00edtio Web s\u00e3o geralmente transmitidas para um servidor da Google nos EUA e a\u00ed armazenadas.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h4>Anonimiza\u00e7\u00e3o do IP<\/h4>\n<p>A anonimiza\u00e7\u00e3o do IP do Google Analytics est\u00e1 activada. Como resultado, o seu endere\u00e7o IP ser\u00e1 truncado pela Google nos estados membros da Uni\u00e3o Europeia ou noutros estados signat\u00e1rios do Acordo sobre o Espa\u00e7o Econ\u00f3mico Europeu antes de ser transmitido para os EUA. S\u00f3 em casos excepcionais \u00e9 que o endere\u00e7o IP completo \u00e9 transmitido para um servidor da Google nos EUA e a\u00ed truncado. Em nome do operador deste s\u00edtio Web, a Google utilizar\u00e1 estas informa\u00e7\u00f5es para analisar a sua utiliza\u00e7\u00e3o do s\u00edtio Web, para compilar relat\u00f3rios sobre a atividade do s\u00edtio Web e para fornecer ao operador do s\u00edtio Web outros servi\u00e7os relacionados com a atividade do s\u00edtio Web e a utiliza\u00e7\u00e3o da Internet. O endere\u00e7o IP transmitido pelo seu browser como parte do Google Analytics n\u00e3o ser\u00e1 fundido com outros dados da Google.<\/p>\n<h4>plugin do navegador<\/h4>\n<p>Pode impedir a recolha e o tratamento dos seus dados pela Google descarregando e instalando o plug-in do navegador dispon\u00edvel na seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n<p>Pode encontrar mais informa\u00e7\u00f5es sobre a forma como o Google Analytics trata os dados do utilizador na pol\u00edtica de privacidade da Google: <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>.<\/p>\n<h4>Sinais do Google<\/h4>\n<p>Utilizamos sinais do Google. Quando visita o nosso s\u00edtio Web, o Google Analytics regista a sua localiza\u00e7\u00e3o, hist\u00f3rico de pesquisa, hist\u00f3rico do YouTube e dados demogr\u00e1ficos (dados do visitante), entre outros. Estes dados podem ser utilizados para publicidade personalizada com a ajuda do Google Signal. Se o utilizador tiver uma conta Google, os dados do visitante do Google Signal s\u00e3o associados \u00e0 sua conta Google e utilizados para mensagens publicit\u00e1rias personalizadas. Os dados tamb\u00e9m s\u00e3o utilizados para compilar estat\u00edsticas an\u00f3nimas sobre o comportamento dos nossos utilizadores.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um contrato de processamento de encomendas com a Google e cumprimos integralmente os requisitos rigorosos das autoridades alem\u00e3s de prote\u00e7\u00e3o de dados quando utilizamos o Google Analytics.<\/p>\n<h4>Medi\u00e7\u00e3o de com\u00e9rcio eletr\u00f3nico do Google Analytics<\/h4>\n<p>Este s\u00edtio Web utiliza a fun\u00e7\u00e3o de \"medi\u00e7\u00e3o do com\u00e9rcio eletr\u00f3nico\" do Google Analytics. Com a ajuda da medi\u00e7\u00e3o do com\u00e9rcio eletr\u00f3nico, o operador do s\u00edtio Web pode analisar o comportamento de compra dos visitantes do s\u00edtio Web para melhorar as suas campanhas de marketing em linha. S\u00e3o registadas informa\u00e7\u00f5es como as encomendas efectuadas, os valores m\u00e9dios das encomendas, os custos de envio e o tempo decorrido entre a visualiza\u00e7\u00e3o e a compra de um produto. Estes dados podem ser resumidos pela Google num ID de transa\u00e7\u00e3o que \u00e9 atribu\u00eddo ao respetivo utilizador ou ao seu dispositivo.<\/p>\n<h3>Publicidade da Microsoft<\/h3>\n<p>O operador do s\u00edtio Web utiliza a Microsoft Advertising. O Microsoft Advertising \u00e9 um programa de publicidade em linha da Microsoft Corporation, One Microsoft Way, Redmond, WA 98052-6399, EUA.<\/p>\n<p>O Microsoft Advertising permite-nos apresentar an\u00fancios no motor de busca Bing ou em s\u00edtios Web de terceiros quando o utilizador introduz determinados termos de pesquisa no Bing (segmenta\u00e7\u00e3o por palavras-chave). Al\u00e9m disso, podem ser apresentados an\u00fancios direcionados com base nos dados do utilizador dispon\u00edveis na Microsoft (por exemplo, dados de localiza\u00e7\u00e3o e interesses) (direcionamento para grupos-alvo). Enquanto operador do s\u00edtio Web, podemos avaliar estes dados quantitativamente, analisando, por exemplo, quais os termos de pesquisa que conduziram \u00e0 apresenta\u00e7\u00e3o dos nossos an\u00fancios e quantos an\u00fancios conduziram aos cliques correspondentes.<\/p>\n<p>Utilizamos o rastreio universal de eventos (UET) da Microsoft Advertising neste s\u00edtio Web. Os dados pseudonimizados s\u00e3o recolhidos para controlar as ac\u00e7\u00f5es que o utilizador realiza nos nossos s\u00edtios Web depois de ter clicado num an\u00fancio da Microsoft Advertising. A UET recolhe o seu endere\u00e7o IP (anonimizado), identificadores do dispositivo, informa\u00e7\u00f5es sobre as defini\u00e7\u00f5es do dispositivo e do browser, Microsoft Click ID (armazenado num cookie), o tempo passado no Web site, as \u00e1reas do Web site a que acedeu, o an\u00fancio que o trouxe ao Web site e a palavra-chave em que clicou.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/learn.microsoft.com\/de-de\/compliance\/regulatory\/offering-eu-model-clauses\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/learn.microsoft.com\/de-de\/compliance\/regulatory\/offering-eu-model-clauses<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/6474\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/6474<\/a>.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h3>Matomo<\/h3>\n<p>Este s\u00edtio Web utiliza o servi\u00e7o de an\u00e1lise Web de fonte aberta Matomo.<\/p>\n<p>Com a ajuda do Matomo, podemos recolher e analisar dados sobre a utiliza\u00e7\u00e3o do nosso s\u00edtio Web pelos visitantes do mesmo. Isto permite-nos saber, entre outras coisas, quando \u00e9 que as p\u00e1ginas foram acedidas e a partir de que regi\u00e3o. Tamb\u00e9m registamos v\u00e1rios ficheiros de registo (por exemplo, endere\u00e7o IP, referenciador, navegador e sistema operativo utilizados) e podemos medir se os visitantes do nosso s\u00edtio Web realizam determinadas ac\u00e7\u00f5es (por exemplo, cliques, compras, etc.).<\/p>\n<p>Esta ferramenta de an\u00e1lise \u00e9 utilizada com base no art. 6, n.\u00ba 1, al\u00ednea f) do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo em analisar o comportamento dos utilizadores para otimizar o seu s\u00edtio Web e a sua publicidade. Se tiver sido solicitado um consentimento correspondente, o tratamento \u00e9 efectuado exclusivamente com base no art. 6, n.\u00ba 1, al\u00ednea a) do RGPD e no \u00a7 25, n.\u00ba 1 da TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo terminal do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o da TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<h4>Anonimiza\u00e7\u00e3o do IP<\/h4>\n<p>Utilizamos a anonimiza\u00e7\u00e3o do IP para a an\u00e1lise com o Matomo. Isto significa que o seu endere\u00e7o IP \u00e9 encurtado antes de ser analisado, de modo a que j\u00e1 n\u00e3o possa ser claramente atribu\u00eddo ao utilizador.<\/p>\n<h4>An\u00e1lise sem cozinha<\/h4>\n<p>Configur\u00e1mos o Matomo de modo a que este n\u00e3o armazene quaisquer cookies no seu browser.<\/p>\n<h4>Hospedagem<\/h4>\n<p>Alojamos o Matomo com o seguinte fornecedor terceiro:<\/p>\n<p>webhoster.de AG<br \/>\nZum Haunert 22<br \/>\n59519 M\u00f6hnesee<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h3>An\u00fancios do Google<\/h3>\n<p>O operador do s\u00edtio Web utiliza o Google Ads. O Google Ads \u00e9 um programa de publicidade em linha da Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>O Google Ads permite-nos apresentar an\u00fancios no motor de busca Google ou em s\u00edtios Web de terceiros quando o utilizador introduz determinados termos de pesquisa no Google (segmenta\u00e7\u00e3o por palavras-chave). Al\u00e9m disso, podem ser apresentados an\u00fancios direcionados com base nos dados do utilizador dispon\u00edveis no Google (por exemplo, dados de localiza\u00e7\u00e3o e interesses) (direcionamento para grupos-alvo). Enquanto operador do s\u00edtio Web, podemos avaliar estes dados quantitativamente, analisando, por exemplo, quais os termos de pesquisa que levaram \u00e0 apresenta\u00e7\u00e3o dos nossos an\u00fancios e quantos an\u00fancios levaram aos cliques correspondentes.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/policies.google.com\/privacy\/frameworks\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy\/frameworks<\/a> e <a href=\"https:\/\/business.safety.google\/controllerterms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/business.safety.google\/controllerterms\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google AdSense (n\u00e3o personalizado)<\/h3>\n<p>Este s\u00edtio Web utiliza o Google AdSense, um servi\u00e7o de integra\u00e7\u00e3o de an\u00fancios. O fornecedor \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>Utilizamos o Google AdSense no modo \"n\u00e3o personalizado\". Ao contr\u00e1rio do modo personalizado, os an\u00fancios n\u00e3o se baseiam no seu comportamento de utilizador anterior e n\u00e3o \u00e9 criado qualquer perfil de utilizador para si. Em vez disso, \u00e9 utilizada a chamada \"informa\u00e7\u00e3o contextual\" para selecionar os an\u00fancios. Os an\u00fancios selecionados baseiam-se ent\u00e3o, por exemplo, na sua localiza\u00e7\u00e3o, no conte\u00fado do s\u00edtio Web em que se encontra ou nos seus termos de pesquisa actuais. Pode obter mais informa\u00e7\u00f5es sobre as diferen\u00e7as entre a segmenta\u00e7\u00e3o personalizada e n\u00e3o personalizada com o Google AdSense aqui: <a href=\"https:\/\/support.google.com\/adsense\/answer\/9007336\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/adsense\/answer\/9007336<\/a>.<\/p>\n<p>Note-se que os cookies ou tecnologias de reconhecimento compar\u00e1veis (por exemplo, impress\u00e3o digital do dispositivo) tamb\u00e9m podem ser utilizados quando se utiliza o Google Adsense em modo n\u00e3o personalizado. De acordo com a Google, estas tecnologias s\u00e3o utilizadas para combater a fraude e o abuso.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<p>Pode personalizar as suas defini\u00e7\u00f5es de publicidade na sua conta de utilizador. Para o fazer, clique na seguinte liga\u00e7\u00e3o e inicie sess\u00e3o: <a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre as tecnologias de publicidade da Google, clique aqui: <a href=\"https:\/\/policies.google.com\/technologies\/ads\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/technologies\/ads<\/a> e <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Remarketing do Google Ads<\/h3>\n<p>Este s\u00edtio Web utiliza as fun\u00e7\u00f5es do Google Ads Remarketing. O fornecedor \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>Com o Google Ads Remarketing, podemos atribuir as pessoas que interagem com a nossa oferta online a grupos-alvo espec\u00edficos para lhes mostrar posteriormente publicidade baseada em interesses na rede de publicidade da Google (remarketing ou retargeting).<\/p>\n<p>Al\u00e9m disso, os grupos-alvo de publicidade criados com o Remarketing do Google Ads podem ser ligados \u00e0s fun\u00e7\u00f5es de dispositivos cruzados do Google. Desta forma, as mensagens publicit\u00e1rias personalizadas e baseadas em interesses que foram adaptadas ao utilizador em fun\u00e7\u00e3o da sua utiliza\u00e7\u00e3o anterior e do seu comportamento de navega\u00e7\u00e3o num dispositivo final (por exemplo, telem\u00f3vel) tamb\u00e9m podem ser apresentadas noutro dispositivo final (por exemplo, tablet ou PC).<\/p>\n<p>Se tiver uma conta Google, pode opor-se \u00e0 publicidade personalizada clicando na seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/adssettings.google.com\/anonymous?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/adssettings.google.com\/anonymous?hl=de<\/a>.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para mais informa\u00e7\u00f5es e disposi\u00e7\u00f5es em mat\u00e9ria de prote\u00e7\u00e3o de dados, consultar a pol\u00edtica de privacidade da Google em: <a href=\"https:\/\/policies.google.com\/technologies\/ads?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/technologies\/ads?hl=de<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h4>Forma\u00e7\u00e3o de grupos-alvo com correspond\u00eancia de clientes<\/h4>\n<p>Entre outras coisas, utilizamos a correspond\u00eancia de clientes do Google Ads Remarketing para criar grupos-alvo. Neste caso, transferimos determinados dados de clientes (por exemplo, endere\u00e7os de correio eletr\u00f3nico) das nossas listas de clientes para a Google. Se os clientes em quest\u00e3o forem utilizadores do Google e estiverem ligados \u00e0 sua conta Google, s\u00e3o-lhes mostradas mensagens publicit\u00e1rias adequadas na rede Google (por exemplo, no YouTube, no Gmail ou no motor de busca).<\/p>\n<h3>Controlo de convers\u00f5es do Google<\/h3>\n<p>Este s\u00edtio Web utiliza o Google Conversion Tracking. O fornecedor \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>Com a ajuda do acompanhamento de convers\u00f5es do Google, o Google e n\u00f3s podemos reconhecer se o utilizador realizou determinadas ac\u00e7\u00f5es. Por exemplo, podemos analisar que bot\u00f5es do nosso s\u00edtio Web foram clicados com que frequ\u00eancia e que produtos foram vistos ou comprados com particular frequ\u00eancia. Esta informa\u00e7\u00e3o \u00e9 utilizada para criar estat\u00edsticas de convers\u00e3o. Descobrimos o n\u00famero total de utilizadores que clicaram nos nossos an\u00fancios e quais as ac\u00e7\u00f5es que realizaram. N\u00e3o recebemos qualquer informa\u00e7\u00e3o que nos permita identificar pessoalmente o utilizador. A pr\u00f3pria Google utiliza cookies ou tecnologias de reconhecimento compar\u00e1veis para efeitos de identifica\u00e7\u00e3o.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Pode encontrar mais informa\u00e7\u00f5es sobre o Controlo de convers\u00f5es do Google na pol\u00edtica de privacidade do Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Meta Pixel (anteriormente Facebook Pixel)<\/h3>\n<p>Este s\u00edtio Web utiliza o pixel de a\u00e7\u00e3o do visitante da Meta para medir as convers\u00f5es. O fornecedor deste servi\u00e7o \u00e9 a Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irlanda. No entanto, segundo a Meta, os dados recolhidos tamb\u00e9m s\u00e3o transferidos para os EUA e outros pa\u00edses terceiros.<\/p>\n<p>Isto permite seguir o comportamento dos visitantes do s\u00edtio depois de terem sido redireccionados para o s\u00edtio Web do fornecedor ao clicarem num meta-an\u00fancio. Isto permite avaliar a efic\u00e1cia dos meta-an\u00fancios para fins estat\u00edsticos e de pesquisa de mercado e otimizar as futuras medidas de publicidade.<\/p>\n<p>Os dados recolhidos s\u00e3o an\u00f3nimos para n\u00f3s, enquanto operadores deste s\u00edtio Web; n\u00e3o podemos tirar quaisquer conclus\u00f5es sobre a identidade dos utilizadores. No entanto, os dados s\u00e3o armazenados e processados pela Meta para que seja poss\u00edvel uma liga\u00e7\u00e3o ao respetivo perfil de utilizador no Facebook ou Instagram e a Meta possa utilizar os dados para os seus pr\u00f3prios fins publicit\u00e1rios, de acordo com a Pol\u00edtica de Utiliza\u00e7\u00e3o de Dados da Meta (<a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a>) pode ser utilizado. Isto permite \u00e0 Meta colocar an\u00fancios nas p\u00e1ginas do Facebook ou Instagram e noutros canais de publicidade. Esta utiliza\u00e7\u00e3o dos dados n\u00e3o pode ser influenciada por n\u00f3s, enquanto operadores do s\u00edtio Web.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Na medida em que os dados pessoais s\u00e3o recolhidos no nosso s\u00edtio Web com a ajuda da ferramenta aqui descrita e transmitidos \u00e0 Meta, n\u00f3s e a Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlanda, somos conjuntamente respons\u00e1veis por este processamento de dados (art. 26.\u00ba do RGPD). A responsabilidade conjunta limita-se exclusivamente \u00e0 recolha dos dados e \u00e0 sua transmiss\u00e3o \u00e0 Meta. O tratamento efectuado pela Meta ap\u00f3s a transmiss\u00e3o n\u00e3o faz parte da responsabilidade conjunta. As obriga\u00e7\u00f5es que nos incumbem em conjunto foram definidas num acordo de processamento conjunto. O texto do acordo pode ser consultado em <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. De acordo com este acordo, somos respons\u00e1veis por fornecer as informa\u00e7\u00f5es de prote\u00e7\u00e3o de dados ao utilizar a ferramenta Meta e pela implementa\u00e7\u00e3o segura da ferramenta no nosso site, de acordo com a lei de prote\u00e7\u00e3o de dados. A Meta \u00e9 respons\u00e1vel pela seguran\u00e7a dos dados dos produtos Meta. O utilizador pode fazer valer os seus direitos enquanto titular dos dados (por exemplo, pedidos de informa\u00e7\u00e3o) relativamente aos dados processados pelo Facebook ou pelo Instagram diretamente junto da Meta. Se fizer valer os seus direitos de titular de dados junto de n\u00f3s, somos obrigados a transmiti-los \u00e0 Meta.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> e <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Encontrar\u00e1 mais informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o da sua privacidade nas informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o de dados da Meta: <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<p>Tamb\u00e9m pode utilizar a fun\u00e7\u00e3o de remarketing \"P\u00fablicos personalizados\" na sec\u00e7\u00e3o de defini\u00e7\u00f5es de an\u00fancios em <a href=\"https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen<\/a> desactiv\u00e1-lo. Para o fazer, tem de ter sess\u00e3o iniciada no Facebook.<\/p>\n<p>Se n\u00e3o tiver uma conta no Facebook ou no Instagram, pode desativar a publicidade baseada na utiliza\u00e7\u00e3o da Meta no s\u00edtio Web da European Interactive Digital Advertising Alliance: <a href=\"http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a>.<\/p>\n<h3>TikTok Pixel<\/h3>\n<p>Integr\u00e1mos o pixel TikTok neste s\u00edtio Web. O fornecedor \u00e9 a TikTok Technology Limited, 10 Earlsfort Terrace, Dublin, D02 T380, Irlanda (a seguir designada por TikTok).<\/p>\n<p>Com a ajuda do TikTok Pixel, podemos exibir publicidade baseada em interesses no TikTok para os visitantes do site que visualizaram as nossas ofertas (TikTok Ads). Ao mesmo tempo, podemos utilizar o TikTok Pixel para determinar a efic\u00e1cia da nossa publicidade no TikTok. Isto permite que a efic\u00e1cia dos an\u00fancios TikTok seja avaliada para fins estat\u00edsticos e de pesquisa de mercado e optimizada para futuras medidas de publicidade. S\u00e3o processados v\u00e1rios dados de utiliza\u00e7\u00e3o, tais como endere\u00e7o IP, visualiza\u00e7\u00f5es de p\u00e1ginas, dura\u00e7\u00e3o da visita, sistemas operativos utilizados e origem do utilizador, informa\u00e7\u00f5es sobre o an\u00fancio em que uma pessoa clicou no TikTok ou um evento que foi desencadeado (carimbo de data\/hora). Estes dados s\u00e3o resumidos num ID de utilizador e atribu\u00eddos ao respetivo dispositivo final do visitante do s\u00edtio Web.<\/p>\n<p>A utiliza\u00e7\u00e3o deste servi\u00e7o baseia-se no consentimento do utilizador, de acordo com o art. 6, n.\u00ba 1, al\u00ednea a), do RGPD e o \u00a7 25, n.\u00ba 1, do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para pa\u00edses terceiros baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.tiktok.com\/legal\/page\/eea\/privacy-policy\/de-DE\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.tiktok.com\/legal\/page\/eea\/privacy-policy\/de-DE<\/a> e <a href=\"https:\/\/ads.tiktok.com\/i18n\/official\/policy\/controller-to-controller\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/ads.tiktok.com\/i18n\/official\/policy\/controller-to-controller<\/a>.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h3>Etiqueta Pinterest<\/h3>\n<p>Integr\u00e1mos etiquetas do Pinterest neste s\u00edtio Web. O fornecedor \u00e9 a Pinterest Europe Ltd, Palmerston House, 2nd Floor, Fenian Street, Dublin 2, Irlanda.<\/p>\n<p>O Pinterest Tag \u00e9 utilizado para registar determinadas ac\u00e7\u00f5es que o utilizador realiza no nosso s\u00edtio Web. Os dados podem ent\u00e3o ser utilizados para lhe mostrar publicidade baseada em interesses no nosso s\u00edtio Web ou noutra p\u00e1gina da rede de publicidade Pinterest Tag.<\/p>\n<p>Para este efeito, a etiqueta do Pinterest regista, entre outras coisas, um ID de etiqueta, a sua localiza\u00e7\u00e3o e o URL de refer\u00eancia. Al\u00e9m disso, podem ser registados dados espec\u00edficos da campanha, como o valor da encomenda, a quantidade da encomenda, o n\u00famero da encomenda, a categoria dos artigos comprados e as visualiza\u00e7\u00f5es de v\u00eddeo.<\/p>\n<p>O Pinterest Tag utiliza tecnologias que permitem o reconhecimento do utilizador em v\u00e1rias p\u00e1ginas para analisar o seu comportamento (por exemplo, cookies ou impress\u00f5es digitais do dispositivo).<\/p>\n<p>Se o consentimento tiver sido obtido, o servi\u00e7o acima mencionado \u00e9 utilizado exclusivamente com base no Art. 6, par\u00e1grafo 1 lit. a RGPD e \u00a7 25 TDDDG. O consentimento pode ser revogado em qualquer altura. Se o consentimento n\u00e3o tiver sido obtido, este servi\u00e7o \u00e9 utilizado com base no Art. 6, n.\u00ba 1, al\u00ednea f) do RGPD; o operador do s\u00edtio Web tem um interesse leg\u00edtimo nas medidas de marketing mais eficazes poss\u00edveis.<\/p>\n<p>O Pinterest \u00e9 uma empresa global, o que significa que os dados tamb\u00e9m podem ser transferidos para os EUA. De acordo com o Pinterest, esta transfer\u00eancia de dados baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.<\/p>\n<p>Pode encontrar mais informa\u00e7\u00f5es sobre o Pinterest Tag aqui: <a href=\"https:\/\/help.pinterest.com\/de\/business\/article\/track-conversions-with-pinterest-tag\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/help.pinterest.com\/de\/business\/article\/track-conversions-with-pinterest-tag<\/a>.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h2>7\u00aa Newsletter<\/h2>\n<h3>Dados do boletim informativo<\/h3>\n<p>Se pretender receber o boletim informativo oferecido no s\u00edtio Web, solicitamos o seu endere\u00e7o de correio eletr\u00f3nico, bem como informa\u00e7\u00f5es que nos permitam verificar se \u00e9 o propriet\u00e1rio do endere\u00e7o de correio eletr\u00f3nico fornecido e se concorda em receber o boletim informativo. N\u00e3o s\u00e3o recolhidos quaisquer outros dados, ou apenas numa base volunt\u00e1ria. Utilizamos estes dados exclusivamente para o envio das informa\u00e7\u00f5es solicitadas e n\u00e3o os transmitimos a terceiros.<\/p>\n<p>Os dados introduzidos no formul\u00e1rio de registo da newsletter s\u00e3o processados exclusivamente com base no seu consentimento (art. 6.\u00ba, n.\u00ba 1, al\u00ednea a) do RGPD). Pode revogar o seu consentimento para o armazenamento dos dados, o endere\u00e7o de correio eletr\u00f3nico e a sua utiliza\u00e7\u00e3o para o envio da newsletter em qualquer altura, por exemplo, atrav\u00e9s da liga\u00e7\u00e3o \"cancelar a subscri\u00e7\u00e3o\" na newsletter. A legalidade das opera\u00e7\u00f5es de processamento de dados j\u00e1 efectuadas n\u00e3o \u00e9 afetada pelo cancelamento.<\/p>\n<p>Os dados que nos fornece para efeitos de subscri\u00e7\u00e3o da newsletter ser\u00e3o armazenados por n\u00f3s ou pelo fornecedor do servi\u00e7o de newsletter at\u00e9 que anule a subscri\u00e7\u00e3o da newsletter e ser\u00e3o eliminados da lista de distribui\u00e7\u00e3o da newsletter depois de anular a subscri\u00e7\u00e3o da newsletter ou depois de a finalidade deixar de se aplicar. Reservamo-nos o direito de apagar ou bloquear endere\u00e7os de correio eletr\u00f3nico da nossa lista de distribui\u00e7\u00e3o de newsletters, se assim o entendermos, no \u00e2mbito do nosso interesse leg\u00edtimo, de acordo com o Art. 6, n.\u00ba 1, al\u00ednea f) do RGPD.<\/p>\n<p>Os dados armazenados por n\u00f3s para outros fins n\u00e3o s\u00e3o afectados por esta situa\u00e7\u00e3o.<\/p>\n<p>Depois de anular a subscri\u00e7\u00e3o da lista de distribui\u00e7\u00e3o de newsletters, o seu endere\u00e7o de correio eletr\u00f3nico pode ser guardado por n\u00f3s ou pelo fornecedor do servi\u00e7o de newsletters numa lista negra, se tal for necess\u00e1rio para evitar futuros envios. Os dados da lista negra ser\u00e3o utilizados apenas para este fim e n\u00e3o ser\u00e3o fundidos com outros dados. Isto serve tanto o seu interesse como o nosso interesse em cumprir os requisitos legais aquando do envio de newsletters (interesse leg\u00edtimo na ace\u00e7\u00e3o do Art. 6, par\u00e1grafo 1 lit. f do RGPD). O armazenamento na lista negra n\u00e3o \u00e9 limitado no tempo. <strong>O utilizador pode opor-se ao armazenamento se os seus interesses se sobrepuserem aos nossos interesses leg\u00edtimos.<\/strong><\/p>\n<h2>8. plugins e ferramentas<\/h2>\n<h3>YouTube com prote\u00e7\u00e3o de dados alargada<\/h3>\n<p>Este s\u00edtio Web incorpora v\u00eddeos do s\u00edtio Web do YouTube. O operador do s\u00edtio Web \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>Quando o utilizador visita um destes s\u00edtios Web em que o YouTube est\u00e1 integrado, \u00e9 estabelecida uma liga\u00e7\u00e3o aos servidores do YouTube. O servidor do YouTube \u00e9 informado sobre as nossas p\u00e1ginas que visitou. Se tiver sess\u00e3o iniciada na sua conta YouTube, permite que o YouTube atribua o seu comportamento de navega\u00e7\u00e3o diretamente ao seu perfil pessoal. Pode impedir que isso aconte\u00e7a, encerrando a sess\u00e3o na sua conta YouTube.<\/p>\n<p>Utilizamos o YouTube no modo de prote\u00e7\u00e3o de dados alargado. De acordo com o YouTube, os v\u00eddeos que s\u00e3o reproduzidos no modo de prote\u00e7\u00e3o de dados alargado n\u00e3o s\u00e3o utilizados para personalizar a navega\u00e7\u00e3o no YouTube. Os an\u00fancios que s\u00e3o reproduzidos no modo de prote\u00e7\u00e3o de dados alargado tamb\u00e9m n\u00e3o s\u00e3o personalizados. No modo de prote\u00e7\u00e3o de dados alargado n\u00e3o s\u00e3o definidos cookies. Em vez disso, s\u00e3o armazenados no browser do utilizador os chamados elementos de armazenamento local, que cont\u00eam dados pessoais semelhantes aos cookies e podem ser utilizados para reconhecer o utilizador. Mais informa\u00e7\u00f5es sobre o modo de prote\u00e7\u00e3o de dados alargado podem ser consultadas aqui: <a href=\"https:\/\/support.google.com\/youtube\/answer\/171780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/youtube\/answer\/171780<\/a>.<\/p>\n<p>Depois de ativar um v\u00eddeo do YouTube, podem ser desencadeadas outras opera\u00e7\u00f5es de processamento de dados sobre as quais n\u00e3o temos qualquer influ\u00eancia.<\/p>\n<p>A utiliza\u00e7\u00e3o do YouTube \u00e9 do interesse de uma apresenta\u00e7\u00e3o apelativa das nossas ofertas online. Isto constitui um interesse leg\u00edtimo na ace\u00e7\u00e3o do art. 6, par. 1 lit. f do RGPD. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo final do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o de dados no YouTube, consulte a sua pol\u00edtica de privacidade em: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Vimeo sem rastreio (Do-Not-Track)<\/h3>\n<p>Este s\u00edtio Web utiliza plugins do portal de v\u00eddeos Vimeo. O fornecedor \u00e9 a Vimeo Inc, 555 West 18th Street, Nova Iorque, Nova Iorque 10011, EUA.<\/p>\n<p>Quando visita uma das nossas p\u00e1ginas equipadas com v\u00eddeos do Vimeo, \u00e9 estabelecida uma liga\u00e7\u00e3o aos servidores do Vimeo. Isto indica ao servidor Vimeo qual das nossas p\u00e1ginas visitou. O Vimeo tamb\u00e9m obt\u00e9m o seu endere\u00e7o IP. No entanto, configur\u00e1mos o Vimeo de modo a que este n\u00e3o rastreie as suas actividades de utilizador e n\u00e3o defina quaisquer cookies.<\/p>\n<p>A utiliza\u00e7\u00e3o do Vimeo \u00e9 do interesse de uma apresenta\u00e7\u00e3o apelativa das nossas ofertas online. Isto constitui um interesse leg\u00edtimo na ace\u00e7\u00e3o do art. 6, par. 1 lit. f do RGPD. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no art. 6, par. 1 lit. a do RGPD; o consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia e, segundo a Vimeo, em \"interesses comerciais leg\u00edtimos\". Pode encontrar mais pormenores aqui: <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/vimeo.com\/privacy<\/a>.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre o tratamento dos dados dos utilizadores, consultar a pol\u00edtica de privacidade do Vimeo em: <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/vimeo.com\/privacy<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5711\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5711<\/a>.<\/p>\n<h3>Google Fonts (alojamento local)<\/h3>\n<p>Este s\u00edtio utiliza as chamadas Google Fonts, que s\u00e3o fornecidas pela Google, para a apresenta\u00e7\u00e3o normalizada de tipos de letra. As fontes do Google s\u00e3o instaladas localmente. N\u00e3o existe qualquer liga\u00e7\u00e3o aos servidores da Google.<\/p>\n<p>Pode encontrar mais informa\u00e7\u00f5es sobre o Google Fonts em <a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.google.com\/fonts\/faq<\/a> e na pol\u00edtica de privacidade da Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Google Maps<\/h3>\n<p>Este s\u00edtio utiliza o servi\u00e7o de mapas Google Maps. O fornecedor \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda. Com a ajuda deste servi\u00e7o, podemos integrar material cartogr\u00e1fico no nosso s\u00edtio Web.<\/p>\n<p>Para utilizar as fun\u00e7\u00f5es do Google Maps, \u00e9 necess\u00e1rio guardar o seu endere\u00e7o IP. Esta informa\u00e7\u00e3o \u00e9 normalmente transmitida para um servidor da Google nos EUA e a\u00ed armazenada. O fornecedor deste s\u00edtio n\u00e3o tem qualquer influ\u00eancia sobre esta transfer\u00eancia de dados. Se o Google Maps estiver ativado, a Google pode utilizar o Google Fonts com o objetivo de normalizar a apresenta\u00e7\u00e3o das fontes. Quando acede ao Google Maps, o seu browser carrega as fontes web necess\u00e1rias na cache do seu browser para que os textos e as fontes sejam apresentados corretamente.<\/p>\n<p>A utiliza\u00e7\u00e3o do Google Maps \u00e9 do interesse de uma apresenta\u00e7\u00e3o apelativa das nossas ofertas online e para facilitar a localiza\u00e7\u00e3o dos locais que indic\u00e1mos no s\u00edtio Web. Isto constitui um interesse leg\u00edtimo na ace\u00e7\u00e3o do art. 6, n.\u00ba 1, al\u00ednea f) do RGPD. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo terminal do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/<\/a> e <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/<\/a>.<\/p>\n<p>Pode encontrar mais informa\u00e7\u00f5es sobre o tratamento dos dados do utilizador na pol\u00edtica de privacidade da Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google reCAPTCHA<\/h3>\n<p>Utilizamos o \"Google reCAPTCHA\" (a seguir designado \"reCAPTCHA\") neste s\u00edtio Web. O fornecedor \u00e9 a Google Ireland Limited (\"Google\"), Gordon House, Barrow Street, Dublin 4, Irlanda.<\/p>\n<p>O objetivo do reCAPTCHA \u00e9 verificar se os dados s\u00e3o introduzidos neste s\u00edtio Web (por exemplo, num formul\u00e1rio de contacto) por um ser humano ou por um programa automatizado. Para o efeito, o reCAPTCHA analisa o comportamento do visitante do s\u00edtio Web com base em diversas carater\u00edsticas. Esta an\u00e1lise come\u00e7a automaticamente assim que o visitante do s\u00edtio Web entra no s\u00edtio Web. Para a an\u00e1lise, o reCAPTCHA avalia diversas informa\u00e7\u00f5es (por exemplo, o endere\u00e7o IP, o tempo de perman\u00eancia do visitante no s\u00edtio Web ou os movimentos do rato efectuados pelo utilizador). Os dados recolhidos durante a an\u00e1lise s\u00e3o transmitidos \u00e0 Google.<\/p>\n<p>As an\u00e1lises do reCAPTCHA s\u00e3o efectuadas completamente em segundo plano. Os visitantes do s\u00edtio Web n\u00e3o s\u00e3o informados de que est\u00e1 a ser efectuada uma an\u00e1lise.<\/p>\n<p>Os dados s\u00e3o armazenados e analisados com base no art. 6, n.\u00ba 1, al\u00ednea f), do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo em proteger o seu s\u00edtio Web de espionagem automatizada abusiva e de acesso n\u00e3o autorizado. <a href=\"https:\/\/webhosting.de\/pt\/srs-mit-postfix-unter-centos\/\">SPAM<\/a> para proteger a sua privacidade. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo terminal do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre o Google reCAPTCHA, consulte a Pol\u00edtica de Privacidade da Google e os Termos de Servi\u00e7o da Google nos seguintes links: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a> e <a href=\"https:\/\/policies.google.com\/terms?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/terms?hl=de<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Wordfence<\/h3>\n<p>Integr\u00e1mos o Wordfence neste s\u00edtio Web. O fornecedor \u00e9 a Defiant Inc, Defiant, Inc, 800 5th Ave Ste 4100, Seattle, WA 98104, EUA (a seguir designada por \"Wordfence\").<\/p>\n<p>O Wordfence serve para proteger o nosso s\u00edtio Web de acessos n\u00e3o desejados ou de ciberataques maliciosos. Para o efeito, o nosso s\u00edtio Web estabelece uma liga\u00e7\u00e3o permanente aos servidores do Wordfence para que este possa comparar as suas bases de dados com os acessos efectuados no nosso s\u00edtio Web e bloque\u00e1-los, se necess\u00e1rio.<\/p>\n<p>A utiliza\u00e7\u00e3o do Wordfence baseia-se no artigo 6.\u00ba, n.\u00ba 1, al\u00ednea f), do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo em proteger o seu s\u00edtio Web da forma mais eficaz poss\u00edvel contra ciberataques. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1, al\u00ednea a) do RGPD e no \u00a7 25, n.\u00ba 1 do TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo final do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/<\/a>.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h3>SoundCloud<\/h3>\n<p>Podem ser integrados neste s\u00edtio Web plug-ins da rede social SoundCloud (SoundCloud Limited, Berners House, 47-48 Berners Street, London W1T 3NF, Reino Unido). Pode reconhecer os plugins SoundCloud pelo log\u00f3tipo SoundCloud nas p\u00e1ginas relevantes.<\/p>\n<p>Quando visita este site, \u00e9 estabelecida uma liga\u00e7\u00e3o direta entre o seu navegador e o servidor do SoundCloud depois de o plug-in ter sido ativado. O SoundCloud recebe ent\u00e3o a informa\u00e7\u00e3o de que visitou este website com o seu endere\u00e7o IP. Se clicar no bot\u00e3o \"Gosto\" ou \"Partilhar\" enquanto estiver ligado \u00e0 sua conta de utilizador SoundCloud, pode ligar e\/ou partilhar o conte\u00fado deste website com o seu perfil SoundCloud. Isto permite ao SoundCloud associar a sua visita a este s\u00edtio Web \u00e0 sua conta de utilizador. Gostar\u00edamos de salientar que, como fornecedor das p\u00e1ginas, n\u00e3o temos conhecimento do conte\u00fado dos dados transmitidos ou da sua utiliza\u00e7\u00e3o pelo SoundCloud.<\/p>\n<p>Os dados s\u00e3o armazenados e analisados com base no Art. 6, par\u00e1grafo 1 lit. f do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo em maximizar a visibilidade nas redes sociais. Se tiver sido solicitado um consentimento correspondente, o tratamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo final do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>O Reino Unido \u00e9 considerado um pa\u00eds terceiro seguro ao abrigo da legisla\u00e7\u00e3o sobre prote\u00e7\u00e3o de dados. Isto significa que o Reino Unido tem um n\u00edvel de prote\u00e7\u00e3o de dados que corresponde ao n\u00edvel de prote\u00e7\u00e3o de dados na Uni\u00e3o Europeia.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre este assunto, consultar a pol\u00edtica de privacidade do SoundCloud em: <a href=\"https:\/\/soundcloud.com\/pages\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/soundcloud.com\/pages\/privacy<\/a>.<\/p>\n<p>Se n\u00e3o quiser que o SoundCloud associe a sua visita a este site \u00e0 sua conta de utilizador SoundCloud, termine sess\u00e3o na sua conta de utilizador SoundCloud antes de ativar o conte\u00fado do plug-in SoundCloud.<\/p>\n<h3>Spotify<\/h3>\n<p>As fun\u00e7\u00f5es do servi\u00e7o de m\u00fasica Spotify est\u00e3o integradas neste s\u00edtio Web. O fornecedor \u00e9 a Spotify AB, Birger Jarlsgatan 61, 113 56 Estocolmo, Su\u00e9cia. Pode reconhecer os plugins do Spotify pelo log\u00f3tipo verde neste s\u00edtio Web. Pode encontrar uma vis\u00e3o geral dos plugins do Spotify em <a href=\"https:\/\/developer.spotify.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developer.spotify.com<\/a>.<\/p>\n<p>Isto permite que seja estabelecida uma liga\u00e7\u00e3o direta entre o seu browser e o servidor Spotify atrav\u00e9s do plugin quando visita este s\u00edtio Web. O Spotify recebe a informa\u00e7\u00e3o de que visitou este s\u00edtio Web com o seu endere\u00e7o IP. Se clicar no bot\u00e3o Spotify enquanto estiver ligado \u00e0 sua conta Spotify, pode associar o conte\u00fado deste s\u00edtio Web ao seu perfil Spotify. Isto permite ao Spotify associar a sua visita a este s\u00edtio Web \u00e0 sua conta de utilizador.<\/p>\n<p>Gostar\u00edamos de salientar que, ao utilizar o Spotify, s\u00e3o utilizados cookies do Google Analytics para que os seus dados de utiliza\u00e7\u00e3o tamb\u00e9m possam ser transmitidos \u00e0 Google ao utilizar o Spotify. O Google Analytics \u00e9 uma ferramenta do Grupo Google, com sede nos EUA, para analisar o comportamento dos utilizadores. O Spotify \u00e9 o \u00fanico respons\u00e1vel por esta integra\u00e7\u00e3o. N\u00f3s, enquanto operadores do s\u00edtio Web, n\u00e3o temos qualquer influ\u00eancia sobre este processamento.<\/p>\n<p>Os dados s\u00e3o armazenados e analisados com base no Art. 6, par\u00e1grafo 1 lit. f do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo no design ac\u00fastico apelativo do seu s\u00edtio Web. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo terminal do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre este assunto, consulte a pol\u00edtica de privacidade do Spotify: <a href=\"https:\/\/www.spotify.com\/de\/legal\/privacy-policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.spotify.com\/de\/legal\/privacy-policy\/<\/a>.<\/p>\n<p>Se n\u00e3o quiser que o Spotify possa associar a sua visita a este s\u00edtio Web \u00e0 sua conta de utilizador do Spotify, termine sess\u00e3o na sua conta de utilizador do Spotify.<\/p>\n<h3>ChatGPT<\/h3>\n<p>Utilizamos o ChatGPT para a comunica\u00e7\u00e3o com os nossos clientes. O fornecedor \u00e9 a OpenAI, 3180 18th St, S\u00e3o Francisco, CA 94110, EUA, <a href=\"https:\/\/openai.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/openai.com<\/a>.<\/p>\n<p>Se iniciar uma conversa connosco atrav\u00e9s do nosso s\u00edtio Web e o ChatGPT estiver ativado, as suas entradas, incluindo os metadados, s\u00e3o transmitidas aos servidores do ChatGPT e a\u00ed processadas para gerar uma resposta adequada.<\/p>\n<p>Configur\u00e1mos o ChatGPT de modo a que os dados pessoais introduzidos n\u00e3o sejam utilizados para treinar o algoritmo do ChatGPT.<\/p>\n<p>A utiliza\u00e7\u00e3o do ChatGPT baseia-se no artigo 6.\u00ba, n.\u00ba 1, al\u00ednea f) do RGPD. O operador do s\u00edtio Web tem um interesse leg\u00edtimo na comunica\u00e7\u00e3o com o cliente mais eficiente poss\u00edvel, utilizando solu\u00e7\u00f5es t\u00e9cnicas modernas. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a GDPR e \u00a7 25, n.\u00ba 1 TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Para mais informa\u00e7\u00f5es, clique aqui: <a href=\"https:\/\/openai.com\/policies\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/openai.com\/policies\/privacy-policy<\/a>.<\/p>\n<h4>Processamento de encomendas<\/h4>\n<p>Celebr\u00e1mos um acordo de processamento de dados (DPA) para a utiliza\u00e7\u00e3o do servi\u00e7o acima mencionado. Trata-se de um contrato previsto pela lei de prote\u00e7\u00e3o de dados, que garante o tratamento dos dados pessoais dos visitantes do nosso s\u00edtio Web apenas de acordo com as nossas instru\u00e7\u00f5es e em conformidade com o RGPD.<\/p>\n<h2>9. marketing em linha e programas de parceria<\/h2>\n<h3>Programas de afilia\u00e7\u00e3o neste s\u00edtio Web<\/h3>\n<p>Participamos em programas de parceiros afiliados. Nos programas de parceiros afiliados, os an\u00fancios de uma empresa s\u00e3o colocados em s\u00edtios Web ou noutros meios de comunica\u00e7\u00e3o de outras empresas da rede de parceiros afiliados. Se o utilizador clicar num destes an\u00fancios de afiliados, ser\u00e1 redireccionado para a oferta anunciada. Se, posteriormente, efetuar uma determinada transa\u00e7\u00e3o (convers\u00e3o), o afiliado e, se for caso disso, o propriet\u00e1rio do suporte em que o an\u00fancio foi colocado, receber\u00e3o uma remunera\u00e7\u00e3o por esse facto. Para calcular esta remunera\u00e7\u00e3o, \u00e9 necess\u00e1rio que o operador da rede de afiliados possa identificar o an\u00fancio que o levou \u00e0 respectiva oferta e a transa\u00e7\u00e3o predefinida que efectuou. Para este efeito, s\u00e3o utilizados cookies ou tecnologias de reconhecimento compar\u00e1veis (por exemplo, impress\u00e3o digital do dispositivo).<\/p>\n<p>Os dados s\u00e3o armazenados e analisados com base no Art. 6, par\u00e1grafo 1 lit. f do RGPD. Os participantes no programa de afiliados t\u00eam um interesse leg\u00edtimo no c\u00e1lculo correto da remunera\u00e7\u00e3o dos afiliados. Se tiver sido solicitado um consentimento correspondente, o processamento \u00e9 efectuado exclusivamente com base no Art. 6, n.\u00ba 1 lit. a RGPD e \u00a7 25, n.\u00ba 1 TDDDG, na medida em que o consentimento inclui o armazenamento de cookies ou o acesso a informa\u00e7\u00f5es no dispositivo final do utilizador (por exemplo, impress\u00e3o digital do dispositivo) na ace\u00e7\u00e3o do TDDDG. O consentimento pode ser revogado em qualquer altura.<\/p>\n<p>Participamos nos seguintes programas de afiliados:<\/p>\n<h4>Programa de parceiros da Amazon<\/h4>\n<p>O fornecedor \u00e9 a Amazon Europe Core S.\u00e0.r.l. Para mais informa\u00e7\u00f5es, consulte a pol\u00edtica de privacidade da Amazon em: <a href=\"https:\/\/www.amazon.de\/gp\/help\/customer\/display.html?nodeId=201909010\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.amazon.de\/gp\/help\/customer\/display.html?nodeId=201909010<\/a>.<\/p>\n<p>A empresa est\u00e1 certificada de acordo com o \"EU-US Data Privacy Framework\" (DPF). O DPF \u00e9 um acordo entre a Uni\u00e3o Europeia e os EUA que se destina a garantir o cumprimento das normas europeias de prote\u00e7\u00e3o de dados para o processamento de dados nos EUA. Todas as empresas certificadas ao abrigo do DPF comprometem-se a cumprir estas normas de prote\u00e7\u00e3o de dados. Para obter mais informa\u00e7\u00f5es sobre este assunto, contacte o fornecedor atrav\u00e9s da seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5776\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5776<\/a>.<\/p>\n<h2>10. Fornecedores de com\u00e9rcio eletr\u00f3nico e de pagamentos<\/h2>\n<h3>Tratamento de dados relativos a clientes e contratos<\/h3>\n<p>Recolhemos, processamos e utilizamos dados pessoais de clientes e de contratos para estabelecer, organizar o conte\u00fado e alterar as nossas rela\u00e7\u00f5es contratuais. Recolhemos, processamos e utilizamos dados pessoais sobre a utiliza\u00e7\u00e3o deste s\u00edtio Web (dados de utiliza\u00e7\u00e3o) apenas na medida em que tal seja necess\u00e1rio para permitir que o utilizador utilize o servi\u00e7o ou para faturar o utilizador. A base legal para tal \u00e9 o art. 6, n.\u00ba 1, al\u00ednea b) do RGPD.<\/p>\n<p>Os dados do cliente recolhidos ser\u00e3o eliminados ap\u00f3s a conclus\u00e3o da encomenda ou a cessa\u00e7\u00e3o da rela\u00e7\u00e3o comercial e a expira\u00e7\u00e3o de quaisquer per\u00edodos de reten\u00e7\u00e3o legais existentes. Os prazos legais de conserva\u00e7\u00e3o n\u00e3o s\u00e3o afectados.<\/p>\n<h3>Transmiss\u00e3o de dados aquando da celebra\u00e7\u00e3o de um contrato para lojas em linha, retalhistas e expedi\u00e7\u00e3o de mercadorias<\/h3>\n<p>Se nos encomendar mercadorias, transmitiremos os seus dados pessoais \u00e0 empresa de transportes encarregada da entrega e ao prestador de servi\u00e7os de pagamento encarregado de processar o pagamento. Apenas ser\u00e3o divulgados os dados necess\u00e1rios para que o respetivo prestador de servi\u00e7os cumpra a sua tarefa. A base legal para tal \u00e9 o Art. 6, par\u00e1grafo 1 lit. b do RGPD, que permite o processamento de dados para o cumprimento de um contrato ou medidas pr\u00e9-contratuais. Se tiver dado o seu consentimento nos termos do art. 6, n.\u00ba 1, al\u00ednea a) do RGPD, transmitiremos o seu endere\u00e7o de correio eletr\u00f3nico \u00e0 empresa de transportes encarregada da entrega para que esta o informe por correio eletr\u00f3nico sobre o estado de expedi\u00e7\u00e3o da sua encomenda; pode revogar o seu consentimento em qualquer altura.<\/p>\n<h3>Transmiss\u00e3o de dados aquando da celebra\u00e7\u00e3o de um contrato de servi\u00e7os e de conte\u00fados digitais<\/h3>\n<p>S\u00f3 transferimos dados pessoais a terceiros se tal for necess\u00e1rio no contexto do processamento de contratos, por exemplo, \u00e0 institui\u00e7\u00e3o de cr\u00e9dito respons\u00e1vel pelo processamento de pagamentos.<\/p>\n<p>A transmiss\u00e3o posterior dos dados n\u00e3o ter\u00e1 lugar ou s\u00f3 ter\u00e1 lugar se o utilizador tiver dado o seu consentimento expresso para a transmiss\u00e3o. Os seus dados n\u00e3o ser\u00e3o transmitidos a terceiros sem o seu consentimento expresso, por exemplo, para fins publicit\u00e1rios.<\/p>\n<p>A base para o processamento de dados \u00e9 o Art. 6, par\u00e1grafo 1 lit. b do RGPD, que permite o processamento de dados para o cumprimento de um contrato ou medidas pr\u00e9-contratuais.<\/p>\n<h3>Servi\u00e7os de pagamento<\/h3>\n<p>Integramos servi\u00e7os de pagamento de empresas terceiras no nosso s\u00edtio Web. Quando nos faz uma compra, os seus dados de pagamento (por exemplo, nome, montante do pagamento, dados da conta, n\u00famero do cart\u00e3o de cr\u00e9dito) s\u00e3o processados pelo prestador de servi\u00e7os de pagamento para efeitos de processamento do pagamento. As disposi\u00e7\u00f5es contratuais e de prote\u00e7\u00e3o de dados dos respectivos fornecedores aplicam-se a estas transac\u00e7\u00f5es. Os prestadores de servi\u00e7os de pagamento s\u00e3o utilizados com base no art. 6, n.\u00ba 1, al\u00ednea b) do RGPD (processamento de contratos) e no interesse de um processo de pagamento simples, c\u00f3modo e seguro (art. 6, n.\u00ba 1, al\u00ednea f) do RGPD). Na medida em que o seu consentimento \u00e9 solicitado para determinadas ac\u00e7\u00f5es, o Art. 6 para. 1 lit. a RGPD \u00e9 a base legal para o processamento de dados; o consentimento pode ser revogado a qualquer momento no futuro.<\/p>\n<p>Neste s\u00edtio Web, utilizamos os seguintes servi\u00e7os de pagamento\/prestadores de servi\u00e7os de pagamento:<\/p>\n<h4>PayPal<\/h4>\n<p>O fornecedor deste servi\u00e7o de pagamento \u00e9 PayPal (Europe) S.\u00e0.r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxembourg (a seguir designado por \"PayPal\").<\/p>\n<p>A transfer\u00eancia de dados para os EUA baseia-se nas cl\u00e1usulas contratuais-tipo da Comiss\u00e3o Europeia. Os pormenores podem ser consultados aqui: <a href=\"https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/pocpsa-full\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/pocpsa-full<\/a>.<\/p>\n<p>Os pormenores podem ser consultados na pol\u00edtica de privacidade do PayPal: <a href=\"https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full<\/a>.<\/p>\n<h4>Klarna<\/h4>\n<p>O fornecedor \u00e9 a Klarna AB, Sveav\u00e4gen 46, 111 34 Estocolmo, Su\u00e9cia (a seguir designada por \"Klarna\"). A Klarna oferece v\u00e1rias op\u00e7\u00f5es de pagamento (por exemplo, compra a presta\u00e7\u00f5es). Se o utilizador optar por pagar com a Klarna (solu\u00e7\u00e3o de checkout da Klarna), a Klarna recolher\u00e1 v\u00e1rios dados pessoais do utilizador. A Klarna utiliza cookies para otimizar a utiliza\u00e7\u00e3o da solu\u00e7\u00e3o de checkout da Klarna. Os pormenores sobre a utiliza\u00e7\u00e3o dos cookies da Klarna podem ser consultados na seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/cookie\/de_de\/checkout.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/cookie\/de_de\/checkout.pdf<\/a>.<\/p>\n<p>Os pormenores podem ser consultados na pol\u00edtica de privacidade da Klarna, na seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.klarna.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.klarna.com\/de\/datenschutz\/<\/a>.<\/p>\n<h4>Paydirekt<\/h4>\n<p>O prestador deste servi\u00e7o de pagamento \u00e9 a Paydirekt GmbH, Hamburger Allee 26-28, 60486 Frankfurt am Main, Alemanha (a seguir designada por \"Paydirekt\"). Quando efectua um pagamento atrav\u00e9s da Paydirekt, a Paydirekt recolhe v\u00e1rios dados relativos \u00e0 transa\u00e7\u00e3o e transmite-os ao banco em que est\u00e1 registado na Paydirekt. Para al\u00e9m dos dados necess\u00e1rios para o pagamento, a Paydirekt pode recolher outros dados, como o endere\u00e7o de entrega ou artigos individuais no cesto de compras, no \u00e2mbito do processamento da transa\u00e7\u00e3o. Paydirekt ent\u00e3o autentica a transa\u00e7\u00e3o usando o procedimento de autentica\u00e7\u00e3o armazenado com o banco para esse fim. O montante do pagamento \u00e9 ent\u00e3o transferido da sua conta para a nossa conta. Nem n\u00f3s nem terceiros t\u00eam acesso aos dados da sua conta. Para obter detalhes sobre o pagamento com Paydirekt, consulte os termos e condi\u00e7\u00f5es e a pol\u00edtica de privacidade de Paydirekt em: <a href=\"https:\/\/www.paydirekt.de\/agb\/index.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.paydirekt.de\/agb\/index.html<\/a>.<\/p>\n<h4>Transfer\u00eancia banc\u00e1ria imediata<\/h4>\n<p>O prestador deste servi\u00e7o de pagamento \u00e9 a Sofort GmbH, Theresienh\u00f6he 12, 80339 Munique (doravante designada por \"Sofort GmbH\"). Com a ajuda do procedimento \"Sofort\u00fcberweisung\", recebemos uma confirma\u00e7\u00e3o de pagamento da Sofort GmbH em tempo real e podemos come\u00e7ar imediatamente a cumprir as nossas obriga\u00e7\u00f5es. Se tiver optado pelo m\u00e9todo de pagamento \"Sofort\u00fcberweisung\", transmite o PIN e um TAN v\u00e1lido \u00e0 Sofort GmbH, com os quais esta pode entrar na sua conta banc\u00e1ria online. Ap\u00f3s o login, a Sofort GmbH verifica automaticamente o saldo da sua conta e efectua a transfer\u00eancia para n\u00f3s utilizando o TAN que nos transmitiu. Em seguida, envia-nos imediatamente uma confirma\u00e7\u00e3o da transa\u00e7\u00e3o. Ap\u00f3s o in\u00edcio de sess\u00e3o, o seu volume de neg\u00f3cios, o limite de cr\u00e9dito da facilidade de descoberto e a exist\u00eancia de outras contas e respectivos saldos s\u00e3o tamb\u00e9m automaticamente verificados. Para al\u00e9m do PIN e do TAN, s\u00e3o tamb\u00e9m transmitidos \u00e0 Sofort GmbH os dados de pagamento que introduziu e os seus dados pessoais. Os seus dados pessoais incluem o seu nome e apelido, endere\u00e7o, n\u00famero(s) de telefone, endere\u00e7o de correio eletr\u00f3nico, endere\u00e7o IP e quaisquer outros dados necess\u00e1rios para o processamento do pagamento. A transmiss\u00e3o destes dados \u00e9 necess\u00e1ria para estabelecer a sua identidade sem margem para d\u00favidas e para evitar tentativas de fraude. Os pormenores sobre o pagamento com Sofort\u00fcberweisung podem ser consultados na seguinte liga\u00e7\u00e3o: <a href=\"https:\/\/www.klarna.com\/sofort\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.klarna.com\/sofort\/<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Datenschutz&shy;erkl&auml;rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen &Uuml;berblick dar&uuml;ber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers&ouml;nlich identifiziert werden k&ouml;nnen. Ausf&uuml;hrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef&uuml;hrten Datenschutzerkl&auml;rung. Datenerfassung auf dieser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"class_list":["post-41","page","type-page","status-publish","hentry"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":null,"_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":"1","_edit_lock":"1740235828:1","_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"8729","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"andmekaitse","_trp_automatically_translated_slug_lv":"datu-aizsardziba","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"tietosuoja","_trp_automatically_translated_slug_ja":"%e3%83%87%e3%83%bc%e3%82%bf%e4%bf%9d%e8%ad%b7","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":null,"_elementor_screenshot_failed":null,"theplus_transient_widgets":[],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"1084","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":"8","rank_math_contentai_score":{"keywords":"74.51","wordCount":"0","linkCount":"0","headingCount":"0","mediaCount":"0"},"ilj_limitincominglinks":"","ilj_maxincominglinks":"1","ilj_limitoutgoinglinks":"","ilj_maxoutgoinglinks":"1","ilj_limitlinksperparagraph":"","ilj_linksperparagraph":"1","ilj_blacklistdefinition":[],"ilj_linkdefinition":[],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":null,"rank_math_og_content_image":null,"_yoast_wpseo_metadesc":null,"_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":null,"footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":1,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":8800,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/pages\/41\/revisions\/8800"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}