{"id":4310,"date":"2020-10-30T23:26:56","date_gmt":"2020-10-30T22:26:56","guid":{"rendered":"https:\/\/webhosting.de\/?p=4310"},"modified":"2020-10-30T23:26:56","modified_gmt":"2020-10-30T22:26:56","slug":"javascript","status":"publish","type":"post","link":"https:\/\/webhosting.de\/pt\/javascript\/","title":{"rendered":"JavaScript"},"content":{"rendered":"<p>O JavaScript \u00e9 um dos tr\u00eas grandes do alojamento web: Al\u00e9m disso, o <a href=\"https:\/\/webhosting.de\/pt\/html-hypertext-markup-language\/\">HTML<\/a> (estrutura da p\u00e1gina) e CSS (apresenta\u00e7\u00e3o), a linguagem de programa\u00e7\u00e3o orientada a objetos oferece dinamiza\u00e7\u00e3o de conte\u00fado. Mas o JavaScript n\u00e3o \u00e9 aplic\u00e1vel apenas no contexto do design da p\u00e1gina. As aplica\u00e7\u00f5es do lado do servidor tamb\u00e9m podem ser controladas com JavaScript.<\/p>\n<h2>Origens do JavaScript<\/h2>\n<p>Apesar do nome, o JavaScript tem pouco a ver com Java. Originalmente, a linguagem de scripting deveria ser chamada LiveScript e foi desenvolvida pela Netscape para a intera\u00e7\u00e3o do Netscape Navigator com applets Java (aplicativos clientes Java). Como software realmente propriet\u00e1rio, o JavaScript representou um fator competitivo para empresas como <a href=\"https:\/\/webhosting.de\/pt\/emails-microsoft-werden-abgewiesen\/\">Microsoft<\/a> Ousado. Estes responderam ao desenvolvimento do JavaScript com suas pr\u00f3prias solu\u00e7\u00f5es, como a linguagem de script JScript. Com o tempo, no entanto, o JavaScript tornou-se a principal linguagem de script para o lado do cliente e (al\u00e9m <a href=\"https:\/\/webhosting.de\/pt\/php\/\">php<\/a>) dinamiza\u00e7\u00e3o do lado do servidor.<\/p>\n<h3>Dinamiza\u00e7\u00e3o do lado do cliente<\/h3>\n<p>Provavelmente a fun\u00e7\u00e3o mais utilizada do JavaScript \u00e9 a possibilidade de dinamiza\u00e7\u00e3o do lado do cliente. O cliente \u00e9 o web browser. A dinamiza\u00e7\u00e3o do lado do cliente significa que o conte\u00fado exibido no cliente \u00e9 manipulado. HTML \u00e9 a descri\u00e7\u00e3o est\u00e1tica da estrutura de uma presen\u00e7a na Web, o chamado Document Object Model (DOM). Enquanto o CSS (Cascading Style Sheets) \u00e9 usado para o desenho separado deste \"esqueleto\", o JavaScript oferece a possibilidade de mover, apagar ou adicionar elementos HTML.<\/p>\n<p>Esta manipula\u00e7\u00e3o de DOM (DOM scripting) pode ser usada de v\u00e1rias maneiras. Atrav\u00e9s dos chamados manipuladores de eventos, as fun\u00e7\u00f5es s\u00e3o primeiramente vinculadas a determinados eventos. Estes podem ser cliques do usu\u00e1rio, pontos no tempo ou o carregamento do site. Usando as ID's atribu\u00eddas aos elementos em HTML, as altera\u00e7\u00f5es baseadas em eventos podem ent\u00e3o ser acionadas. Isto pode incluir tudo desde a programa\u00e7\u00e3o de formul\u00e1rios simples e din\u00e2micos ou filtros de mesa at\u00e9 \u00e0 incorpora\u00e7\u00e3o de leitores de v\u00eddeo ou gr\u00e1ficos complexos e din\u00e2micos.<\/p>\n<h3>JQuery: O JavaScript mais descomplicado<\/h3>\n<p>O JavaScript \u00e9 um exemplo de linguagens de programa\u00e7\u00e3o orientadas a objetos. Como tal, o limiar de entrada para web designers inexperientes \u00e9 relativamente elevado. Sem restringir a funcionalidade do JavaScript (muito), a biblioteca JavaScript JQuery oferece uma sintaxe simplificada que permite que os casos de uso mais comuns sejam criados de forma r\u00e1pida e f\u00e1cil. Enquanto o JavaScript oferece complexidade e mutabilidade similares ao Java ou Python, definindo prot\u00f3tipos (ao inv\u00e9s de classes), inst\u00e2ncias (objetos concretos) e m\u00e9todos (fun\u00e7\u00f5es vinculadas a objetos), o JQuery limita o vocabul\u00e1rio e as estruturas. Os comandos t\u00eam uma estrutura estacion\u00e1ria para que a estrutura possa ser compreendida muito rapidamente. Portanto, a menos que voc\u00ea esteja lidando com aplica\u00e7\u00f5es complexas e incomuns, muito provavelmente existe uma solu\u00e7\u00e3o simples em JQuery.<\/p>\n<h3>Dinamiza\u00e7\u00e3o do lado do servidor: AJAX e Node.js<\/h3>\n<p>Al\u00e9m da manipula\u00e7\u00e3o DOM, o JavaScript tamb\u00e9m \u00e9 usado para comunica\u00e7\u00e3o com servidores, como consultas a bases de dados. Desde 2009 existe o node.js, um framework para dinamiza\u00e7\u00e3o do lado do servidor com JavaScript. Isto j\u00e1 era poss\u00edvel antes de 2009, mas o node.js permite uma integra\u00e7\u00e3o mais f\u00e1cil. Isto \u00e9 uma vantagem para programadores JavaScript, porque assim eles n\u00e3o precisam mais usar outras linguagens como php. Al\u00e9m disso, o node.js tamb\u00e9m permite a paraleliza\u00e7\u00e3o de processos. Isto \u00e9 uma vantagem, porque demasiados destes chamados fios podem levar a uma paralisa\u00e7\u00e3o. Com o node.js, os pedidos passam por um \u00fanico fio, o que pode aumentar consideravelmente o desempenho.<\/p>\n<p>Node.js \u00e9 um exemplo para as possibilidades do AJAX. A sigla significa um procedimento chamado JavaScript Ass\u00edncrono e XML. Este princ\u00edpio torna poss\u00edvel recuperar o conte\u00fado dos servidores sem ter que recarregar a p\u00e1gina inteira. Para muitos sites como o YouTube, uma recarga completa ap\u00f3s pedidos de v\u00eddeo ou carregamento de coment\u00e1rios seria uma grande desvantagem. O AJAX tamb\u00e9m \u00e9 uma solu\u00e7\u00e3o para o problema da acumula\u00e7\u00e3o de pedidos gra\u00e7as ao processamento ass\u00edncrono, como explicado acima para o Node.js.<\/p>\n<h3>Integra\u00e7\u00e3o de JavaScript<\/h3>\n<p>A integra\u00e7\u00e3o b\u00e1sica de JavaScript em ofertas web funciona exatamente da mesma forma que a conex\u00e3o com arquivos CSS. Portanto, h\u00e1 duas possibilidades para isto: Por um lado, o JavaScript pode ser usado na cabe\u00e7a ou no corpo do documento HTML.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>JavaScript geh\u00f6rt zu den gro\u00dfen drei des Webhostings: Neben HTML (Seitenstruktur) und CSS (Darstellung) bietet die objektorientierte Programmiersprache Dynamisierung von Inhalten. Aber JavaScript ist nicht nur im Kontext der Seitengestaltung einsetzbar. Auch serverseitige Anwendungen k\u00f6nnen mit JavaScript kontrolliert werden. Urspr\u00fcnge von JavaScript Trotz des Namens hat JavaScript nur wenig mit Java zu tun. Urspr\u00fcnglich sollte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[732],"tags":[335,336,337],"class_list":["post-4310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lexikon","tag-javascript","tag-jquery","tag-js"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":"javascript","_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":null,"_edit_lock":null,"_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"4094","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"javascript","_trp_automatically_translated_slug_lv":"javascript","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"javascript","_trp_automatically_translated_slug_ja":"%e3%82%b8%e3%83%a3%e3%83%90%e3%82%b9%e3%82%af%e3%83%aa%e3%83%97%e3%83%88","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":["tp-video-player"],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"716","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":null,"rank_math_contentai_score":null,"ilj_limitincominglinks":null,"ilj_maxincominglinks":null,"ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":null,"ilj_linkdefinition":["javascript"],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":"javascript","rank_math_og_content_image":null,"_yoast_wpseo_metadesc":"JavaScript geh\u00f6rt zu den gro\u00dfen drei des Webhosting. Trotz des Namens hat JavaScript nur wenig mit Java zu tun.","_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":"JavaScript geh\u00f6rt zu den gro\u00dfen drei des Webhosting. Trotz des Namens hat JavaScript nur wenig mit Java zu tun.","surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":"936","footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/posts\/4310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/comments?post=4310"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/posts\/4310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/media\/936"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/media?parent=4310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/categories?post=4310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/tags?post=4310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}