{"id":4454,"date":"2020-10-30T21:12:33","date_gmt":"2020-10-30T20:12:33","guid":{"rendered":"https:\/\/webhosting.de\/?p=4454"},"modified":"2020-10-30T21:12:33","modified_gmt":"2020-10-30T20:12:33","slug":"redireccionamento-em-facebook-marketing-funcoes-o","status":"publish","type":"post","link":"https:\/\/webhosting.de\/pt\/retargeting-im-facebook-marketing-funktioniert-das\/","title":{"rendered":"Reorienta\u00e7\u00e3o no Marketing do Facebook - isso funciona?"},"content":{"rendered":"<p>O redireccionamento soa \"perigoso\" no in\u00edcio. Mas qualquer um que lide com <a href=\"https:\/\/webhosting.de\/pt\/facebook-likes-kaufen-der-koenigsweg-zur-kundenvertreibung\/\">Facebook<\/a> O marketing est\u00e1 ocupado, n\u00e3o h\u00e1 como lidar com o tema.<br \/>\nE mesmo que voc\u00ea talvez n\u00e3o esteja (ainda) familiarizado com o termo, voc\u00ea definitivamente j\u00e1 trope\u00e7ou no redirecionamento.<\/p>\n<h2>Como funciona o redireccionamento<\/h2>\n<p>Provavelmente j\u00e1 experimentaram isto. Voc\u00ea visita uma loja na internet, olha para um determinado produto e ele segue voc\u00ea em todos os lugares a partir de ent\u00e3o. Voc\u00ea est\u00e1 em um <a href=\"https:\/\/webhosting.de\/pt\/eine-eigene-webseite-fuer-ihr-unternehmen-ja-oder-nein\/\">website<\/a> ou no Facebook e de repente veja o produto novamente - seja diretamente na sua linha do tempo ou na lateral do site. Isto n\u00e3o \u00e9 coincid\u00eancia.este tipo de publicidade \u00e9 chamado de redirecionamento.<br \/>\nVoc\u00ea j\u00e1 demonstrou que est\u00e1 interessado neste produto e por isso a perda de espalhamento \u00e9 mantida muito baixa. Isto \u00e9 armazenado no seu computador num cookie inofensivo, que nada mais \u00e9 do que um pequeno ficheiro de texto. Uma vez que demonstrou interesse, presume-se tamb\u00e9m que o an\u00fancio n\u00e3o o aborrece, mas apoia a sua decis\u00e3o de compra.<\/p>\n<h2><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2018\/08\/facebook-pixel.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-3398\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2018\/08\/facebook-pixel-1024x198.png\" alt=\"p\u00edxel do facebook\" width=\"696\" height=\"135\" \/><\/a>Todo operador do site deve confiar no redirecionamento?<\/h2>\n<p>Se voc\u00ea possui uma loja online ou vende outro produto em seu site, \u00e9 uma boa id\u00e9ia investir em publicidade online. Se voc\u00ea incluir um pequeno pixel no seu site com anteced\u00eancia, o que n\u00e3o \u00e9 mais do que um pouco de c\u00f3digo, voc\u00ea pode continuar indicando clientes que j\u00e1 foram ao seu site. Isto faz sentido, \u00e9 claro. Afinal, um cliente muitas vezes n\u00e3o compra at\u00e9 ao s\u00e9timo contacto com o <a href=\"https:\/\/webhosting.de\/pt\/existenzgruendung-online-chancen-und-stolpersteine\/\">Loja<\/a> - seja online ou offline.<br \/>\nO redirecionamento, portanto, ajuda voc\u00ea a convencer seus clientes e traz\u00ea-los de volta ao seu site. Visto sob esta luz, o redireccionamento \u00e9 tamb\u00e9m uma forma de reten\u00e7\u00e3o de clientes.<br \/>\nAo exibir repetidamente o an\u00fancio, seus clientes potenciais ser\u00e3o informados de que voc\u00ea \u00e9 o melhor endere\u00e7o para este produto e eles - provavelmente - n\u00e3o olhar\u00e3o em outros sites.<\/p>\n<h2><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2018\/08\/retargeting-webhosting-2.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-3402\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2018\/08\/retargeting-webhosting-2.jpg\" alt=\"redireccionamento-armazenamento-2\" width=\"693\" height=\"743\" \/><\/a>Publicidade direccionada<\/h2>\n<p>A publicidade direccionada \u00e9, de qualquer forma, mais rent\u00e1vel. Mesmo que o pre\u00e7o do clique real do cliente seja superior, pode-se assumir que o cliente ter\u00e1 muito mais probabilidades de comprar o produto quando voltar a entrar em contacto com ele do que um cliente completamente novo que possa ter a inten\u00e7\u00e3o de se informar sobre o produto.<br \/>\nO redirecionamento ajuda a mostrar o an\u00fancio apenas aos clientes que j\u00e1 manifestaram interesse.<\/p>\n<h2><\/h2>\n<h2>Cr\u00edticas ao redireccionamento<\/h2>\n<p>Os utilizadores podem rapidamente sentir-se \"seguidos\" pelo redireccionamento. Eles t\u00eam a impress\u00e3o de que os dados sobre o seu comportamento sufocante s\u00e3o recolhidos sem o seu consentimento, para que possam ser abordados repetidamente - sem que isso seja desejado. Isto tamb\u00e9m coloca os protetores de dados contra o redirecionamento. Do ponto de vista de um operador de loja online, o redirecionamento faz todo o sentido, mas do ponto de vista do usu\u00e1rio n\u00e3o deve ser uma coisa boa demais. Com o chamado limite de frequ\u00eancia, os marqueteiros online podem determinar a frequ\u00eancia de exibi\u00e7\u00e3o e tirar proveito disso. Porque quando voc\u00ea come\u00e7a a pensar em si mesmo, rapidamente se torna claro: ningu\u00e9m quer ver o mesmo an\u00fancio uma e outra vez. Se isso acontecer durante os blocos publicit\u00e1rios na televis\u00e3o, simplesmente trocamos de lugar. Se isto acontecer na Internet, podemos recorrer a um bloqueador de an\u00fancios e desligar completamente a publicidade.<br \/>\nUma vez feito isso, voc\u00ea n\u00e3o ser\u00e1 capaz de recuperar clientes que j\u00e1 tiveram o(s) item(s) em seu carrinho de compras e possivelmente s\u00f3 perten\u00e7am ao grupo de \"desist\u00eancias do carrinho de compras\". Este grupo-alvo j\u00e1 est\u00e1 convencido de voc\u00ea, eles s\u00f3 t\u00eam que fazer o \u00faltimo clique para completar a compra. A irrita\u00e7\u00e3o deste grupo alvo refere-se ao cliente da sua loja.<br \/>\nPor isso, se decidir redireccionar o seu alvo, deve tratar disso com cuidado para n\u00e3o perturbar os seus potenciais clientes.<\/p>\n<h2><a href=\"https:\/\/webhosting.de\/wp-content\/uploads\/2018\/08\/retargeting-facebook-2.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-3401\" src=\"https:\/\/webhosting.de\/wp-content\/uploads\/2018\/08\/retargeting-facebook-2.jpg\" alt=\"reorientado-facebook-2\" width=\"693\" height=\"743\" \/><\/a>Conclus\u00e3o<\/h2>\n<p>Para os varejistas e marqueteiros online em geral, o redirecionamento no Facebook, Google e similares \u00e9 uma ben\u00e7\u00e3o. Afinal, garante que a dispers\u00e3o da perda de publicidade \u00e9 baixa e, portanto, os custos n\u00e3o disparam a alturas inimagin\u00e1veis. No entanto, deve ser tratado de forma sensata. O ditado \"Faz aos outros o que queres que te fa\u00e7am a ti\". encaixa perfeitamente aqui. Cada um de n\u00f3s est\u00e1 rodeado de toneladas de publicidade todos os dias e tamb\u00e9m temos uma toler\u00e2ncia relativamente alta quando se trata de publicidade. No entanto, quando \u00e9 demais, nos perturba e nos damos a muito trabalho e investimos nosso tempo para desligar o que nos perturba.<br \/>\nPortanto, se voc\u00ea usar o redirecionamento sabiamente, isso o ajudar\u00e1 a aumentar as vendas sem incomodar seus clientes. Pelo contr\u00e1rio, seus clientes podem at\u00e9 mesmo tomar sua publicidade cautelosa como um lembrete e retornar ao seu site para finalmente fechar a venda.<\/p>","protected":false},"excerpt":{"rendered":"<p>Retargeting h\u00f6rt sich erst einmal &#8222;gef\u00e4hrlich&#8220; an. Aber jeder, der sich mit Facebook Marketing besch\u00e4ftigt, wird nicht drum herum kommen sich mit dem Thema auseinander zu setzen. Und auch, wenn Ihnen der Begriff vielleicht (noch) nicht gel\u00e4ufig ist, Sie sind garantiert bereits \u00fcber das Retargeting gestolpert. So funktioniert Retargeting Sie haben das sicher schon erlebt. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[678],"tags":[],"class_list":["post-4454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecommerce"],"acf":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"litespeed-optimize-size":null,"litespeed-optimize-set":null,"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"stockpack_author_name":null,"stockpack_author_url":null,"stockpack_provider":null,"stockpack_image_url":null,"stockpack_license":null,"stockpack_license_url":null,"stockpack_modification":null,"color":null,"original_id":null,"original_url":null,"original_link":null,"unsplash_location":null,"unsplash_sponsor":null,"unsplash_exif":null,"unsplash_attachment_metadata":null,"_elementor_is_screenshot":null,"surfer_file_name":null,"surfer_file_original_url":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_elements_download_event":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_trp_menu_languages":null,"rank_math_primary_category":null,"rank_math_title":null,"inline_featured_image":null,"_yoast_wpseo_primary_category":null,"rank_math_schema_blogposting":null,"rank_math_schema_videoobject":null,"_oembed_049c719bc4a9f89deaead66a7da9fddc":null,"_oembed_time_049c719bc4a9f89deaead66a7da9fddc":null,"_yoast_wpseo_focuskw":"","_yoast_wpseo_linkdex":null,"_oembed_27e3473bf8bec795fbeb3a9d38489348":null,"_oembed_c3b0f6959478faf92a1f343d8f96b19e":null,"_trp_translated_slug_en_us":null,"_wp_desired_post_slug":null,"_yoast_wpseo_title":null,"tldname":null,"tldpreis":null,"tldrubrik":null,"tldpolicylink":null,"tldsize":null,"tldregistrierungsdauer":null,"tldtransfer":null,"tldwhoisprivacy":null,"tldregistrarchange":null,"tldregistrantchange":null,"tldwhoisupdate":null,"tldnameserverupdate":null,"tlddeletesofort":null,"tlddeleteexpire":null,"tldumlaute":null,"tldrestore":null,"tldsubcategory":null,"tldbildname":null,"tldbildurl":null,"tldclean":null,"tldcategory":null,"tldpolicy":null,"tldbesonderheiten":null,"tld_bedeutung":null,"_oembed_d167040d816d8f94c072940c8009f5f8":null,"_oembed_b0a0fa59ef14f8870da2c63f2027d064":null,"_oembed_4792fa4dfb2a8f09ab950a73b7f313ba":null,"_oembed_33ceb1fe54a8ab775d9410abf699878d":null,"_oembed_fd7014d14d919b45ec004937c0db9335":null,"_oembed_21a029d076783ec3e8042698c351bd7e":null,"_oembed_be5ea8a0c7b18e658f08cc571a909452":null,"_oembed_a9ca7a298b19f9b48ec5914e010294d2":null,"_oembed_f8db6b27d08a2bb1f920e7647808899a":null,"_oembed_168ebde5096e77d8a89326519af9e022":null,"_oembed_cdb76f1b345b42743edfe25481b6f98f":null,"_oembed_87b0613611ae54e86e8864265404b0a1":null,"_oembed_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_oembed_time_27aa0e5cf3f1bb4bc416a4641a5ac273":null,"_tldname":null,"_tldclean":null,"_tldpreis":null,"_tldcategory":null,"_tldsubcategory":null,"_tldpolicy":null,"_tldpolicylink":null,"_tldsize":null,"_tldregistrierungsdauer":null,"_tldtransfer":null,"_tldwhoisprivacy":null,"_tldregistrarchange":null,"_tldregistrantchange":null,"_tldwhoisupdate":null,"_tldnameserverupdate":null,"_tlddeletesofort":null,"_tlddeleteexpire":null,"_tldumlaute":null,"_tldrestore":null,"_tldbildname":null,"_tldbildurl":null,"_tld_bedeutung":null,"_tldbesonderheiten":null,"_oembed_ad96e4112edb9f8ffa35731d4098bc6b":null,"_oembed_8357e2b8a2575c74ed5978f262a10126":null,"_oembed_3d5fea5103dd0d22ec5d6a33eff7f863":null,"_eael_widget_elements":null,"_oembed_0d8a206f09633e3d62b95a15a4dd0487":null,"_oembed_time_0d8a206f09633e3d62b95a15a4dd0487":null,"_aioseo_description":null,"_eb_attr":null,"_eb_data_table":null,"_oembed_819a879e7da16dd629cfd15a97334c8a":null,"_oembed_time_819a879e7da16dd629cfd15a97334c8a":null,"_acf_changed":null,"_wpcode_auto_insert":null,"_edit_last":null,"_edit_lock":null,"_oembed_e7b913c6c84084ed9702cb4feb012ddd":null,"_oembed_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_time_bfde9e10f59a17b85fc8917fa7edf782":null,"_oembed_03514b67990db061d7c4672de26dc514":null,"_oembed_time_03514b67990db061d7c4672de26dc514":null,"rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_eael_post_view_count":"4598","_trp_automatically_translated_slug_ru_ru":null,"_trp_automatically_translated_slug_et":"retargeting-facebook-marketing-toeoed-see","_trp_automatically_translated_slug_lv":"retargeting-in-facebook-marketing-works-that","_trp_automatically_translated_slug_fr_fr":null,"_trp_automatically_translated_slug_en_us":null,"_wp_old_slug":null,"_trp_automatically_translated_slug_da_dk":null,"_trp_automatically_translated_slug_pl_pl":null,"_trp_automatically_translated_slug_es_es":null,"_trp_automatically_translated_slug_hu_hu":null,"_trp_automatically_translated_slug_fi":"retargeting-facebook-markkinointi-toimii-ettae","_trp_automatically_translated_slug_ja":"%e3%83%95%e3%82%a7%e3%82%a4%e3%82%b9%e3%83%96%e3%83%83%e3%82%af%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0%e6%a9%9f%e8%83%bd%e3%81%ae%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86","_trp_automatically_translated_slug_lt_lt":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_elementor_version":null,"_elementor_pro_version":null,"_wp_page_template":"default","_elementor_page_settings":null,"_elementor_data":null,"_elementor_css":null,"_elementor_conditions":null,"_happyaddons_elements_cache":null,"_oembed_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_time_75446120c39305f0da0ccd147f6de9cb":null,"_oembed_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_time_3efb2c3e76a18143e7207993a2a6939a":null,"_oembed_59808117857ddf57e478a31d79f76e4d":null,"_oembed_time_59808117857ddf57e478a31d79f76e4d":null,"_oembed_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_time_965c5b49aa8d22ce37dfb3bde0268600":null,"_oembed_81002f7ee3604f645db4ebcfd1912acf":null,"_oembed_time_81002f7ee3604f645db4ebcfd1912acf":null,"_elementor_screenshot":null,"_oembed_7ea3429961cf98fa85da9747683af827":null,"_oembed_time_7ea3429961cf98fa85da9747683af827":null,"_elementor_controls_usage":null,"_elementor_page_assets":[],"_elementor_screenshot_failed":null,"theplus_transient_widgets":["tp-video-player"],"_eael_custom_js":null,"_wp_old_date":null,"_trp_automatically_translated_slug_it_it":null,"_trp_automatically_translated_slug_pt_pt":null,"_trp_automatically_translated_slug_zh_cn":null,"_trp_automatically_translated_slug_nl_nl":null,"_trp_automatically_translated_slug_pt_br":null,"_trp_automatically_translated_slug_sv_se":null,"rank_math_analytic_object_id":"931","rank_math_internal_links_processed":null,"_trp_automatically_translated_slug_ro_ro":null,"_trp_automatically_translated_slug_sk_sk":null,"_trp_automatically_translated_slug_bg_bg":null,"_trp_automatically_translated_slug_sl_si":null,"litespeed_vpi_list":["webhostinglogo.png"],"litespeed_vpi_list_mobile":["webhostinglogo.png"],"rank_math_seo_score":null,"rank_math_contentai_score":null,"ilj_limitincominglinks":null,"ilj_maxincominglinks":null,"ilj_limitoutgoinglinks":null,"ilj_maxoutgoinglinks":null,"ilj_limitlinksperparagraph":null,"ilj_linksperparagraph":null,"ilj_blacklistdefinition":null,"ilj_linkdefinition":["retargeting im facebook marketing - funktioniert das?"],"_eb_reusable_block_ids":null,"rank_math_focus_keyword":null,"rank_math_og_content_image":null,"_yoast_wpseo_metadesc":"","_yoast_wpseo_content_score":null,"_yoast_wpseo_focuskeywords":null,"_yoast_wpseo_keywordsynonyms":null,"_yoast_wpseo_estimated-reading-time-minutes":null,"rank_math_description":null,"surfer_last_post_update":null,"surfer_last_post_update_direction":null,"surfer_keywords":null,"surfer_location":null,"surfer_draft_id":null,"surfer_permalink_hash":null,"surfer_scrape_ready":null,"_thumbnail_id":"1288","footnotes":null,"_links":{"self":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/posts\/4454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/comments?post=4454"}],"version-history":[{"count":0,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/posts\/4454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/media\/1288"}],"wp:attachment":[{"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/media?parent=4454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/categories?post=4454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webhosting.de\/pt\/wp-json\/wp\/v2\/tags?post=4454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}